{"id":9833,"date":"2020-11-19T22:24:17","date_gmt":"2020-11-20T01:24:17","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=9833"},"modified":"2020-11-19T22:24:17","modified_gmt":"2020-11-20T01:24:17","slug":"salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/","title":{"rendered":"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En la tarde de hoy, personal de la salud del Hospital \u201cDr. Jaime Ferre\u201d puso en funcionamiento un equipo de af\u00e9resis con la finalidad de efectuar tratamientos destinados a la recuperaci\u00f3n de pacientes con coronavirus en el nosocomio local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La compra del aparato se logr\u00f3 con un trabajo articulado entre la provincia y el municipio, sumado al aporte del sector privado, quienes tomaron la iniciativa de avanzar para lograr la adquisici\u00f3n de la m\u00e1quina valuada en $ 4 millones. El hecho de extraer plasma es trascendental para la salud de toda la regi\u00f3n, y su utilidad mantendr\u00e1 vigencia una vez que haya sido superada la pandemia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobernador de la provincia de Santa Fe habl\u00f3 sobre la donaci\u00f3n y la puesta en funcionamiento del equipo de af\u00e9resis plasm\u00e1tica en el Hospital: \u201cQuiero agradecer a quienes se han movilizado detr\u00e1s de este nuevo objetivo de sumar equipamiento a nuestro Hospital Jaime Ferr\u00e9, junto al esfuerzo que hace la Cooperadora permanentemente y generando confianza para que los empresarios puedan sentirse con la tranquilidad de que es un recurso que va a tener un muy buen uso\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el mandatario agreg\u00f3 que \u201cla primera conversaci\u00f3n que tuve con un empresario de esta ciudad fue por respiradores. La preocupaci\u00f3n era c\u00f3mo traerlos cuando se enteraron que aqu\u00ed ten\u00edamos 5 equipos. Ese esfuerzo com\u00fan con el Municipio llev\u00f3 a que podamos tener un equipamiento hist\u00f3rico en camas, respiradores, monitores, el cual nos permiti\u00f3 crecer mucho, pasando largamente los 30 funcionando y con posibilidad de llegar a los 37\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl esfuerzo que se hizo vali\u00f3 la pena porque, no solo permiti\u00f3 equiparnos, sino que pudimos dotar al personal de capacitaci\u00f3n necesaria, de equipos de protecci\u00f3n y, fundamentalmente, de otros aparatos para poder realizar di\u00e1lisis aqu\u00ed. Es decir, se invirti\u00f3, en muy poco tiempo, m\u00e1s de 50 millones de pesos, y eso se logr\u00f3 con toda la decisi\u00f3n de poner al d\u00eda la infraestructura que necesita la ciudad y la regi\u00f3n\u201d; cerr\u00f3 Perotti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un avance importante<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el intendente Luis Castellano valor\u00f3 la llegada del aparato a la ciudad y reflexion\u00f3 acerca del momento que hoy nos toca transitar. \u201cEl hecho de poder recuperar plasma de la gente que ha tenido Covid-19 muestra como nada que dependemos unos de otros. Si hay algo que la pandemia dej\u00f3 en claro es que somos un cuerpo social y que, si no nos ayudamos entre nosotros, nos vence. Este es el hecho m\u00e1s palpable: la donaci\u00f3n de parte de algo que tenemos en nuestro cuerpo que sirve para ayudar a que otro pueda vivir. Es un hecho de amor muy grande y yo invito a todos aquellos y aquellas que tengan la posibilidad de donar, lo hagan porque es un acto de amor\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, el funcionario le agradeci\u00f3 al gobernador por su compromiso con la comunidad y valor\u00f3 el esfuerzo del personal sanitario: \u201cTambi\u00e9n quiero agradecerle a Omar Perotti por el apoyo que posibilit\u00f3 transformar este Hospital Jaime Ferr\u00e9 en estos meses de gesti\u00f3n y a todo el equipo de la instituci\u00f3n por el sacrificio que est\u00e1n haciendo para estar a la altura de las circunstancias, as\u00ed como todo nuestro equipo de salud municipal que viene acompa\u00f1ando en los controles y en la asistencia complementaria. Nos sentimos orgullosos de serlo y de ser parte\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cConcretamos un sue\u00f1o\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La directora de la Regi\u00f3n Salud Rafaela, Eter Senn, se conmovi\u00f3 ante los presentes porque se le hab\u00eda hecho una costumbre escuchar a distintos pacientes recuperados tener que realizar un tedioso viaje a Santa Fe y Rosario para donar plasma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPara el Gobierno provincial y municipal, una de las premisas es garantizar la salud y el acceso al sistema de salud. Este es el horizonte que tenemos que tener: que toda la poblaci\u00f3n pueda ser parte del sistema de salud cuando lo necesita, de manera igualitaria y con equidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director del Hospital, Diego Lanzotti tom\u00f3 la palabra y coment\u00f3: \u201cEs un hito importante el del d\u00eda de hoy porque se juntan las voluntades del Gobierno provincial y el municipal, senadores, empresarios y los ciudadanos, representados por la Cooperadora\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste elemento tecnol\u00f3gico va a lograr que podamos aplicar antes las dosis de plasma de convaleciente para lograr que m\u00e1s ciudadanos se recuperen. Quiero convocar a las personas que padecieron la enfermedad y se recuperaron a que se acerquen al Hospital y podamos tener la cantidad de plasma suficiente para todos los enfermos\u201d; finaliz\u00f3 el m\u00e9dico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n estuvieron presentes en la recorrida, el presidente del Centro Comercial e Industrial de Rafaela y la Regi\u00f3n, Diego Castro; la jefa del Servicio de Hemoterapia del Hospital, Marisa Rubin; la coordinadora de Epidemiolog\u00eda de la Direcci\u00f3n Regional de Salud Rafaela, Sandra Capello y el subsecretario de Salud del Municipio, Mart\u00edn Racca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Visita a dos instituciones<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.sabado100.com.ar\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-19-at-20.54.59-1-1024x635.jpeg\" alt=\"\" class=\"wp-image-9835\"\/><figcaption>Perotti, Morel y Castellano en el flamante gimnasio \u00abRicardo Goddio\u00bb.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de la recorrida por el Hospital, el gobernador Omar Perotti y el intendente Luis Castellano se acercaron al club 9 de Julio para recorrer las instalaciones del nuevo gimnasio deportivo \u201cRicardo Goddio\u201d que se inaugurar\u00e1 el d\u00eda de ma\u00f1ana. Fueron recibidos por su presidente Hugo Morel, quien por agradecimiento a la visita, les entreg\u00f3 una remera de la instituci\u00f3n juliense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.sabado100.com.ar\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-19-at-20.54.59-2-1024x682.jpeg\" alt=\"\" class=\"wp-image-9836\"\/><figcaption>Perotti y Castellano con autoridades del CCIRR.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Finalizaron la jornada con un encuentro con la comisi\u00f3n del Centro Comercial e Industrial donde conversaron sobre temas de agenda y proyectos en com\u00fan a futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la presencia del gobernador Perotti, el intendente Castellano y profesionales m\u00e9dicos, comenz\u00f3 a funcionar el equipo de af\u00e9resis en el Hospital \u201cDr. Jaime Ferr\u00e9\u201d. Este equipamiento, valuado en $ 4 millones, permitir\u00e1 que la donaci\u00f3n de plasma pueda realizarse en nuestra ciudad.<\/p>\n","protected":false},"author":2,"featured_media":9834,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[4632],"class_list":["post-9833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Con la presencia del gobernador Perotti, el intendente Castellano y profesionales m\u00e9dicos, comenz\u00f3 a funcionar el equipo de af\u00e9resis en el Hospital \u201cDr. Jaime Ferr\u00e9\u201d. Este equipamiento, valuado en $ 4 millones, permitir\u00e1 que la donaci\u00f3n de plasma pueda realizarse en nuestra ciudad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-20T01:24:17+00:00\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela\",\"datePublished\":\"2020-11-20T01:24:17+00:00\",\"dateModified\":\"2020-11-20T01:24:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/\"},\"wordCount\":950,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/\",\"name\":\"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-11-20T01:24:17+00:00\",\"dateModified\":\"2020-11-20T01:24:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/","og_locale":"es_ES","og_type":"article","og_title":"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela - Sabado 100","og_description":"Con la presencia del gobernador Perotti, el intendente Castellano y profesionales m\u00e9dicos, comenz\u00f3 a funcionar el equipo de af\u00e9resis en el Hospital \u201cDr. Jaime Ferr\u00e9\u201d. Este equipamiento, valuado en $ 4 millones, permitir\u00e1 que la donaci\u00f3n de plasma pueda realizarse en nuestra ciudad.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2020-11-20T01:24:17+00:00","author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela","datePublished":"2020-11-20T01:24:17+00:00","dateModified":"2020-11-20T01:24:17+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/"},"wordCount":950,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#primaryimage"},"thumbnailUrl":"","keywords":["Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/","url":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/","name":"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-11-20T01:24:17+00:00","dateModified":"2020-11-20T01:24:17+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/salud-puso-en-marcha-el-equipo-de-aferesis-plasmatica-en-rafaela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Salud puso en marcha el equipo de af\u00e9resis plasm\u00e1tica en Rafaela"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/9833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=9833"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/9833\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=9833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=9833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=9833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}