{"id":9709,"date":"2020-11-10T20:45:39","date_gmt":"2020-11-10T23:45:39","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=9709"},"modified":"2020-11-10T20:45:39","modified_gmt":"2020-11-10T23:45:39","slug":"aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/","title":{"rendered":"Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por\u00a0<a href=\"https:\/\/www.lanacion.com.ar\/autor\/alan-soria-guadalupe-7262\">Alan Soria Guadalupe<\/a>.-<\/strong> <strong>El Senado se mantiene como el obst\u00e1culo m\u00e1s dif\u00edcil de superar para el proyecto de\u00a0<\/strong><a href=\"https:\/\/www.lanacion.com.ar\/politica\/seguir-marcando-una-agenda-propia-objetivo-del-nid2505502\">legalizaci\u00f3n del aborto.<\/a>\u00a0La C\u00e1mara alta a\u00fan mantendr\u00eda el rechazo a la iniciativa seg\u00fan un relevamiento en base a\u00a0<a href=\"https:\/\/www.lanacion.com.ar\/politica\/debate-por-el-aborto-segui-el-conteo-de-votos-en-tiempo-real-nid2160090\">c\u00f3mo votaron los legisladores en 2018,<\/a>\u00a0los cambios manifestados desde entonces y qu\u00e9 expresaron p\u00fablicamente los diputados y senadores que asumieron el a\u00f1o pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El escenario arrojar\u00eda los mismos resultados que la \u00faltima votaci\u00f3n, cuando la iniciativa super\u00f3 la instancia en Diputados, para luego ser rechazada en la C\u00e1mara alta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien la votaci\u00f3n depender\u00e1 de la cantidad de legisladores que haya en ese momento en el recinto,<strong>&nbsp;si se tiene en cuenta la totalidad de los 72 senadores, hay 35 que est\u00e1n en contra y 32 que est\u00e1n a favor. Hay cuatro indefinidos y una abstenci\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En una discusi\u00f3n que se espera que se defina voto a voto,<\/strong>&nbsp;el escenario en la C\u00e1mara alta puede cambiar de un momento a otro a partir del a\u00f1o que viene.&nbsp;<strong>El Senado tiene por ahora un voto en contra menos debido a la licencia extendida del senador Jos\u00e9 Alperovich<\/strong>&nbsp;(Tucum\u00e1n &#8211; Frente de Todos), que ya hab\u00eda manifestado su rechazo al proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El legislador, acusado de abuso sexual,&nbsp;<a href=\"https:\/\/www.lanacion.com.ar\/politica\/acusado-abuso-sexual-el-senado-aprobo-nueva-nid2373666\">pidi\u00f3 en agosto<\/a>&nbsp;mantenerse fuera de actividad por m\u00e1s tiempo por las demoras en los tiempos procesales que gener\u00f3 la pandemia.&nbsp;<strong>Alperovich volver\u00eda a ocupar su banca el 1\u00ba de enero.<\/strong>&nbsp;La fecha en la que el oficialismo inicie el debate en el Congreso ser\u00e1 clave.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los senadores indefinidos est\u00e1n&nbsp;<strong>Stella Olalla&nbsp;<\/strong>(Entre R\u00edos &#8211; Juntos por el Cambio),&nbsp;<strong>Edgardo Kueider<\/strong>&nbsp;(Entre R\u00edos, Frente de Todos),&nbsp;<strong>Roberto Mirabella<\/strong>&nbsp;(Santa Fe &#8211; Frente de Todos) y&nbsp;<strong>Jos\u00e9 Emilio Neder<\/strong>&nbsp;(Santiago del Estero &#8211; Frente C\u00edvico por Santiago).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lucila Crexell<\/strong>&nbsp;(Neuqu\u00e9n &#8211; Frente de Todos), en tanto, se abstuvo en la votaci\u00f3n de hace dos a\u00f1os, pero est\u00e1 a favor de la despenalizaci\u00f3n hasta la semana 12 de embarazo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/bucket3.glanacion.com\/anexos\/fotos\/68\/3198568h768.jpg\" alt=\"En 2018, el proyecto de despenalizaci\u00f3n del aborto fue aprobado en Diputados pero el Senado lo rechazo\"\/><figcaption>En 2018 el proyecto de despenalizaci\u00f3n del aborto fue aprobado en Diputados pero el Senado lo rechazo.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"el-escenario-en-diputados\">El escenario en Diputados<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En la C\u00e1mara de Diputados, por su parte, el escenario estar\u00eda allanado<\/strong>&nbsp;para aprobar la iniciativa,&nbsp;<strong>aunque el n\u00famero de indefinidos tambi\u00e9n podr\u00eda inclinar la balanza<\/strong>&nbsp;en caso de que esos legisladores decidan votar a favor o en contra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que hace dos a\u00f1os,&nbsp;<strong>Diputados votar\u00eda a favor del proyecto. Lo har\u00eda por 108 votos a favor, contra 100 en contra. Sin embargo,&nbsp;todav\u00eda hay 48 legisladores que no expresaron su postura y una abstenci\u00f3n.&nbsp;<\/strong>Los que no dieron a conocer su posici\u00f3n son, en mayor\u00eda, diputados que iniciaron su mandato en diciembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El panorama en la C\u00e1mara baja cambi\u00f3 sensiblemente desde marzo, con la incorporaci\u00f3n de un voto a favor m\u00e1s tras la renuncia de&nbsp;<strong>Elisa Carri\u00f3<\/strong>&nbsp;a su banca. La dirigente fue reemplazada por&nbsp;<strong>Jos\u00e9 Pati\u00f1o&nbsp;<\/strong>(Ciudad de Buenos Aires &#8211; Pro), que se expres\u00f3 p\u00fablicamente a favor de la iniciativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los que no definieron su postura en Diputados es el presidente de la UCR,&nbsp;<strong>Alfredo Cornejo&nbsp;<\/strong>(Mendoza &#8211; Juntos por el Cambio), quien a principios de a\u00f1o&nbsp;<strong>hab\u00eda propuesto convocar a una consulta popular vinculante<\/strong>&nbsp;para definir si se debe avanzar en el proyecto o no.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como ocurre con otros proyectos de ley que promueven reformas a los derechos sociales, el&nbsp;<strong>proyecto de legalizaci\u00f3n del aborto no tiene un voto definido hacia un lado o el otro&nbsp;<\/strong>seg\u00fan el espacio. Si bien el Presidente apoya la iniciativa, por ejemplo, el jefe del bloque del PJ en el Senado,&nbsp;<strong>Jos\u00e9 Mayans, rechaza con crudeza el aborto y lo compara con la \u00abpena de muerte\u00bb.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De todos modos,&nbsp;<strong>en el Senado ser\u00e1 gravitante el modo en que se involucre Cristina Kirchner.&nbsp;<\/strong>La vicepresidenta se convirti\u00f3 en una de las abanderadas de la iniciativa en favor de la legalizaci\u00f3n del aborto, pero en el \u00faltimo tiempo envi\u00f3 se\u00f1ales para no adelantar el debate y, de eso modo, evitar las tensiones que llegar\u00e1n inevitablemente con la votaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"que-proponia-el-gobierno-en-marzo\">Qu\u00e9 propon\u00eda el Gobierno en marzo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El 1\u00ba de marzo, durante la apertura de sesiones legislativas, el presidente<strong>&nbsp;Alberto Fern\u00e1ndez&nbsp;<\/strong>anunci\u00f3 que estaba a punto de enviar al Congreso el proyecto de interrupci\u00f3n voluntaria del embarazo, pero la pandemia de coronavirus demor\u00f3 todos los planes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todav\u00eda no se conocen los detalles del proyecto de ley ni el nivel de similitud con el que se discuti\u00f3 hace dos a\u00f1os, durante el gobierno de&nbsp;<strong>Mauricio Macri.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por esa fecha, el oficialismo ten\u00eda previsto enviar el proyecto de legalizaci\u00f3n y plantearlo como un tema de salud p\u00fablica. Se propon\u00eda habilitar la interrupci\u00f3n voluntaria del embarazo hasta la semana 14 de gestaci\u00f3n, como hoy fija el C\u00f3digo Penal para los casos no punibles y en sinton\u00eda con el texto que se vot\u00f3 hace dos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto promovido por la Campa\u00f1a Nacional a favor del Aborto Legal, Seguro y Gratuito tampoco contempla la objeci\u00f3n de conciencia y establece que se puede abortar hasta la semana 14 de gestaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto estar\u00eda complementado con otra iniciativa que busca implementar un plan de \u00ab1000 d\u00edas\u00bb, que brindar\u00e1 ayuda econ\u00f3mica a la persona gestante y su hijo o hija durante los primeros a\u00f1os de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se hablaba, a principios de a\u00f1o, de la incorporaci\u00f3n de la objeci\u00f3n de conciencia institucional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong> https:\/\/www.lanacion.com.ar\/politica\/aborto-nid2505631<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara Alta mantendr\u00eda el rechazo a la iniciativa. Entre los senadores indefinidos est\u00e1n el rafaelino Roberto Mirabella, Stella Olalla (Entre R\u00edos), Edgardo Kueider (Entre R\u00edos) y Jos\u00e9 Neder (Santiago del Estero).<\/p>\n","protected":false},"author":2,"featured_media":9710,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[4596],"class_list":["post-9709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-aborto-legal-voto-por-voto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"La C\u00e1mara Alta mantendr\u00eda el rechazo a la iniciativa. Entre los senadores indefinidos est\u00e1n el rafaelino Roberto Mirabella, Stella Olalla (Entre R\u00edos), Edgardo Kueider (Entre R\u00edos) y Jos\u00e9 Neder (Santiago del Estero).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-10T23:45:39+00:00\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado\",\"datePublished\":\"2020-11-10T23:45:39+00:00\",\"dateModified\":\"2020-11-10T23:45:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/\"},\"wordCount\":1008,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Aborto legal: voto por voto\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/\",\"name\":\"Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-11-10T23:45:39+00:00\",\"dateModified\":\"2020-11-10T23:45:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/","og_locale":"es_ES","og_type":"article","og_title":"Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado - Sabado 100","og_description":"La C\u00e1mara Alta mantendr\u00eda el rechazo a la iniciativa. Entre los senadores indefinidos est\u00e1n el rafaelino Roberto Mirabella, Stella Olalla (Entre R\u00edos), Edgardo Kueider (Entre R\u00edos) y Jos\u00e9 Neder (Santiago del Estero).","og_url":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2020-11-10T23:45:39+00:00","author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado","datePublished":"2020-11-10T23:45:39+00:00","dateModified":"2020-11-10T23:45:39+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/"},"wordCount":1008,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#primaryimage"},"thumbnailUrl":"","keywords":["Aborto legal: voto por voto"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/","url":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/","name":"Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-11-10T23:45:39+00:00","dateModified":"2020-11-10T23:45:39+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/aborto-legal-voto-por-voto-como-es-el-escenario-en-diputados-y-el-senado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Aborto legal: voto por voto, c\u00f3mo es el escenario en Diputados y el Senado"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/9709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=9709"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/9709\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=9709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=9709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=9709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}