{"id":966,"date":"2006-08-12T23:08:49","date_gmt":"2006-08-12T21:08:49","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=966"},"modified":"2006-08-12T23:08:49","modified_gmt":"2006-08-12T21:08:49","slug":"no-es-cierto-que-la-tecnologia-lo-resuelve-todo","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/","title":{"rendered":"\u00abNo es cierto que la tecnolog\u00eda lo resuelve todo\u00bb"},"content":{"rendered":"<p>Se escucha aqu\u00ed y all\u00e1: de la mano de las nuevas tecnolog\u00edas, tarde o temprano, el mundo habr\u00e1 de parecerse a un para\u00edso. An\u00edbal Ford escucha con recelo ese discurso. Le suena a canto de sirenas. Egresado de Filosof\u00eda y Letras, profesor consulto de la Facultad de Ciencias Sociales de la Universidad de Buenos Aires (UBA) y ex director de la carrera de Comunicaci\u00f3n y de la maestr\u00eda en Comunicaci\u00f3n y Cultura de esa facultad, analiza el fen\u00f3meno desde la \u00f3ptica de la realidad pol\u00edtica y social. \u201cYo no soy un especialista en nuevas tecnolog\u00edas, sino en los problemas culturales que ellas generan\u201d, dice, y exhibe su preocupaci\u00f3n por la brecha que separa a los cibernavegantes de los millones de seres humanos que a\u00fan carecen de electricidad, agua potable y alfabetizaci\u00f3n.<\/p>\n<p>Periodista, escritor, investigador del Instituto Gino Germani y viajero incansable, ha publicado numerosas obras. En el campo de la ficci\u00f3n, \u201cSumbosa\u201d, \u201cRamos generales\u201d y \u201cOxidaci\u00f3n\u201d, entre otras; en el terreno del ensayo, dos de las m\u00e1s recientes son \u201cLa marca de la bestia\u201d y \u201cResto del mundo\u201d, ambas de Editorial Norma. Actualmente, junto con el antrop\u00f3logo Carlos Masotta, prepara un libro sobre el faro del fin del mundo, tarea que lo ha llevado a viajar varias veces a Isla de los Estados, en el extremo sur argentino.<\/p>\n<p>-\u00bfQu\u00e9 problemas plantea la desigual distribuci\u00f3n de las nuevas tecnolog\u00edas en el mundo globalizado?<\/p>\n<p>-Aunque se diga que lo que no est\u00e1 en Internet no existe, hay muchas cosas que est\u00e1n fuera de Internet. Y las utop\u00edas comunicacionales, es decir, las propuestas que afirman que, resueltos los problemas de comunicaci\u00f3n entre los hombres, se van a resolver los problemas del mundo, fracasaron siempre. Creo que hay que ubicar las nuevas tecnolog\u00edas en su lugar: no ignorarlas, pero tampoco endiosarlas. Los problemas econ\u00f3micos, pol\u00edticos y socioculturales que afectan al mundo exigen transformaciones estructurales, no simb\u00f3licas. Al trabajar sobre una agenda global no se puede ignorar la brecha entre riqueza y pobreza, brecha en la que el Programa de las Naciones Unidas para el Desarrollo viene insistiendo desde hace a\u00f1os y que, traducida en cifras, significa que el 80 por ciento de la riqueza se concentra en el 20 por ciento de la poblaci\u00f3n. Lo grave es que esa distancia va creciendo con el paso del tiempo. Eso explica una cantidad de conflictos contempor\u00e1neos como, por ejemplo, las migraciones desesperadas. Estamos hablando de situaciones realmente extremas: el 30 por ciento de los habitantes del planeta vive sin agua potable. En ese marco, analizo el problema de las nuevas tecnolog\u00edas.<\/p>\n<p>-\u00bfCritica la globalizaci\u00f3n?<\/p>\n<p>-Ante tanta apolog\u00eda de la globalizaci\u00f3n o de las formas en las que \u00e9sta se produce, hay que poner en escena las desigualdades comunicacionales. En ciertos pa\u00edses hay un televisor por habitante y en otros, un televisor cada cincuenta habitantes. Menos del tres por ciento de la poblaci\u00f3n mundial tiene la posibilidad de navegar por Internet. Gran parte de los seres humanos carecen de tel\u00e9fonos y ni siquiera han tenido acceso a la alfabetizaci\u00f3n. Entonces me pregunto si los problemas de los pa\u00edses que han quedado del otro lado de la vidriera se solucionan con las nuevas tecnolog\u00edas.<\/p>\n<p>-Hay quienes sostienen que con el auge de los blogs la informaci\u00f3n se ir\u00e1 democratizando, hasta hacer de cada ciudadano un periodista. \u00bfCu\u00e1l es su postura?<\/p>\n<p>-Creo que esa idea de democratizaci\u00f3n es ut\u00f3pica, aunque en la guerra de Irak se dieron situaciones interesantes: periodistas que en su blog escrib\u00edan lo que de verdad pensaban, mientras que para el diario escrib\u00edan otra cosa, de acuerdo con el contrato de lectura del peri\u00f3dico. En la guerra del Golfo, en cambio, hubo una censura muy cerrada; all\u00ed, el ej\u00e9rcito norteamericano logr\u00f3 manejar la informaci\u00f3n, mientras que en Irak se filtraron much\u00edsimos datos que produjeron fen\u00f3menos fuertes en el nivel comunicacional.<\/p>\n<p>-\u00bfPodr\u00eda dar un ejemplo?<\/p>\n<p>-S\u00ed: el tipo de difusi\u00f3n que tuvieron en Internet las fotos de las torturas practicadas contra los prisioneros iraqu\u00edes en la c\u00e1rcel de Abu Ghraib. No podemos soslayar que las im\u00e1genes de la tortura que estaban ubicadas en el plano m\u00e1s sexual pasaron de inmediato a la industria pornogr\u00e1fica, que incluso hizo filmaciones en las que simulaban el horror de aquella prisi\u00f3n. Eso fue ir mucho m\u00e1s all\u00e1 del l\u00edmite. Demasiado. Por eso creo que la supuesta democratizaci\u00f3n de las comunicaciones a partir de Internet y los blogs es muy irreal. Por otra parte, no hay que perder de vista que en la actualidad una decena de empresas manejan el 80 por ciento de la comunicaci\u00f3n, la informaci\u00f3n y la cultura en el nivel mundial. Hay se\u00f1ales de TV que tienen diez versiones diferentes para diez pa\u00edses diferentes, pero todas ellas est\u00e1n administradas desde el centro.<\/p>\n<p>-\u00bfC\u00f3mo est\u00e1 posicionada la Argentina en esa realidad del mercado televisivo?<\/p>\n<p>-Si tomo el conjunto de los canales de cable que se ven en la Argentina, puedo hacer etnograf\u00eda de los Estados Unidos porque tengo todos los perfiles de ese pa\u00eds, y he perdido, en cambio, muchas de las se\u00f1ales de Am\u00e9rica latina que se ve\u00edan en otra \u00e9poca. A eso hay que sumarle que en casi toda la zona pobre y des\u00e9rtica de la Argentina hay antenas parab\u00f3licas, con la posibilidad de acceder a los canales internacionales. Ese panorama nos obliga a plantearnos una serie de preguntas. \u00bfQu\u00e9 piensa alguien que est\u00e1 sumergido econ\u00f3micamente al ver las ostentaciones del centro del mundo por televisi\u00f3n? \u00bfOpta por la emigraci\u00f3n? \u00bfSe resiente? \u00bfConsigue meter esa informaci\u00f3n dentro de otro sistema cultural? Honestamente, no lo s\u00e9. Esto es algo que apenas empezamos a trabajar y, por el momento, desconocemos d\u00f3nde va a desembocar.<\/p>\n<p>-\u00bfQu\u00e9 peso tiene lo que se publica en Internet en la formaci\u00f3n de la opini\u00f3n p\u00fablica?<\/p>\n<p>-La influencia de Internet por ahora es indirecta. Es cierto que muchos de los que le\u00edan los diarios impresos ahora los consultan en la Red, pero esos lectores no son toda la sociedad. Actualmente estoy trabajando en la construcci\u00f3n de las noticias en casos excepcionales. El estudio parte de una lluvia de cenizas que ocurri\u00f3 en Buenos Aires en 1932, y estamos analizando c\u00f3mo construyeron la noticia los diarios de la \u00e9poca para compararlo con lo que es la informaci\u00f3n sobre cat\u00e1strofes en la actualidad.<\/p>\n<p>-Con referencia a la actualidad, ante un fen\u00f3meno como el tsunami, por ejemplo, \u00bfpueden los medios gr\u00e1ficos generar un impacto an\u00e1logo al que producen las im\u00e1genes transmitidas por TV?<\/p>\n<p>-Es diferente. Cuando se dio la lluvia de cenizas en 1932, Cr\u00edtica public\u00f3 fotos y un relato muy fuerte, casi b\u00edblico. Ahora, al ver en la pantalla del televisor la devastaci\u00f3n producida por un tsunami o la tragedia de Nueva Orle\u00e1ns, uno percibe lo que est\u00e1 pasando y de inmediato lo une con otros registros televisivos, como las series sobre cat\u00e1strofes naturales. Y, finalmente, toda esa informaci\u00f3n se recopila como espect\u00e1culo.<\/p>\n<p>-\u00bfQu\u00e9 ocurre con la comunicaci\u00f3n de las tragedias provocadas por los hombres, como los atentados terroristas?<\/p>\n<p>-Hay ciertos puntos de conexi\u00f3n en el modo como se comunican las cat\u00e1strofes naturales y las producidas por acci\u00f3n del hombre. La bomba en Londres o el atentado a la AMIA, por citar dos casos, tambi\u00e9n son episodios que sacuden a toda la sociedad y que rompen la rutina informativa. Pero adem\u00e1s exigen comprensi\u00f3n y b\u00fasqueda de sentido con urgencia. El punto de conflicto es que faltan herramientas para darles sentido de inmediato.<\/p>\n<p>-En cuanto a las posibilidades de encontrar el sentido de lo que ocurre, \u00bfla televisi\u00f3n est\u00e1 por delante o por detr\u00e1s de la gr\u00e1fica?<\/p>\n<p>-Ante todo, hay que considerar que el hombre busca sentido y que, cuando no lo encuentra, experimenta mucha angustia. El hombre tiene una pulsi\u00f3n por el sentido. La gr\u00e1fica, en virtud de su tradici\u00f3n documentalista y de su archivo, tiene m\u00e1s posibilidades de ubicar lo que ha ocurrido dentro de una serie. Frente a un accidente de avi\u00f3n, por caso, un medio gr\u00e1fico presenta la noticia y adem\u00e1s hace referencia a los diez \u00faltimos accidentes de avi\u00f3n. En la gr\u00e1fica a\u00fan se siente la presencia de un archivo que la televisi\u00f3n no tiene. La televisi\u00f3n se mueve en otro nivel y suele ocurrir, como de hecho ocurri\u00f3 con el atentado a la AMIA, que el camar\u00f3grafo vaya por arriba del periodista: lo que est\u00e1 mostrando el camar\u00f3grafo es m\u00e1s fuerte que lo que est\u00e1 diciendo el periodista en el mismo momento. Pero la imagen, salvo en casos excepcionales, es ambigua: si no tiene un pie de escritura y si se la muestra fuera del contexto, puede interpretarse de varias maneras.<\/p>\n<p>-\u00bfC\u00f3mo deber\u00edan enfrentar los medios gr\u00e1ficos el desaf\u00edo que les plantea la televisi\u00f3n? \u00bfTratando de parecerse a ella con textos hiperbreves, o privilegiando la escritura, el an\u00e1lisis y la opini\u00f3n?<\/p>\n<p>-En esto hay dos posiciones, pero antes de analizarlas hay que dejar en claro que el periodismo gr\u00e1fico es muy peque\u00f1o en comparaci\u00f3n con los otros medios. Basta pensar que The New York Times tira un mill\u00f3n ochocientos mil ejemplares, mientras que MTV llega a cuatrocientos millones de personas. En cuanto al modo en que la gr\u00e1fica enfrenta el desaf\u00edo de la TV, en los Estados Unidos se han dado diversas reacciones. USA Today tom\u00f3 un modelo muy televisivo: textos breves, muchas fotograf\u00edas y muchas ilustraciones. The New York Times, la vieja dama gris, sigue privilegiando la informaci\u00f3n, aunque ha pasado a presentarla de otro modo: en sus primeras planas aparece cada vez m\u00e1s informaci\u00f3n editorial y menos noticias de \u00faltimo momento. En el caso de The Wall Street Journal hay un mantenimiento total del contrato de lectura, a tal punto que el 11 de septiembre de 2001 fue el \u00fanico diario que no public\u00f3 ninguna foto del atentado en la tapa.<\/p>\n<p>-En \u00abLa marca de la bestia\u00bb, usted hablaba del crecimiento de las zonas de informaci\u00f3n general en los peri\u00f3dicos y del decrecimiento de la lectura de las \u00abzonas duras\u00bb (pol\u00edtica, internacionales, econom\u00eda). \u00bfCu\u00e1l es el origen y la vigencia de esa transformaci\u00f3n?<\/p>\n<p>-Durante la d\u00e9cada del 90 hubo un gran desarrollo de lo que yo denomino \u00abinfoentretenimiento\u00bb. Es decir, el cruce entre informaci\u00f3n y entretenimiento. Se pens\u00f3 que con la ca\u00edda del Muro de Berl\u00edn se hab\u00edan terminado los grandes problemas. Pero ese modelo entr\u00f3 en crisis en los \u00faltimos dos o tres a\u00f1os, en los que fue necesario volver a un tipo de informaci\u00f3n m\u00e1s dura.<\/p>\n<p>-\u00bfPor qu\u00e9 se agot\u00f3 aquel modelo de comunicaci\u00f3n?<\/p>\n<p>-Porque cuando Francis Fukuyama proclamaba que se hab\u00eda acabado la historia, estaba macaneando. La historia no hab\u00eda terminado. Desde los 90 hasta ahora hubo una enorme cantidad de conflictos b\u00e9licos, un terrible crecimiento de la brecha entre riqueza y pobreza, migraciones desesperadas y crisis socioecon\u00f3micas que demostraron que el mundo segu\u00eda con una historia pesada, muy fuerte.<\/p>\n<p>Adriana Schettini<\/p>\n<p>Fuente: diario La Naci\u00f3n, Buenos Aires, 12 de agosto de 2006.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es la opini\u00f3n del escritor An\u00edbal Ford quien analiza la actualidad socio-cultural del pa\u00eds y del mundo durante una entrevista.<\/p>\n<p>Por Adriana Schettini <\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4,26],"tags":[],"class_list":["post-966","post","type-post","status-publish","format-standard","hentry","category-cultura-y-sociedad","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;No es cierto que la tecnolog\u00eda lo resuelve todo&quot; - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;No es cierto que la tecnolog\u00eda lo resuelve todo&quot; - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Es la opini\u00f3n del escritor An\u00edbal Ford quien analiza la actualidad socio-cultural del pa\u00eds y del mundo durante una entrevista. Por Adriana Schettini\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2006-08-12T21:08:49+00:00\" \/>\n<meta name=\"author\" content=\"sabado100\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado100\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/\"},\"author\":{\"name\":\"sabado100\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/1a82439a05a3356129d4d51dd7ca16b4\"},\"headline\":\"\u00abNo es cierto que la tecnolog\u00eda lo resuelve todo\u00bb\",\"datePublished\":\"2006-08-12T21:08:49+00:00\",\"dateModified\":\"2006-08-12T21:08:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/\"},\"wordCount\":1964,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"articleSection\":[\"Cultura y Sociedad\",\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/\",\"name\":\"\\\"No es cierto que la tecnolog\u00eda lo resuelve todo\\\" - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"datePublished\":\"2006-08-12T21:08:49+00:00\",\"dateModified\":\"2006-08-12T21:08:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abNo es cierto que la tecnolog\u00eda lo resuelve todo\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/1a82439a05a3356129d4d51dd7ca16b4\",\"name\":\"sabado100\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4048f7037fffe4fd73611d5730c1cb40.jpg?ver=1787740882\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4048f7037fffe4fd73611d5730c1cb40.jpg?ver=1787740882\",\"caption\":\"sabado100\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado1002\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"No es cierto que la tecnolog\u00eda lo resuelve todo\" - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/","og_locale":"es_ES","og_type":"article","og_title":"\"No es cierto que la tecnolog\u00eda lo resuelve todo\" - Sabado 100","og_description":"Es la opini\u00f3n del escritor An\u00edbal Ford quien analiza la actualidad socio-cultural del pa\u00eds y del mundo durante una entrevista. Por Adriana Schettini","og_url":"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2006-08-12T21:08:49+00:00","author":"sabado100","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado100","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/"},"author":{"name":"sabado100","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/1a82439a05a3356129d4d51dd7ca16b4"},"headline":"\u00abNo es cierto que la tecnolog\u00eda lo resuelve todo\u00bb","datePublished":"2006-08-12T21:08:49+00:00","dateModified":"2006-08-12T21:08:49+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/"},"wordCount":1964,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"articleSection":["Cultura y Sociedad","General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/","url":"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/","name":"\"No es cierto que la tecnolog\u00eda lo resuelve todo\" - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"datePublished":"2006-08-12T21:08:49+00:00","dateModified":"2006-08-12T21:08:49+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/no-es-cierto-que-la-tecnologia-lo-resuelve-todo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"\u00abNo es cierto que la tecnolog\u00eda lo resuelve todo\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/1a82439a05a3356129d4d51dd7ca16b4","name":"sabado100","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4048f7037fffe4fd73611d5730c1cb40.jpg?ver=1787740882","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4048f7037fffe4fd73611d5730c1cb40.jpg?ver=1787740882","caption":"sabado100"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado1002\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=966"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/966\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}