{"id":8469,"date":"2020-08-08T19:14:50","date_gmt":"2020-08-08T22:14:50","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=8469"},"modified":"2020-08-08T19:14:50","modified_gmt":"2020-08-08T22:14:50","slug":"concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/","title":{"rendered":"Concurso literario de la juventud del Club de Leones de Rafaela"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/m.ellitoral.com\/um\/fotos\/291543_club_de_leones.jpg\" alt=\"El Club de Leones cumpli\u00f3 60 a\u00f1os de &quot;servicio&quot; : : El Litoral ...\"\/><figcaption>El Club de Leones funciona en calle Alem 346.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Club de Leones de Rafaela difundi\u00f3 las <strong>b<u>ases y condiciones<\/u><\/strong> del concurso literario de la juventud, que a continuaci\u00f3n se transcriben:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>1) Participantes: <\/u><\/strong>Todos los j\u00f3venes de 16 a 30 a\u00f1os, residentes en la ciudad de Rafaela y su zona de influencia (localidades vecinas), cuyas obras no hayan sido premiadas ni publicadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>2)Fundamentaci\u00f3n del certamen<\/u>: &nbsp;<\/strong>El Leonismo,&nbsp;consciente del especial momento que les ha tocado vivir a los j\u00f3venes, en el marco de un mundo aquejado por la pandemia del COVID19, en el que se vive en una cuarentena que impide una comunicaci\u00f3n directa con pares, familiares y la comunidad en general, en este mes de <strong>agosto<\/strong>, especialmente dedicado a la <strong>juventud<\/strong>, intenta incentivarlos a reflexionar acerca de las consecuencias psicof\u00edsicas, emocionales y econ\u00f3mico-sociales que produce este flagelo, gracias al aporte y la mirada particular de su grupo etario, para que puedan incorporarse de manera efectiva y contribuir desde su \u00e1mbito, al nacimiento de un mundo m\u00e1s justo y solidario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>3) Tema de los escritos: <\/u><\/strong><strong>\u201cLa bondad importa en tiempos de pandemia<\/strong><strong>.\u00bb<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>4) G\u00e9neros:<\/u><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong><u>Prosa:<\/u>&nbsp;<\/strong>m\u00e1ximo tres carillas A 4.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong><u>Poes\u00eda<\/u>:&nbsp;<\/strong>m\u00e1ximo cincuenta versos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>&nbsp;5) N\u00famero de obras que pueden ser enviadas: <\/u><\/strong>&nbsp;Hasta dos por categor\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>&nbsp;6) Presentaci\u00f3n<\/u><\/strong><strong>:&nbsp;<\/strong>en hoja A4, fuente Arial, cuerpo 12, a dos espacios, por triplicado y firmado con seud\u00f3nimo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>7) Datos del autor<\/u><\/strong>: dentro del sobre de env\u00edo tama\u00f1o oficio, se incluir\u00e1 otro m\u00e1s peque\u00f1o cerrado, que incluir\u00e1 los&nbsp; datos personales del escritor&nbsp; (apellido, nombres, edad, domicilio, tel\u00e9fono, localidad, seud\u00f3nimo, correo electr\u00f3nico y copia del DNI), en cuya cubierta se determinar\u00e1 la categor\u00eda, nombre del \/los trabajo(s) y el seud\u00f3nimo utilizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>8) Recepci\u00f3n:<\/u><\/strong>&nbsp;Desde el 12 de agosto (D\u00eda Internacional de la Juventud)&nbsp;hasta el 31 de octubre de 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>9) Jurado<\/u><\/strong>: se expedir\u00e1 el durante el mes de noviembre&nbsp; de 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>10) Premios: <\/u><\/strong>se adjudicar\u00e1n dos premios por g\u00e9nero: primero y segundo, consistentes en diploma y medalla, quedando librada &nbsp;a decisi\u00f3n del Jurado la cantidad de menciones a otorgar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>11) Entrega de premios<\/u><\/strong><strong>:<\/strong>&nbsp;seg\u00fan fecha a comunicar con antelaci\u00f3n,&nbsp;en acto a realizarse en la \u201cCasa del Le\u00f3n\u201d,&nbsp; sede del Club de Leones de Rafaela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>12) Env\u00edo de los trabajos<\/u><\/strong><strong>: &nbsp;\u201c<\/strong>Concurso Literario de la Juventud\u201d&nbsp;, a Leandro N. Alem 346 (2300) Rafaela (Santa Fe) . Por correo o personalmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><u>13) Aclaraci\u00f3n:<\/u><\/strong> Las obras que no resultasen premiadas podr\u00e1n ser retiradas por sus autores, hasta 60 d\u00edas despu\u00e9s de la fecha de entrega de premios, en la sede del Club de Leones de Rafaela,&nbsp;Alem 346, Rafaela, Sta. Fe, en horario de Secretar\u00eda: de 8:00 a 12:00.&nbsp; Los sobres con datos personales s\u00f3lo ser\u00e1n abiertos en el caso de que fueran seleccionados, siendo destruidos los de quienes no recibieran ninguna distinci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Club de Leones de Rafaela difundi\u00f3 las bases y condiciones del concurso literario de la juventud, que a continuaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8470,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4,26],"tags":[4911],"class_list":["post-8469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-y-sociedad","category-general","tag-concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Concurso literario de la juventud del Club de Leones de Rafaela - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concurso literario de la juventud del Club de Leones de Rafaela - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"El Club de Leones de Rafaela difundi\u00f3 las bases y condiciones del concurso literario de la juventud, que a continuaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-08T22:14:50+00:00\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"Concurso literario de la juventud del Club de Leones de Rafaela\",\"datePublished\":\"2020-08-08T22:14:50+00:00\",\"dateModified\":\"2020-08-08T22:14:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/\"},\"wordCount\":520,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Concurso literario de la juventud del Club de Leones de Rafaela\"],\"articleSection\":[\"Cultura y Sociedad\",\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/\",\"name\":\"Concurso literario de la juventud del Club de Leones de Rafaela - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-08-08T22:14:50+00:00\",\"dateModified\":\"2020-08-08T22:14:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Concurso literario de la juventud del Club de Leones de Rafaela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concurso literario de la juventud del Club de Leones de Rafaela - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/","og_locale":"es_ES","og_type":"article","og_title":"Concurso literario de la juventud del Club de Leones de Rafaela - Sabado 100","og_description":"El Club de Leones de Rafaela difundi\u00f3 las bases y condiciones del concurso literario de la juventud, que a continuaci\u00f3n [&hellip;]","og_url":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2020-08-08T22:14:50+00:00","author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"Concurso literario de la juventud del Club de Leones de Rafaela","datePublished":"2020-08-08T22:14:50+00:00","dateModified":"2020-08-08T22:14:50+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/"},"wordCount":520,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#primaryimage"},"thumbnailUrl":"","keywords":["Concurso literario de la juventud del Club de Leones de Rafaela"],"articleSection":["Cultura y Sociedad","General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/","url":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/","name":"Concurso literario de la juventud del Club de Leones de Rafaela - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-08-08T22:14:50+00:00","dateModified":"2020-08-08T22:14:50+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/concurso-literario-de-la-juventud-del-club-de-leones-de-rafaela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Concurso literario de la juventud del Club de Leones de Rafaela"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/8469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=8469"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/8469\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=8469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=8469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=8469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}