{"id":4405,"date":"2016-03-05T16:01:31","date_gmt":"2016-03-05T14:01:31","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=4405"},"modified":"2016-03-05T16:01:31","modified_gmt":"2016-03-05T14:01:31","slug":"analisis-de-la-audiencia-entre-el-papa-y-macri","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/","title":{"rendered":"An\u00e1lisis de la audiencia entre el Papa y Macri"},"content":{"rendered":"<p>Se trata del editorial del programa \u00abS\u00e1bado 100\u00bb por radio Sol Rafaela FM 90,9 que conduce Emilio Grande (h.).- El reciente encuentro entre Bergoglio y el actual Presidente de la Argentina sigue dando \u201ctela para cortar\u201d en la opini\u00f3n p\u00fablica, especialmente a la hora de comparar cuando Cristina Fern\u00e1ndez era la jefa del Estado y sus reuniones con Francisco.<br \/>\nA la ex presidenta la recibi\u00f3 en seis oportunidades, de las cuales tres fueron en el Vaticano, siendo la \u00faltima muy recordada cuando se apareci\u00f3 con integrantes de La C\u00e1mpora. Las otras tres veces fueron durante visitas papales en Brasil, Paraguay y Cuba.<br \/>\nA decir verdad, Su Santidad no hace acepciones de personas, recibiendo a las m\u00e1s altas autoridades gubernamentales del mundo, l\u00edderes religiosos de diferentes confesiones, pasando por no creyentes y pecadores, hasta el com\u00fan de la gente, en especial a los enfermos y ni\u00f1os, basta ver las audiencias generales de los mi\u00e9rcoles en la plaza San Pedro.<br \/>\nAlgunos analistas consideraron una supuesta frialdad en los gestos de Francisco. En cambio, para Macri \u201cel Papa fue extremadamente cordial\u201d, a tal punto que pregunt\u00f3: \u201cAqu\u00ed falta alguien\u201d, cuando vio a Juliana Awada, en alusi\u00f3n a su hija Antonia.<br \/>\nEl ex arzobispo de Buenos Aires le pidi\u00f3 a Macri con especial \u00e9nfasis que no ceda en su lucha contra la corrupci\u00f3n, el narcotr\u00e1fico, mayor inclusi\u00f3n social y la reconciliaci\u00f3n de los argentinos, verdades incontrastables de alguien que conoce al dedillo los problemas de fondo de nuestro pa\u00eds.<br \/>\nDicen que Jorge Bergoglio es peronista. El colega Morales Sol\u00e1 aclara que tuvo admiraci\u00f3n por el viejo Per\u00f3n setentista y consensual, pero fue cr\u00edtico del menemismo y m\u00e1s a\u00fan del kirchnerismo. No hay que olvidar el maltrato que le dispensaron N\u00e9stor y Cristina al ex cardenal, no asistiendo a los tedeums del 25 de Mayo y 9 de Julio, para no escuchar sus filosas cr\u00edticas.<br \/>\nOtro elemento a reflexionar es el rosario que le regal\u00f3 el Papa a Milagro Sala, que gener\u00f3 una pol\u00e9mica inusitada entre los duros kirchneristas y los anti. M\u00e1s all\u00e1 de las investigaciones y denuncias contra la l\u00edder juje\u00f1a y del mal proceso judicial porque est\u00e1 presa mientras hay ex funcionarios procesados del anterior Gobierno en libertad, el Papa regala cientos de rosarios con un sentido religioso buscando la conversi\u00f3n de las personas, de hecho a mi familia nos entreg\u00f3 cuatro el 5 de febrero de 2014 cuando estuvimos en el Vaticano. Tampoco son admisibles las declaraciones de Carri\u00f3 en que no debe entrometerse en la pol\u00edtica argentina al empoderar a violentos como Sala y Moreno.<br \/>\nFrancisco tiene una mirada misericordiosa, pacificadora y que ve m\u00e1s all\u00e1 de la temporal coyuntura nacional: si el Presidente argentino hubiera sido otro, le habr\u00eda pedido lo mismo que a Macri: luchar contra la corrupci\u00f3n, el narcotr\u00e1fico y la unidad nacional\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata del editorial del programa \u00abS\u00e1bado 100\u00bb por radio Sol Rafaela FM 90,9 que conduce Emilio Grande (h.).- El [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[31,5,29],"tags":[5443],"class_list":["post-4405","post","type-post","status-publish","format-standard","hentry","category-editorial","category-politica","category-religion","tag-analisis-de-la-audiencia-entre-el-papa-y-macri"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>An\u00e1lisis de la audiencia entre el Papa y Macri - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00e1lisis de la audiencia entre el Papa y Macri - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Se trata del editorial del programa \u00abS\u00e1bado 100\u00bb por radio Sol Rafaela FM 90,9 que conduce Emilio Grande (h.).- El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-05T14:01:31+00:00\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"An\u00e1lisis de la audiencia entre el Papa y Macri\",\"datePublished\":\"2016-03-05T14:01:31+00:00\",\"dateModified\":\"2016-03-05T14:01:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/\"},\"wordCount\":504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"keywords\":[\"An\u00e1lisis de la audiencia entre el Papa y Macri\"],\"articleSection\":[\"Editorial\",\"Pol\u00edtica\",\"Religi\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/\",\"name\":\"An\u00e1lisis de la audiencia entre el Papa y Macri - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"datePublished\":\"2016-03-05T14:01:31+00:00\",\"dateModified\":\"2016-03-05T14:01:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An\u00e1lisis de la audiencia entre el Papa y Macri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00e1lisis de la audiencia entre el Papa y Macri - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/","og_locale":"es_ES","og_type":"article","og_title":"An\u00e1lisis de la audiencia entre el Papa y Macri - Sabado 100","og_description":"Se trata del editorial del programa \u00abS\u00e1bado 100\u00bb por radio Sol Rafaela FM 90,9 que conduce Emilio Grande (h.).- El [&hellip;]","og_url":"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2016-03-05T14:01:31+00:00","author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"An\u00e1lisis de la audiencia entre el Papa y Macri","datePublished":"2016-03-05T14:01:31+00:00","dateModified":"2016-03-05T14:01:31+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/"},"wordCount":504,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"keywords":["An\u00e1lisis de la audiencia entre el Papa y Macri"],"articleSection":["Editorial","Pol\u00edtica","Religi\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/","url":"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/","name":"An\u00e1lisis de la audiencia entre el Papa y Macri - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"datePublished":"2016-03-05T14:01:31+00:00","dateModified":"2016-03-05T14:01:31+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/analisis-de-la-audiencia-entre-el-papa-y-macri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"An\u00e1lisis de la audiencia entre el Papa y Macri"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/4405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=4405"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/4405\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=4405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=4405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=4405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}