{"id":39401,"date":"2026-08-05T17:43:35","date_gmt":"2026-08-05T17:43:35","guid":{"rendered":"https:\/\/sabado100.com.ar\/es-ar\/?p=39401"},"modified":"2026-08-05T17:43:36","modified_gmt":"2026-08-05T17:43:36","slug":"funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/","title":{"rendered":"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por Emilio Grande (h.).-<\/strong> En una reuni\u00f3n \u201ccaliente\u201d, los funcionarios municipales Germ\u00e1n Bottero (secretario de Gobierno y Modernizaci\u00f3n) y Silvina Bravino (secretaria de Hacienda y Finanzas) subieron este ma\u00f1ana al 6\u00ba piso con el objetivo de brindar explicaciones y justificar el proyecto del Ejecutivo, que propone elevar el valor de la Unidad de Cuenta Municipal (UCM) de $72,71 a $102,47, lo que representa el 40,93% para el per\u00edodo de septiembre a diciembre de 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto en cuesti\u00f3n se tratar\u00e1 sobre tablas en la sesi\u00f3n ordinaria de este jueves a las 9:00 horas, que, en caso de aprobarse la actualizaci\u00f3n de la UCM, impactar\u00e1 en el valor de los tributos municipales (tasa, DREI, cementerio, ZEC, entre otros).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa UCM hace un a\u00f1o y medio que no se actualiza y tuvo que ver con el impacto del primer semestre de ese a\u00f1o; desde noviembre del 2025 no se aument\u00f3 m\u00e1s y ha sido rechazado mayoritariamente por el Concejo. M\u00e1s all\u00e1 de que est\u00e1 a la baja en los \u00faltimos tiempos, en un contexto inflacionario necesitamos actualizar los tributos que tienen un valor fijo y deben actualizarse conforme a los aumentos salariales y dem\u00e1s servicios, teniendo una urgencia particular la pol\u00edtica salarial, que ya cerr\u00f3 la Provincia, con el pedido de los municipales, siendo recursos extras que se ajustan por inflaci\u00f3n y necesitamos estos recursos para ajustarlos a la inflaci\u00f3n que hubo\u201d, justific\u00f3 Bottero al t\u00e9rmino del encuentro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre lo expresado por Bravino que el segundo semestre ser\u00e1 complicado en caso que siga congelada la UCM, solamente alcanzar\u00e1 para pagar sueldos y no prestar todos los servicios, el funcionario admiti\u00f3 que \u201ces verdad porque es una situaci\u00f3n compleja, la recaudaci\u00f3n interanual en coparticipaci\u00f3n ha ca\u00eddo respecto al 30% de inflaci\u00f3n interanual y los tributos municipales no se han movido. El segundo semestre ser\u00e1 complicado, hemos empezado con un plan de ajuste, cerrando los s\u00e1bados el transporte p\u00fablico, trabajar sobre las horas extras, tratar de hacer una reducci\u00f3n en alquileres, en un proceso que no es tan r\u00e1pido y autom\u00e1tico. El impacto ser\u00e1 en los meses posteriores. En virtud de ser buenos administradores y claros con el dinero de todos los rafaelinos no nos vamos a endeudar y, obviamente, gastar lo que tenemos. Si no est\u00e1 la posibilidad de aumentar, <a>seguiremos haciendo pol\u00edticas de reducci\u00f3n donde sea posible <\/a>para terminar el a\u00f1o\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTenemos compromisos tomados con la ciudadan\u00eda en terminar la plaza, la Recova, las veredas del centro, todas las obras del Odesur y del oeste; empezar el pavimento que fue cuestionado, es una decisi\u00f3n avanzar porque lo solicitaron los vecinos y lo necesita la ciudad. Las obras que est\u00e1n empezadas se van a terminar. Quiz\u00e1s esto nos obliga a repensar que empezamos de nuevo o cu\u00e1ndo lo hacemos; estamos transformando la ciudad que impacta positivamente\u201d, concluy\u00f3 Bottero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Opini\u00f3n de tres concejales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mar\u00eda Paz Caruso expres\u00f3 que \u201cnuevamente planteamos nuestra preocupaci\u00f3n por la falta de conocimiento que tiene la actual gesti\u00f3n respecto a las finanzas del Municipio. Lo \u00fanico que tienen en claro es que quieren aumentar los tributos. No saben para qu\u00e9 o por qu\u00e9. Simplemente porque no han proyectado correctamente las inversiones y hoy, como expres\u00f3 mi compa\u00f1ero de bloque Juan Senn, est\u00e1 en riesgo la estabilidad econ\u00f3mica del Municipio. La recaudaci\u00f3n es buena, el problema son las prioridades y lo que est\u00e1n haciendo con los recursos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Milagros Zafra se\u00f1al\u00f3 que \u201cen definitiva piden una actualizaci\u00f3n de la UCM de un 41%, seg\u00fan la polin\u00f3mica, que tiene en cuenta la inflaci\u00f3n, pero considerando la evoluci\u00f3n desde abril de 2023 los aumentos de UCM han ido por encima de la inflaci\u00f3n, aunque ellos manifiestan recaudar menos, pero no trajeron los datos. Dicen recaudar menos por coparticipaci\u00f3n, pero el crecimiento de la actividad econ\u00f3mica en Argentina es del 3% aproximadamente este a\u00f1o; as\u00ed que deber\u00edan justificar sus afirmaciones con los datos pertinentes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lisandro M\u00e1rsico mencion\u00f3 que \u201cse les pregunt\u00f3 si pensaban hacer un escalonamiento, los funcionarios respondieron que no, pero dejaban librado a los bloques alguna propuesta alternativa que se haga. Algunas preguntas respondieron y otras no. El justicialismo votar\u00e1 en contra sin ning\u00fan tipo de escalonamiento; desde LLA hicieron algunas preguntas y no quedaron conformes con las respuestas. El PJ solicit\u00f3 cu\u00e1nto pensaban ahorrar en forma programada con una estipulaci\u00f3n de los \u00edtems a recortar, que dijeron en una conferencia de prensa; en algunos se dio respuesta y en otros no\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo votar\u00e1n ma\u00f1ana los concejales? Caruso ensay\u00f3 una respuesta en voz alta: \u201cNada cambi\u00f3 desde hace dos meses a ahora; al contrario, no ejecutaron el plan de ajuste. Entiendo que se van a mantener en su postura anterior\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A decir verdad, el PJ ya se pronunci\u00f3 en contra del aumento, a Zafra no le convencieron las respuestas de los funcionarios municipales y M\u00e1rsico no tiene una postura tomada debido a las reuniones previstas en el PDP y en Unidos. Solamente, con otro voto negativo seguir\u00e1 el congelamiento hasta fin de 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Otros proyectos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Convenio marco de colaboraci\u00f3n &#8211; regularizaci\u00f3n dominial dentro del marco de ley nacional 24.374 (DEM):<\/strong>&nbsp;se refrenda el DFC-2026-805-E-MUNIRAFSF-INT, ratificatorio del contenido suscripto el 9 de junio de 2026 entre el Municipio, el Instituto Municipal de la Vivienda y el Ministerio de Igualdad y Desarrollo Humano de la provincia de Santa Fe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan los considerandos, la ley nacional 24.374 y sus modificatorias establece un r\u00e9gimen destinado a la regularizaci\u00f3n dominial de inmuebles ocupados con destino a vivienda \u00fanica y permanente, permitiendo que quienes posean una tenencia p\u00fablica, pac\u00edfica y continua durante al menos tres a\u00f1os anteriores al 1 de enero del 2009, puedan acceder a la titularidad dominial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Restaurar servicio de iluminaci\u00f3n p\u00fablica en diferentes sectores de la ciudad (Juntos Avancemos):<\/strong>&nbsp;solicitan al Departamento Ejecutivo Municipal que proceda a restaurar el servicio de iluminaci\u00f3n p\u00fablica en los siguientes sectores: espacio verde Abele y Bv. Lehmann (totalmente a oscuras, cuenta con columnas y reflectores); sector de la locomotora, Roque S\u00e1enz Pe\u00f1a y Av. Mitre; ruta nacional 34, traza urbana barrio 17 de Octubre\/Amancay (tramos completos de columnas en los canteros sin iluminaci\u00f3n); colectora Angela de la Casa barrios Martin Fierro y Amancay; colectora Club de Planeadores (varias columnas sin funcionar); plaza Progreso (sector de juegos); play\u00f3n deportivo barrio Mora (reflectores de columnas sin funcionar); Av. Italia y Canal Norte sobre la avenida (varias columnas sin funcionar); rotonda Bv. Yrigoyen y Av. Fader mano norte (varias columnas).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bottero dijo que \u201cdeben actualizarse conforme a los aumentos salariales y dem\u00e1s servicios\u201d, admitiendo que de no aprobarse \u201cseguiremos haciendo pol\u00edticas de reducci\u00f3n donde sea posible\u201d. El proyecto se votar\u00e1 sobre tablas este jueves. Opinan Caruso, Zafra y M\u00e1rsico.<\/p>\n","protected":false},"author":1,"featured_media":39402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[9242],"class_list":["post-39401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Funcionarios intentaron justificar el aumento del 41% en los tributos municipales - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Bottero dijo que \u201cdeben actualizarse conforme a los aumentos salariales y dem\u00e1s servicios\u201d, admitiendo que de no aprobarse \u201cseguiremos haciendo pol\u00edticas de reducci\u00f3n donde sea posible\u201d. El proyecto se votar\u00e1 sobre tablas este jueves. Opinan Caruso, Zafra y M\u00e1rsico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-05T17:43:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-05T17:43:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-05-at-12.30.07.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\"},\"headline\":\"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales\",\"datePublished\":\"2026-08-05T17:43:35+00:00\",\"dateModified\":\"2026-08-05T17:43:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/\"},\"wordCount\":1131,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-05-at-12.30.07.jpeg\",\"keywords\":[\"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/\",\"name\":\"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-05-at-12.30.07.jpeg\",\"datePublished\":\"2026-08-05T17:43:35+00:00\",\"dateModified\":\"2026-08-05T17:43:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-05-at-12.30.07.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-05-at-12.30.07.jpeg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sabado100.com.ar\/es-ar\"],\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/","og_locale":"es_ES","og_type":"article","og_title":"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales - Sabado 100","og_description":"Bottero dijo que \u201cdeben actualizarse conforme a los aumentos salariales y dem\u00e1s servicios\u201d, admitiendo que de no aprobarse \u201cseguiremos haciendo pol\u00edticas de reducci\u00f3n donde sea posible\u201d. El proyecto se votar\u00e1 sobre tablas este jueves. Opinan Caruso, Zafra y M\u00e1rsico.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2026-08-05T17:43:35+00:00","article_modified_time":"2026-08-05T17:43:36+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-05-at-12.30.07.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/"},"author":{"name":"admin","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5"},"headline":"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales","datePublished":"2026-08-05T17:43:35+00:00","dateModified":"2026-08-05T17:43:36+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/"},"wordCount":1131,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-05-at-12.30.07.jpeg","keywords":["Funcionarios intentaron justificar el aumento del 41% en los tributos municipales"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/","url":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/","name":"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-05-at-12.30.07.jpeg","datePublished":"2026-08-05T17:43:35+00:00","dateModified":"2026-08-05T17:43:36+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-05-at-12.30.07.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-05-at-12.30.07.jpeg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/funcionarios-intentaron-justificar-el-aumento-del-41-en-los-tributos-municipales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Funcionarios intentaron justificar el aumento del 41% en los tributos municipales"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","caption":"admin"},"sameAs":["https:\/\/sabado100.com.ar\/es-ar"],"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=39401"}],"version-history":[{"count":1,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39401\/revisions"}],"predecessor-version":[{"id":39403,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39401\/revisions\/39403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/39402"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=39401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=39401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=39401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}