{"id":39367,"date":"2026-08-03T21:58:18","date_gmt":"2026-08-03T21:58:18","guid":{"rendered":"https:\/\/sabado100.com.ar\/es-ar\/?p=39367"},"modified":"2026-08-03T21:58:20","modified_gmt":"2026-08-03T21:58:20","slug":"viotti-propuso-el-aumento-del-41-en-los-tributos-municipales","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/","title":{"rendered":"Viotti propuso el aumento del 41% en los tributos municipales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por Emilio Grande (h.).-<\/strong> En la ma\u00f1ana de este lunes, el intendente Leonardo Viotti se reuni\u00f3 con algunos concejales en el despacho de Intendencia para abordar distintos temas vinculados a la agenda de Rafaela. Participaron Mabel Fossatti (presidente del cuerpo), Juan Scavino, Valeria Soltermam, Milagros Zafra y Fabricio Dellasanta, como as\u00ed tambi\u00e9n el secretario de Gobierno y Modernizaci\u00f3n, Germ\u00e1n Bottero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En primer lugar, el mandatario inform\u00f3 que, a partir de la nueva ley org\u00e1nica de municipios, el proyecto de presupuesto 2027 podr\u00e1 ser presentado con posterioridad al 30 de septiembre, acord\u00e1ndose que el Ejecutivo prev\u00e9 remitir hacia fines de octubre al sexto piso. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la oportunidad, el Intendente se despach\u00f3 con el proyecto enviado por el Departamento Ejecutivo, que propone una actualizaci\u00f3n de la Unidad de Cuenta Municipal (UCM), que determina el valor de los tributos municipales (tasa, DREI, cementerio, ZEC, entre otros), proponiendo elevar el valor de la UCM de $72,71 a $102,47, lo que representa el 40,93% para el periodo de septiembre a diciembre de 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por este motivo, Viotti inform\u00f3 que la secretaria de Hacienda y Finanzas Silvina Bravino se encuentra a disposici\u00f3n para mantener reuniones con los ediles, con la premisa de brindar detalles de la propuesta y responder las consultas que surjan durante el an\u00e1lisis. La reuni\u00f3n est\u00e1 prevista este mi\u00e9rcoles a las 8:00 horas y no se descarta que este proyecto sea votado sobre tablas en la sesi\u00f3n ordinaria de este jueves a las 9:00 horas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-39369\" srcset=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35-1-1024x768.jpeg 1024w, https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35-1-300x225.jpeg 300w, https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35-1-768x576.jpeg 768w, https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35-1.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan los considerandos del proyecto ingresado al sexto piso, durante el 2025 y el primer semestre del 2026, los salarios, el combustible, la energ\u00eda, los repuestos, los contratos, los materiales y los restantes insumos necesarios para sostener los servicios municipales continuaron actualiz\u00e1ndose, mientras el valor de la UCM durante el 2025 se actualiz\u00f3 en un 26,56% y permaneci\u00f3 congelado durante todo el ejercicio 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el primer semestre del 2026 las remuneraciones del personal municipal fueron objeto de recomposiciones paritarias que acumularon un 16%, con impacto directo y permanente sobre uno de los principales componentes del gasto corriente municipal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La continuidad de la presi\u00f3n salarial para el segundo semestre constituye un hecho objetivo y previsible: la provincia de Santa Fe acord\u00f3 para su administraci\u00f3n central incrementos porcentuales que totalizan un 10,10%, con garant\u00edas que elevan la mejora hasta un 15,5% para los agentes de menores ingresos; y la negociaci\u00f3n paritaria municipal de la Festram estableci\u00f3 un incremento del 11%, distribuido entre los meses de julio, septiembre y noviembre del 2026, adem\u00e1s de la adecuaci\u00f3n del salario m\u00ednimo garantizado. La variaci\u00f3n salarial posee una ponderaci\u00f3n del 50% de la f\u00f3rmula polin\u00f3mica prevista en el art\u00edculo 31 de la tributaria 5635.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las sesiones ordinarias del 27 de noviembre de 2025 y del 4 de junio de 2026 fueron rechazados los aumentos propuestos por el Ejecutivo, congel\u00e1ndose la UCM en $72,71 durante 2026. Ahora Viotti va por un tercer intento con un descabellado aumento del 41% para el \u00faltimo cuatrimestre del a\u00f1o. El PJ ya se pronunci\u00f3 en contra, la LLA tiene que escuchar la justificaci\u00f3n de Bravino y M\u00e1rsico no tiene una postura tomada. \u00bfSer\u00e1 dos sin tres o se impondr\u00e1 el oficialismo? Estamos ante la presencia de finales abiertos, parafraseando a Pedro Sotolongo Codina (cient\u00edfico cubano)\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Opini\u00f3n de los concejales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Juan Senn:<\/strong> \u201cel Intendente pretende que el vecino pague con su bolsillo la administraci\u00f3n que hace de los recursos municipales. Nosotros no vamos a ser c\u00f3mplices de eso. Que ahora pretenda un impuestazo del 40% ya es demasiado. Si sigue as\u00ed, sin un plan de gobierno, va a fundir la Municipalidad. La Secretaria de Hacienda va a visitar el Concejo y, a pesar de que pedimos cambio de horario desde nuestro bloque porque no vamos a estar por otro compromiso asumido con anterioridad, decidieron que vaya igual\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Juan Scavino:<\/strong> \u201cese % es el que da la polin\u00f3mica, que incluso est\u00e1 por debajo de la inflaci\u00f3n; no es una cuesti\u00f3n de oficialismo o no oficialismo. Espero que el resto se d\u00e9 cuenta que no hay margen, se va a intentar votar este jueves porque ya hay referencias a nivel provincial y hay quienes quieren asfixiar al intendente Viotti, pero se tienen que dar cuenta que en esta ocasi\u00f3n asfixiar\u00edan a los empleados municipales porque la paritaria es con este recurso; de lo contrario, no te extra\u00f1es que el viernes haya alguna medida de fuerza o algo por el estilo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Milagros Zafra:<\/strong> \u201ctodav\u00eda no tenemos una decisi\u00f3n tomada porque hay que escuchar lo que dicen y c\u00f3mo est\u00e1n las cuentas del Municipio. En principio uno no quiere bajo ning\u00fan punto de vista avalar un aumento de impuestos y, por ese motivo, queremos saber qu\u00e9 tienen para justificar ese pedido\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Intendente inform\u00f3 del proyecto de actualizaci\u00f3n de la UCM en una reuni\u00f3n con algunos concejales en su despacho. Bravino explicar\u00e1 los fundamentos este mi\u00e9rcoles en el 6\u00ba piso. Se podr\u00eda tratar sobre tablas en la ordinaria de este jueves. Opinan Senn, Scavino y Zafra.<\/p>\n","protected":false},"author":1,"featured_media":39368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[23,5],"tags":[9233],"class_list":["post-39367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-politica","tag-viotti-propuso-el-aumento-del-41-en-los-tributos-municipales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Viotti propuso el aumento del 41% en los tributos municipales - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viotti propuso el aumento del 41% en los tributos municipales - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"El Intendente inform\u00f3 del proyecto de actualizaci\u00f3n de la UCM en una reuni\u00f3n con algunos concejales en su despacho. Bravino explicar\u00e1 los fundamentos este mi\u00e9rcoles en el 6\u00ba piso. Se podr\u00eda tratar sobre tablas en la ordinaria de este jueves. Opinan Senn, Scavino y Zafra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-03T21:58:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T21:58:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\"},\"headline\":\"Viotti propuso el aumento del 41% en los tributos municipales\",\"datePublished\":\"2026-08-03T21:58:18+00:00\",\"dateModified\":\"2026-08-03T21:58:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/\"},\"wordCount\":805,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35.jpeg\",\"keywords\":[\"Viotti propuso el aumento del 41% en los tributos municipales\"],\"articleSection\":[\"Econom\u00eda\",\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/\",\"name\":\"Viotti propuso el aumento del 41% en los tributos municipales - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35.jpeg\",\"datePublished\":\"2026-08-03T21:58:18+00:00\",\"dateModified\":\"2026-08-03T21:58:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35.jpeg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viotti propuso el aumento del 41% en los tributos municipales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sabado100.com.ar\/es-ar\"],\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viotti propuso el aumento del 41% en los tributos municipales - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/","og_locale":"es_ES","og_type":"article","og_title":"Viotti propuso el aumento del 41% en los tributos municipales - Sabado 100","og_description":"El Intendente inform\u00f3 del proyecto de actualizaci\u00f3n de la UCM en una reuni\u00f3n con algunos concejales en su despacho. Bravino explicar\u00e1 los fundamentos este mi\u00e9rcoles en el 6\u00ba piso. Se podr\u00eda tratar sobre tablas en la ordinaria de este jueves. Opinan Senn, Scavino y Zafra.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2026-08-03T21:58:18+00:00","article_modified_time":"2026-08-03T21:58:20+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/"},"author":{"name":"admin","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5"},"headline":"Viotti propuso el aumento del 41% en los tributos municipales","datePublished":"2026-08-03T21:58:18+00:00","dateModified":"2026-08-03T21:58:20+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/"},"wordCount":805,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35.jpeg","keywords":["Viotti propuso el aumento del 41% en los tributos municipales"],"articleSection":["Econom\u00eda","Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/","url":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/","name":"Viotti propuso el aumento del 41% en los tributos municipales - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35.jpeg","datePublished":"2026-08-03T21:58:18+00:00","dateModified":"2026-08-03T21:58:20+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/08\/WhatsApp-Image-2026-08-03-at-13.03.35.jpeg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/viotti-propuso-el-aumento-del-41-en-los-tributos-municipales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Viotti propuso el aumento del 41% en los tributos municipales"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","caption":"admin"},"sameAs":["https:\/\/sabado100.com.ar\/es-ar"],"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=39367"}],"version-history":[{"count":1,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39367\/revisions"}],"predecessor-version":[{"id":39370,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39367\/revisions\/39370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/39368"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=39367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=39367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=39367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}