{"id":39298,"date":"2026-07-30T13:39:22","date_gmt":"2026-07-30T13:39:22","guid":{"rendered":"https:\/\/sabado100.com.ar\/es-ar\/?p=39298"},"modified":"2026-07-30T13:39:23","modified_gmt":"2026-07-30T13:39:23","slug":"del-doble-beneficio","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/","title":{"rendered":"Del doble beneficio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Nota II y \u00faltima<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por Ricardo Miguel Fessia.-<\/strong> De pronto y con motivo de la agitada vida pol\u00edtica surgi\u00f3 un tema en donde escuchamos voces de un lado y del otro, movidas por simpat\u00edas o pasiones, pero se trata de un tema donde hay que usar la raz\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es la cuesti\u00f3n del doble beneficio jubilatorio: es decir si una misma persona puede recibir \u201cdos beneficios\u201d en forma conjunta. Se torn\u00f3 p\u00fablico o m\u00e1s p\u00fablico, a partir de la percepci\u00f3n de dos beneficios por parte de la ex presidente Cristina Fern\u00e1ndez y toda la saga de retiro de una de ellas y de suspensi\u00f3n luego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Memoriosos o hurgadores o justificadores, como sean, echaron mano a la memoria y trajeron del ostracismo a la tambi\u00e9n compa\u00f1era, Mar\u00eda Estela Mart\u00ednez de Per\u00f3n, tambi\u00e9n vicepresidente y presidente, dicho por orden cronol\u00f3gico, que percibe dos retribuciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isabel o Isabelita Per\u00f3n, tal como es m\u00e1s conocida, goza de un doble beneficio previsional y desde hace varias d\u00e9cadas vive en Espa\u00f1a, actualmente en Villafranca del Castillo, a las afueras de Madrid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando su esposo y presidente, el general Juan Per\u00f3n, fallece el 1 de julio de 1974, ella asume de inmediato como presidente de la Rep\u00fablica y, a nuestros efectos, el Instituto de Ayuda Financiera para el pago de Retiros y Pensiones Militares (IAF) -entidad creada por decreto-ley 13.461 del 14 de mayo de 1946- en cumplimiento de las previsiones de la ley del gobierno de facto N\u00ba 19.101 -promulgada el 30 de junio de 1.971-, y que rige actualmente con m\u00faltiples modificaciones para cada Fuerza desde su creaci\u00f3n en 1946 bajo la Presidencia de Edelmiro Farrell, le otorg\u00f3 la pensi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El IAF se cre\u00f3 por el gobierno de facto por medio del decreto-ley N\u00ba 13.641 del 14 de mayo de 1946 y ratificaci\u00f3n de inmediato por la ley N\u00b0 12.913 del 31 de diciembre de 1946 para darle fuerza de ley definitiva. La propia entidad se encarga de aclarar que esta normativa corresponde a un r\u00e9gimen especial de retiros y pensiones que nada tiene que ver con los llamados reg\u00edmenes de privilegios, es una situaci\u00f3n totalmente distinta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El otro beneficio de car\u00e1cter vitalicio, lo recibi\u00f3 por su condici\u00f3n de ex Presidente de la Naci\u00f3n, y le fue otorgada de acuerdo a la ley N\u00ba 16.989 sancionada y promulgada por el presidente de facto Juan Carlos Ongan\u00eda el 19 de octubre de 1.966 (Bolet\u00edn Oficial, 26 de octubre de 1966), pero que se efectiviz\u00f3 con posterioridad a 1984 cuando el presidente Ra\u00fal R. Alfons\u00edn concret\u00f3 un acuerdo pol\u00edtico con Isabel Per\u00f3n, enviando al Congreso un proyecto &nbsp;de ley de amnist\u00eda especial denominado \u201cInstrumento de reparaci\u00f3n hist\u00f3rica\u201d, que devino en la ley N\u00ba 23.062, sancionada el 23 de mayo de 1984, por la cual se declar\u00f3 comprendida en las previsiones de sus art\u00edculos a la expresidente, disponiendo que los jueces carecen de legitimaci\u00f3n para juzgar a las autoridades constitucionales destituidas por actos de rebeli\u00f3n, por ausencia del presupuesto representado, por su desafuero parlamentario o juicio pol\u00edtico previstos constitucionalmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atento a ello, y con su regreso al pa\u00eds para firmar el acuerdo se le abonaron las pensiones por viudez atrasadas, las propias como expresidente y los intereses por la herencia no percibida durante los siete a\u00f1os que fue retenida por la dictadura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ley N\u00ba 16.989 fue derogada a partir del 31 de diciembre de 1991 por el art\u00edculo 11 de la ley 23.966 (Bolet\u00edn Oficial, 20 de agosto de 1991), dando lugar a la sanci\u00f3n de la N\u00ba 24.018 del 13 de noviembre de 1991 (Bolet\u00edn Oficial, 18 diciembre de 1991).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por esta norma se otorgaron los beneficios previsionales a Cristina E. Fern\u00e1ndez de Kirchner, por lo que la situaci\u00f3n de ambas es diferente en lo legal, pero semejante en los privilegios que la pol\u00edtica dispone de acuerdo a distintas circunstancias que pueden ser atendible o criticables, pero est\u00e1n contenidas en un marco normativo y para ello se requieren de acuerdo entre las distintas fuerzas pol\u00edticas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Isabelita Per\u00f3n goza de un doble beneficio previsional y desde hace varias d\u00e9cadas vive en Espa\u00f1a, a las afueras de Madrid.<\/p>\n","protected":false},"author":1,"featured_media":39301,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[9211],"class_list":["post-39298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-y-sociedad","tag-del-doble-beneficio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Del doble beneficio - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Del doble beneficio - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Isabelita Per\u00f3n goza de un doble beneficio previsional y desde hace varias d\u00e9cadas vive en Espa\u00f1a, a las afueras de Madrid.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-30T13:39:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-30T13:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-10.38.56.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"992\" \/>\n\t<meta property=\"og:image:height\" content=\"734\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\"},\"headline\":\"Del doble beneficio\",\"datePublished\":\"2026-07-30T13:39:22+00:00\",\"dateModified\":\"2026-07-30T13:39:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/\"},\"wordCount\":686,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-10.38.56.jpeg\",\"keywords\":[\"Del doble beneficio\"],\"articleSection\":[\"Cultura y Sociedad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/\",\"name\":\"Del doble beneficio - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-10.38.56.jpeg\",\"datePublished\":\"2026-07-30T13:39:22+00:00\",\"dateModified\":\"2026-07-30T13:39:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-10.38.56.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-10.38.56.jpeg\",\"width\":992,\"height\":734},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Del doble beneficio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sabado100.com.ar\/es-ar\"],\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Del doble beneficio - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/","og_locale":"es_ES","og_type":"article","og_title":"Del doble beneficio - Sabado 100","og_description":"Isabelita Per\u00f3n goza de un doble beneficio previsional y desde hace varias d\u00e9cadas vive en Espa\u00f1a, a las afueras de Madrid.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2026-07-30T13:39:22+00:00","article_modified_time":"2026-07-30T13:39:23+00:00","og_image":[{"width":992,"height":734,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-10.38.56.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/"},"author":{"name":"admin","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5"},"headline":"Del doble beneficio","datePublished":"2026-07-30T13:39:22+00:00","dateModified":"2026-07-30T13:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/"},"wordCount":686,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-10.38.56.jpeg","keywords":["Del doble beneficio"],"articleSection":["Cultura y Sociedad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/","url":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/","name":"Del doble beneficio - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-10.38.56.jpeg","datePublished":"2026-07-30T13:39:22+00:00","dateModified":"2026-07-30T13:39:23+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-10.38.56.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-10.38.56.jpeg","width":992,"height":734},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/del-doble-beneficio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Del doble beneficio"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","caption":"admin"},"sameAs":["https:\/\/sabado100.com.ar\/es-ar"],"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=39298"}],"version-history":[{"count":1,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39298\/revisions"}],"predecessor-version":[{"id":39302,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39298\/revisions\/39302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/39301"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=39298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=39298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=39298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}