{"id":39257,"date":"2026-07-27T21:55:43","date_gmt":"2026-07-27T21:55:43","guid":{"rendered":"https:\/\/sabado100.com.ar\/es-ar\/?p=39257"},"modified":"2026-07-27T21:55:44","modified_gmt":"2026-07-27T21:55:44","slug":"envidiosa-o-victima-del-trauma","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/","title":{"rendered":"\u00bfEnvidiosa? O v\u00edctima del trauma"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por Luciana Mazzei.-<\/strong> La serie <em>Envidiosa<\/em> por Netflix ha logrado captar la atenci\u00f3n de muchos espectadores, por sus situaciones humor\u00edsticas y la exagerada e incluso grotesca imagen de esta mujer, celosa, caprichosa, que se compara con otros constantemente y critica a todos. M\u00e1s all\u00e1 de lo entretenido de los momentos que se producen entre ella y el resto de los protagonistas, vale la pena hacer un an\u00e1lisis m\u00e1s profundo sobre la \u201cenvidiosa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detr\u00e1s de esa mujer aparentemente segura de s\u00ed misma y un poco mundana se esconde una ni\u00f1a atravesada por el trauma de su infancia: un padre que las abandon\u00f3, a ella, a su hermana y a su madre; y una madre que tuvo que salir a ganarse la vida para sostener a sus hijas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero tambi\u00e9n acarrea con el mandato de casarse y tener hijos, para sanar esas heridas de la infancia que la dejaron hu\u00e9rfana y vulnerable, necesitada de amor y de ser vista. Vive atrapada en la inseguridad e insatisfacci\u00f3n que le provoca no lograr sus metas, dificultando la construcci\u00f3n de una identidad propia, desde donde vincularse asertivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Trauma infantil y su huella en los v\u00ednculos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hablamos de trauma para referirnos a situaciones que dejan a la persona sin capacidad de afrontamiento. Experiencias que generan una constante sensaci\u00f3n de amenaza, desamparo o p\u00e9rdida de control. El trauma no es solamente lo que nos sucede, sino tambi\u00e9n lo que ocurre dentro de nosotros como consecuencia de lo que vivimos (Garbor Mat\u00e9).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El trauma no se refiere s\u00f3lo a situaciones extremas de violencia o abuso. Las experiencias de abandono emocional, cr\u00edticas constantes, rechazo, falta de reconocimiento, negligencia parental, conflictos familiares intensos o v\u00ednculos poco seguros con las figuras de cuidado tambi\u00e9n dejan heridas y, para algunas personas, se convierten en trauma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto genera dificultades en el desarrollo emocional y relacional porque la persona aprende a adaptarse para defenderse y sobrevivir en un entorno que intuye poco seguro. Estas adaptaciones (huir, luchar, congelarse y agradar) se cronifican en la vinculaci\u00f3n de la persona, llegando a la adultez utilizando los mismos mecanismos cada vez que un entorno se manifiesta como poco seguro o amenazante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el d\u00eda a d\u00eda vemos a estas personas que tienen una necesidad constante de comparaci\u00f3n con otras personas, baja autoestima y sensaci\u00f3n de insuficiencia, miedo al rechazo o al abandono, dependencia emocional, dificultad para construir relaciones estables, celos excesivos, necesidad permanente de reconocimiento, sensaci\u00f3n de vac\u00edo aun cuando se alcanzan metas importantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La \u201cenvidiosa\u201d no tiene deseos de perjudicar a los otros, sino que sufre profundamente el dolor de pensar que carece de aquello que considera necesario para ser feliz, y se pierde la posibilidad de verse seg\u00fan sus cualidades, deseos y metas. Llev\u00e1ndola a una profunda sensaci\u00f3n de frustraci\u00f3n al no poder disfrutar de sus propios logros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su ni\u00f1a herida necesita ser vista y sentirse amada como quien en verdad es. Y en este recorrido la psic\u00f3loga la confronta con estas heridas, pero tambi\u00e9n la ayuda a abrir un abanico de posibilidades diferentes, pero parecidas a estas creencias tan arraigadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acompa\u00f1ada por la psic\u00f3loga, logra reconocer sus heridas, aprender a no repetir patrones de adaptaci\u00f3n y a tomar conciencia de que puede lograr relaciones m\u00e1s saludables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conocer el trauma propio no justifica el dolor que se puede provocar a los dem\u00e1s, pero si ayuda a comprenderse y a buscar ayuda para sanar. Todos tenemos una historia que condiciona nuestra manera de vincularnos, lo importante es preguntarnos \u00bfqu\u00e9 hago con este dolor?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La autora es mag\u00edster en orientaci\u00f3n familiar, radicada en la ciudad de Rafaela.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la serie por la plataforma de internet, la protagonista aparentemente segura de s\u00ed misma y un poco mundana se esconde una ni\u00f1a atravesada por el trauma de su infancia.<\/p>\n","protected":false},"author":1,"featured_media":39258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[9199],"class_list":["post-39257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-y-sociedad","tag-envidiosa-o-victima-del-trauma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfEnvidiosa? O v\u00edctima del trauma - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEnvidiosa? O v\u00edctima del trauma - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"En la serie por la plataforma de internet, la protagonista aparentemente segura de s\u00ed misma y un poco mundana se esconde una ni\u00f1a atravesada por el trauma de su infancia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-27T21:55:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-27T21:55:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/envidiosa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\"},\"headline\":\"\u00bfEnvidiosa? O v\u00edctima del trauma\",\"datePublished\":\"2026-07-27T21:55:43+00:00\",\"dateModified\":\"2026-07-27T21:55:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/\"},\"wordCount\":637,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/envidiosa.jpg\",\"keywords\":[\"\u00bfEnvidiosa? O v\u00edctima del trauma\"],\"articleSection\":[\"Cultura y Sociedad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/\",\"name\":\"\u00bfEnvidiosa? O v\u00edctima del trauma - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/envidiosa.jpg\",\"datePublished\":\"2026-07-27T21:55:43+00:00\",\"dateModified\":\"2026-07-27T21:55:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/envidiosa.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/envidiosa.jpg\",\"width\":770,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEnvidiosa? O v\u00edctima del trauma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sabado100.com.ar\/es-ar\"],\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEnvidiosa? O v\u00edctima del trauma - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfEnvidiosa? O v\u00edctima del trauma - Sabado 100","og_description":"En la serie por la plataforma de internet, la protagonista aparentemente segura de s\u00ed misma y un poco mundana se esconde una ni\u00f1a atravesada por el trauma de su infancia.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2026-07-27T21:55:43+00:00","article_modified_time":"2026-07-27T21:55:44+00:00","og_image":[{"width":770,"height":480,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/envidiosa.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/"},"author":{"name":"admin","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5"},"headline":"\u00bfEnvidiosa? O v\u00edctima del trauma","datePublished":"2026-07-27T21:55:43+00:00","dateModified":"2026-07-27T21:55:44+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/"},"wordCount":637,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/envidiosa.jpg","keywords":["\u00bfEnvidiosa? O v\u00edctima del trauma"],"articleSection":["Cultura y Sociedad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/","url":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/","name":"\u00bfEnvidiosa? O v\u00edctima del trauma - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/envidiosa.jpg","datePublished":"2026-07-27T21:55:43+00:00","dateModified":"2026-07-27T21:55:44+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/envidiosa.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/envidiosa.jpg","width":770,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/envidiosa-o-victima-del-trauma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"\u00bfEnvidiosa? O v\u00edctima del trauma"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","caption":"admin"},"sameAs":["https:\/\/sabado100.com.ar\/es-ar"],"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=39257"}],"version-history":[{"count":1,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39257\/revisions"}],"predecessor-version":[{"id":39259,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39257\/revisions\/39259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/39258"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=39257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=39257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=39257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}