{"id":39150,"date":"2026-07-20T18:21:56","date_gmt":"2026-07-20T18:21:56","guid":{"rendered":"https:\/\/sabado100.com.ar\/es-ar\/?p=39150"},"modified":"2026-07-20T18:21:58","modified_gmt":"2026-07-20T18:21:58","slug":"marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/","title":{"rendered":"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Escuela Municipal de Artes Esc\u00e9nicas \u201cJos\u00e9 Pepe Fanto\u201d, que depende de la Secretar\u00eda de Educaci\u00f3n y Cultura de la Municipalidad de Rafaela invita a participar de \u201c40 a\u00f1os no son nada\u201d, un ciclo de actividades para celebrar cuatro d\u00e9cadas de recorrido art\u00edstico del destacado director, dramaturgo y referente del teatro rafaelino Marcelo Allasino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con una programaci\u00f3n especial que se extender\u00e1 durante los meses de julio y agosto, se estar\u00e1n presentando diferentes producciones y artistas en un mismo ciclo por distintos espacios de la ciudad, para celebrar el teatro como pr\u00e1ctica art\u00edstica, pensamiento y construcci\u00f3n de comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La EMAE se suma a esta agenda, acompa\u00f1ando este aniversario con la organizaci\u00f3n de tres propuestas que se llevar\u00e1n a cabo en el Aula C de la escuela, con entrada libre y gratuita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En primer lugar, el d\u00eda mi\u00e9rcoles 29 de julio a las 20:00, invita a participar de una conversaci\u00f3n p\u00fablica denominada \u201cHacer teatro en Rafaela\u201d, donde Marcelo Allasino junto a artistas locales que participaron en diferentes proyectos en el transcurso de estos a\u00f1os, ofrecer\u00e1n una charla abierta a todo p\u00fablico sobre la experiencia de crear, gestionar y sostener una pr\u00e1ctica teatral independiente desde \u201cuna ciudad del interior del interior\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un recorrido por cuarenta a\u00f1os de trabajo compartido, atravesado por la formaci\u00f3n, la producci\u00f3n, la gesti\u00f3n cultural y la construcci\u00f3n de comunidad, para pensar el teatro como una forma de estar en el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, el d\u00eda mi\u00e9rcoles 5 de agosto a las 20:00, habr\u00e1 una lectura compartida abierta a todo p\u00fablico denominada \u201cTextos para una celebraci\u00f3n\u201d. Junto a actores y actrices invitados, se leer\u00e1n fragmentos de obras seleccionadas y de su autor\u00eda, materiales in\u00e9ditos y apuntes de trabajo que recorren distintas etapas de su proceso creativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un encuentro para compartir la escritura como territorio de exploraci\u00f3n, memoria y b\u00fasqueda, all\u00ed donde las ideas comienzan a transformarse en escena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, los d\u00edas lunes 3 y martes 4 de agosto de 13:30 a 16:00, se ofrecer\u00e1 un seminario intensivo denominado Desmontaje sobre \u201cMis palabras\u201d, s\u00f3lo para alumnos de la Diplomatura en Artes Esc\u00e9nicas de EMAE, docentes y egresados de dicha instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir del an\u00e1lisis del texto, la puesta en escena y el intercambio con el equipo art\u00edstico, el encuentro abordar\u00e1 algunos fragmentos de la obra como punto de partida para ejercicios t\u00e9cnicos y creativos, acercando a los participantes a las decisiones que dan forma a una producci\u00f3n teatral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe recordar que el proyecto de creaci\u00f3n de la Escuela Municipal de Artes Esc\u00e9nicas en el \u00e1mbito del Liceo Municipal \u201cMiguel Flores\u201d, anunciado en diciembre de 2013, fue impulsado por Allasino, en el marco de su gesti\u00f3n como Secretario de Cultura de la Municipalidad de Rafaela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde entonces, la Escuela Municipal de Artes Esc\u00e9nicas \u201cJos\u00e9 Pepe Fanto\u201d es el \u00fanico espacio p\u00fablico\/gubernamental qu\u00e9 ofrece de forma sistematizada, formaci\u00f3n integral en actuaci\u00f3n con proyecci\u00f3n profesional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La instituci\u00f3n acompa\u00f1a en este homenaje a quien trabaj\u00f3 para que Rafaela no solo fuera un centro de difusi\u00f3n del teatro, trabajando y promoviendo desde sus inicios el Festival de Teatro de Rafaela como principal gestor cultural y art\u00edstico del evento, sino tambi\u00e9n para que lo produzca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante julio y agosto, la Escuela Municipal de Artes Esc\u00e9nicas realizar\u00e1 conversaciones, lecturas y un seminario para compartir parte de su recorrido art\u00edstico de 40 a\u00f1os en la ciudad.<\/p>\n","protected":false},"author":1,"featured_media":39151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[9163],"class_list":["post-39150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-y-sociedad","tag-marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Durante julio y agosto, la Escuela Municipal de Artes Esc\u00e9nicas realizar\u00e1 conversaciones, lecturas y un seminario para compartir parte de su recorrido art\u00edstico de 40 a\u00f1os en la ciudad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-20T18:21:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T18:21:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-20-at-13.06.44.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1066\" \/>\n\t<meta property=\"og:image:height\" content=\"885\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\"},\"headline\":\"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE\",\"datePublished\":\"2026-07-20T18:21:56+00:00\",\"dateModified\":\"2026-07-20T18:21:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/\"},\"wordCount\":577,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-20-at-13.06.44.jpeg\",\"keywords\":[\"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE\"],\"articleSection\":[\"Cultura y Sociedad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/\",\"name\":\"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-20-at-13.06.44.jpeg\",\"datePublished\":\"2026-07-20T18:21:56+00:00\",\"dateModified\":\"2026-07-20T18:21:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-20-at-13.06.44.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-20-at-13.06.44.jpeg\",\"width\":1066,\"height\":885},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sabado100.com.ar\/es-ar\"],\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/","og_locale":"es_ES","og_type":"article","og_title":"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE - Sabado 100","og_description":"Durante julio y agosto, la Escuela Municipal de Artes Esc\u00e9nicas realizar\u00e1 conversaciones, lecturas y un seminario para compartir parte de su recorrido art\u00edstico de 40 a\u00f1os en la ciudad.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2026-07-20T18:21:56+00:00","article_modified_time":"2026-07-20T18:21:58+00:00","og_image":[{"width":1066,"height":885,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-20-at-13.06.44.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/"},"author":{"name":"admin","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5"},"headline":"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE","datePublished":"2026-07-20T18:21:56+00:00","dateModified":"2026-07-20T18:21:58+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/"},"wordCount":577,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-20-at-13.06.44.jpeg","keywords":["Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE"],"articleSection":["Cultura y Sociedad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/","url":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/","name":"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-20-at-13.06.44.jpeg","datePublished":"2026-07-20T18:21:56+00:00","dateModified":"2026-07-20T18:21:58+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-20-at-13.06.44.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-20-at-13.06.44.jpeg","width":1066,"height":885},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/marcelo-allasino-celebra-cuatro-decadas-de-teatro-en-la-emae\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Marcelo Allasino celebra cuatro d\u00e9cadas de teatro en la EMAE"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","caption":"admin"},"sameAs":["https:\/\/sabado100.com.ar\/es-ar"],"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=39150"}],"version-history":[{"count":1,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39150\/revisions"}],"predecessor-version":[{"id":39152,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39150\/revisions\/39152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/39151"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=39150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=39150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=39150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}