{"id":39006,"date":"2026-07-04T13:56:00","date_gmt":"2026-07-04T13:56:00","guid":{"rendered":"https:\/\/sabado100.com.ar\/es-ar\/?p=39006"},"modified":"2026-07-04T13:56:02","modified_gmt":"2026-07-04T13:56:02","slug":"argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/","title":{"rendered":"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>MIAMI (Por <a href=\"https:\/\/www.lanacion.com.ar\/autor\/leandro-contento\/\">Leandro Contento<\/a>).-<\/strong> Ning\u00fan mal es necesario y mucho menos en un Mundial.\u00a0<strong>Pero si este triunfo sufrido ante Cabo Verde sirve para algo, deber\u00eda ser para recordarle a Argentina que, a partir de ahora, ya no alcanza con la chapa<\/strong>. Despu\u00e9s de una actuaci\u00f3n preocupante frente a una de las selecciones m\u00e1s d\u00e9biles del torneo,\u00a0<strong>el campe\u00f3n del mundo avanz\u00f3 a los octavos de final<\/strong>. Gan\u00f3 m\u00e1s por jerarqu\u00eda que por juego y no puede permitirse otra actuaci\u00f3n as\u00ed si quiere sostener con argumentos la ilusi\u00f3n del bicampeonato. En su primer partido de eliminaci\u00f3n directa descubri\u00f3 una versi\u00f3n desconocida en este torneo: la de un equipo vulnerable, que por momentos perdi\u00f3 el control y dej\u00f3 de transmitir esa sensaci\u00f3n de que el triunfo jam\u00e1s corr\u00eda peligro.\u00a0<a href=\"https:\/\/www.lanacion.com.ar\/deportes\/futbol\/egipto-vencio-a-australia-y-es-el-proximo-rival-de-argentina-en-el-mundial-en-los-octavos-de-final-nid03072026\/\">En octavos espera Egipto.<\/a>\u00a0Despu\u00e9s de lo visto en Miami, ning\u00fan rival parece tan accesible como antes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acaso solo<strong>\u00a0Lionel Scaloni<\/strong>\u00a0imaginaba un partido tan peleado. En la previa hab\u00eda elogiado mucho a Cabo Verde, aunque entonces sus palabras sonaban m\u00e1s a respeto protocolar que a una preocupaci\u00f3n real. Argentina jug\u00f3 incluso por debajo del nivel que hab\u00eda mostrado en la etapa de grupos, donde ya hab\u00eda quedado en deuda. Busc\u00f3 que el triunfo fuera consecuencia del dominio y no de un golpe por golpe frente a un rival armado para defender y contragolpear. Equipos con ese talento pueden darse ese lujo: dejar correr los minutos hasta encontrar el espacio, sabiendo que la oportunidad iba a llegar.\u00a0<strong>Pero esa paciencia por momentos se transform\u00f3 en parsimonia.<\/strong>\u00a0Instalado en campo rival, frente a un laborioso Cabo Verde que defend\u00eda con las l\u00edneas muy juntas, aunque desde un bloque medio y no tan cerca de su arco, el equipo de Scaloni mov\u00eda la pelota de un lado a otro, pero\u00a0<strong>le faltaban ingenio, velocidad y precisi\u00f3n para romper ese cerrojo.<\/strong>\u00a0Conduc\u00edan Lisandro Mart\u00ednez y Cristian Romero, pero el resto aparec\u00eda tapado, incluido Messi,\u00a0<strong>siempre rodeado por dos marcas<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Demor\u00f3 casi medio tiempo en activar el plan alternativo: saltear l\u00edneas para encontrar a los laterales en profundidad o pinchar la pelota al \u00e1rea para los delanteros, aprovechando que la \u00faltima l\u00ednea de de Cabo Verde ofrec\u00eda muchas menos garant\u00edas cuando retroced\u00eda que cuando defend\u00eda de frente.&nbsp;<strong>As\u00ed lleg\u00f3 el gol: un bochazo de Lisandro desde mitad de cancha para que Messi ganara la espalda de Disney Borges,<\/strong>&nbsp;amortiguara la pelota con el rev\u00e9s del bot\u00edn izquierdo y definiera por encima de Vozinha. La misma f\u00f3rmula que dej\u00f3 a Argentina afuera del Mundial de 1998, pero invertida: de Bergkamp a Messi, para que esta vez la selecci\u00f3n avanzara de ronda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El s\u00e9ptimo gol de Messi en el Mundial no bast\u00f3 para terminar de desenredar la mara\u00f1a<\/strong>. Argentina volvi\u00f3 a caer por momentos en un ritmo demasiado pausado, sin esa marcha m\u00e1s, ese v\u00e9rtigo que hab\u00eda sido una de sus marcas en Qatar y durante buena parte de las eliminatorias.&nbsp;<strong>Con Alexis Mac Allister como volante central, el mediocampo perdi\u00f3 dinamismo.<\/strong>&nbsp;El futbolista de Liverpool jug\u00f3 m\u00e1s pendiente del orden que de darle ritmo al equipo, y Argentina sinti\u00f3 esa falta de velocidad en una zona clave de la cancha, donde necesitaba mover la pelota con mayor rapidez para desarticular a un rival intenso para recuperar y \u00e1gil para salir de contraataque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el segundo tiempo, Cabo Verde adelant\u00f3 unos metros sus l\u00edneas y Argentina pas\u00f3 a construir desde m\u00e1s atr\u00e1s, pero el equipo africano tambi\u00e9n mostr\u00f3 otras intenciones en ataque.&nbsp;<strong>Ya no se conform\u00f3 con tapar l\u00edneas de pase y mantener el juego lejos de Vozinha<\/strong>. Empez\u00f3 a acelerar, aprovechando una selecci\u00f3n lenta y por momentos desconectada, que dej\u00f3 flotando una sensaci\u00f3n poco habitual: que el triunfo no estaba asegurado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y no lo estaba.&nbsp;<strong>Deroy Duarte<\/strong>&nbsp;primero exigi\u00f3 a Emiliano Mart\u00ednez con un remate de media distancia y, unos minutos despu\u00e9s,&nbsp;<strong>apareci\u00f3 solo en el \u00e1rea para definir cruzado y marcar el empate.&nbsp;<\/strong>Una desinteligencia fatal: Enzo Fern\u00e1ndez no sigui\u00f3 su carrera para cubrir un posible centro atr\u00e1s y Lisandro Mart\u00ednez tard\u00f3 en salir a achicar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Scaloni busc\u00f3 cambiar desde el banco, aunque sin modificar el esquema ni la idea.&nbsp;<strong>Argentina segu\u00eda dependiendo casi exclusivamente de Messi:<\/strong>&nbsp;el juego pasaba por sus pies y tambi\u00e9n las infracciones cerca del \u00e1rea que \u00e9l mismo provocaba para probar de tiro libre. Tuvo la chance m\u00e1s clara, entrando al \u00e1rea con la pelota dominada, pero perdi\u00f3 el mano a mano con Vozinha, el arquero de 40 a\u00f1os que termin\u00f3 imponi\u00e9ndose en el duelo personal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El final fue tomando ribetes dram\u00e1ticos.&nbsp;<\/strong>Argentina insist\u00eda sin claridad y las veces que lograba llegar con cierta claridad aparec\u00eda siempre una pierna rival. A eso se sum\u00f3 la lesi\u00f3n de Medina, uno de los que m\u00e1s empujaba, y oblig\u00f3 a Scaloni a invertir un cambio que pensaba seguramente para otra funci\u00f3n. Y el posible penal por mano de Roberto Lopes a falta de dos minutos. Y el tiro libre de Messi que muri\u00f3 otra vez en los guantes del arquero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El suplementario tuvo algo de la final de Lusail, incluso en el color de las camisetas.<\/strong>&nbsp;Un partido&nbsp;<em>roto<\/em>, sin medio campo, con dos equipos de recetas distintas pero dispuestos a no renunciar a la victoria. Lleg\u00f3 el gol de&nbsp;<strong>Lisandro Mart\u00ednez<\/strong>, tras un tiro de esquina de Messi, pero&nbsp;<strong>Sidny Lopes Cabral,<\/strong>&nbsp;el lateral que es compa\u00f1ero de Nicol\u00e1s Otamendi en Benfica, la colg\u00f3 de un \u00e1ngulo y le dio a Argentina otro golpe. Y tambi\u00e9n otra se\u00f1al de alerta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La selecci\u00f3n lleg\u00f3 al final echando el resto, con Messi notablemente cansado,<strong>&nbsp;Leandro Paredes<\/strong>&nbsp;intentando serenar el juego y Cabo Verde fortalecido an\u00edmicamente, convencido de que el batacazo todav\u00eda era posible. Y ah\u00ed, cuando ya nadie encontraba respuestas y el estadio miraba en silencio un desenlace impredecible,<strong>&nbsp;apareci\u00f3 otro c\u00f3rner de Messi para que Cuti Romero cabeceara a la red.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este Mundial no da tiempo ni margen para el festejo. El martes, Argentina volver\u00e1 a jugar, ahora en Atlanta y frente a otro rival africano, en busca de los cuartos de final. El desahogo del final fue un premio al esfuerzo, a la perseverancia y a creer hasta el \u00faltimo minuto, aunque tambi\u00e9n dej\u00f3 una ense\u00f1anza:&nbsp;<strong>si vuelve a jugar as\u00ed, el pr\u00f3ximo aviso puede ser el \u00faltimo.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong> <a href=\"https:\/\/www.lanacion.com.ar\/\">https:\/\/www.lanacion.com.ar\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El equipo de Scaloni gan\u00f3 m\u00e1s por jerarqu\u00eda que por juego y no puede permitirse otra actuaci\u00f3n as\u00ed si quiere sostener con argumentos la ilusi\u00f3n del bicampeonato.<\/p>\n","protected":false},"author":1,"featured_media":39007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[219],"tags":[9122],"class_list":["post-39006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"El equipo de Scaloni gan\u00f3 m\u00e1s por jerarqu\u00eda que por juego y no puede permitirse otra actuaci\u00f3n as\u00ed si quiere sostener con argumentos la ilusi\u00f3n del bicampeonato.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-04T13:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-04T13:56:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-04-at-10.51.19.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\"},\"headline\":\"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n\",\"datePublished\":\"2026-07-04T13:56:00+00:00\",\"dateModified\":\"2026-07-04T13:56:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/\"},\"wordCount\":1159,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-04-at-10.51.19.jpeg\",\"keywords\":[\"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/\",\"name\":\"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-04-at-10.51.19.jpeg\",\"datePublished\":\"2026-07-04T13:56:00+00:00\",\"dateModified\":\"2026-07-04T13:56:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-04-at-10.51.19.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-04-at-10.51.19.jpeg\",\"width\":780,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1788331523\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1788331523\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sabado100.com.ar\/es-ar\"],\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/","og_locale":"es_ES","og_type":"article","og_title":"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n - Sabado 100","og_description":"El equipo de Scaloni gan\u00f3 m\u00e1s por jerarqu\u00eda que por juego y no puede permitirse otra actuaci\u00f3n as\u00ed si quiere sostener con argumentos la ilusi\u00f3n del bicampeonato.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2026-07-04T13:56:00+00:00","article_modified_time":"2026-07-04T13:56:02+00:00","og_image":[{"width":780,"height":520,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-04-at-10.51.19.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/"},"author":{"name":"admin","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5"},"headline":"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n","datePublished":"2026-07-04T13:56:00+00:00","dateModified":"2026-07-04T13:56:02+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/"},"wordCount":1159,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-04-at-10.51.19.jpeg","keywords":["Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/","url":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/","name":"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-04-at-10.51.19.jpeg","datePublished":"2026-07-04T13:56:00+00:00","dateModified":"2026-07-04T13:56:02+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-04-at-10.51.19.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-04-at-10.51.19.jpeg","width":780,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/argentina-sufrio-para-ganarle-a-cabo-verde-y-ya-no-alcanza-con-la-chapa-de-campeon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Argentina sufri\u00f3 para ganarle a Cabo Verde y ya no alcanza con la chapa de campe\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1788331523","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1788331523","caption":"admin"},"sameAs":["https:\/\/sabado100.com.ar\/es-ar"],"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=39006"}],"version-history":[{"count":1,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39006\/revisions"}],"predecessor-version":[{"id":39008,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/39006\/revisions\/39008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/39007"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=39006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=39006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=39006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}