{"id":38603,"date":"2026-05-31T23:33:08","date_gmt":"2026-05-31T23:33:08","guid":{"rendered":"https:\/\/sabado100.com.ar\/es-ar\/?p=38603"},"modified":"2026-05-31T23:33:09","modified_gmt":"2026-05-31T23:33:09","slug":"morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/","title":{"rendered":"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La concejal Mar\u00eda Paz Caruso present\u00f3 una iniciativa dirigida al Departamento Ejecutivo para que se incorpore, en el formulario de preguntas del Relevamiento Socioecon\u00f3mico 2026, una consulta referida espec\u00edficamente al nivel de endeudamiento de las familias de la ciudad. Asimismo, solicit\u00f3 relevar las estrategias que los hogares est\u00e1n desplegando para enfrentar esta situaci\u00f3n en los casos donde las deudas ya influyen directamente en la din\u00e1mica de sus ingresos y gastos mensuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abConsiderando que en Rafaela llevamos a cabo anualmente el Relevamiento Socioecon\u00f3mico, el cual recopila informaci\u00f3n valios\u00edsima sobre vivienda, aspectos sociales, ocupaci\u00f3n, desocupaci\u00f3n, salud y educaci\u00f3n, entendemos que esta es la herramienta id\u00f3nea y el momento fundamental para conocer con precisi\u00f3n lo que est\u00e1 sucediendo puertas adentro de los hogares rafaelinos respecto a la morosidad\u00bb, explic\u00f3 la concejal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, la edil manifest\u00f3 preocupaci\u00f3n por una problem\u00e1tica que ya se visualiza con fuerza en los medios nacionales, donde se advierte un crecimiento exponencial durante los \u00faltimos meses, un fen\u00f3meno que est\u00e1 obligando a las familias a cambiar sus h\u00e1bitos de consumo y de subsistencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Legislar sobre datos reales, no sobre supuestos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La incorporaci\u00f3n de esta variable es clave ante el escenario de fuerte presi\u00f3n fiscal e inflaci\u00f3n que golpea a la comunidad. \u00abNo podemos legislar a ciegas. Dicha informaci\u00f3n ser\u00e1 un insumo vital y sumamente necesario a la hora de tomar iniciativas legislativas de protecci\u00f3n econ\u00f3mica, tanto para el dise\u00f1o de pol\u00edticas p\u00fablicas por parte del Poder Ejecutivo como para nuestra tarea en el Concejo Municipal\u00bb, enfatiz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La propuesta busca encender una alarma sobre el impacto que la crisis y el encarecimiento de los servicios y tributos locales est\u00e1n teniendo en la econom\u00eda dom\u00e9stica. \u00abDetr\u00e1s de las fr\u00edas estad\u00edsticas de recaudaci\u00f3n hay familias que est\u00e1n eligiendo qu\u00e9 pagar y qu\u00e9 dejar de pagar para llegar a fin de mes. Conocer el mapa real del endeudamiento en Rafaela nos va a permitir generar herramientas legislativas justas, oportunas y con los pies sobre la tierra\u00bb, concluy\u00f3 Caruso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caruso ingres\u00f3 un pedido para incorporar consultas espec\u00edficas sobre la situaci\u00f3n financiera de los hogares locales en el Relevamiento Socioeconomico anual que realiza el ICEDEL. \u201cEs fundamental conocer lo que est\u00e1 sucediendo a nivel local con las deudas familiares para poder legislar con datos certeros y defender el bolsillo de los vecinos\u201d, fundament\u00f3.<\/p>\n","protected":false},"author":1,"featured_media":38604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[23],"tags":[9018],"class_list":["post-38603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Caruso ingres\u00f3 un pedido para incorporar consultas espec\u00edficas sobre la situaci\u00f3n financiera de los hogares locales en el Relevamiento Socioeconomico anual que realiza el ICEDEL. \u201cEs fundamental conocer lo que est\u00e1 sucediendo a nivel local con las deudas familiares para poder legislar con datos certeros y defender el bolsillo de los vecinos\u201d, fundament\u00f3.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-31T23:33:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-31T23:33:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-14.00.50.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\"},\"headline\":\"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela\",\"datePublished\":\"2026-05-31T23:33:08+00:00\",\"dateModified\":\"2026-05-31T23:33:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/\"},\"wordCount\":370,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-14.00.50.jpeg\",\"keywords\":[\"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela\"],\"articleSection\":[\"Econom\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/\",\"name\":\"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-14.00.50.jpeg\",\"datePublished\":\"2026-05-31T23:33:08+00:00\",\"dateModified\":\"2026-05-31T23:33:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-14.00.50.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-14.00.50.jpeg\",\"width\":1200,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sabado100.com.ar\/es-ar\"],\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/","og_locale":"es_ES","og_type":"article","og_title":"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela - Sabado 100","og_description":"Caruso ingres\u00f3 un pedido para incorporar consultas espec\u00edficas sobre la situaci\u00f3n financiera de los hogares locales en el Relevamiento Socioeconomico anual que realiza el ICEDEL. \u201cEs fundamental conocer lo que est\u00e1 sucediendo a nivel local con las deudas familiares para poder legislar con datos certeros y defender el bolsillo de los vecinos\u201d, fundament\u00f3.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2026-05-31T23:33:08+00:00","article_modified_time":"2026-05-31T23:33:09+00:00","og_image":[{"width":1200,"height":960,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-14.00.50.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/"},"author":{"name":"admin","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5"},"headline":"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela","datePublished":"2026-05-31T23:33:08+00:00","dateModified":"2026-05-31T23:33:09+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/"},"wordCount":370,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-14.00.50.jpeg","keywords":["Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela"],"articleSection":["Econom\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/","url":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/","name":"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-14.00.50.jpeg","datePublished":"2026-05-31T23:33:08+00:00","dateModified":"2026-05-31T23:33:09+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-14.00.50.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-31-at-14.00.50.jpeg","width":1200,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/morosidad-solicitan-que-se-mida-lo-que-esta-pasando-en-rafaela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Morosidad: solicitan que se mida lo que est\u00e1 pasando en Rafaela"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","caption":"admin"},"sameAs":["https:\/\/sabado100.com.ar\/es-ar"],"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/38603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=38603"}],"version-history":[{"count":1,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/38603\/revisions"}],"predecessor-version":[{"id":38605,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/38603\/revisions\/38605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/38604"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=38603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=38603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=38603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}