{"id":38305,"date":"2026-05-13T20:47:27","date_gmt":"2026-05-13T20:47:27","guid":{"rendered":"https:\/\/sabado100.com.ar\/es-ar\/?p=38305"},"modified":"2026-05-13T20:47:28","modified_gmt":"2026-05-13T20:47:28","slug":"presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/","title":{"rendered":"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el marco de una conferencia de prensa realizada en la Biblioteca Lermo Rafael Balbi, ubicada en el Complejo Cultural del Viejo Mercado, el Gobierno Municipal de Rafaela present\u00f3 el llamado a concurso para el dise\u00f1o de la bandera oficial de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la actividad estuvieron presentes la secretaria de Educaci\u00f3n y Cultura, Norma Becchio; y el secretario de Gobierno y Modernizaci\u00f3n, Germ\u00e1n Bottero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la mencionada conferencia, Becchio mencion\u00f3: \u00abDesde el Municipio hemos lanzado una convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o oficial de la bandera de Rafaela. Un dise\u00f1o que va a identificar a la ciudad en distintos eventos\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La funcionaria expres\u00f3 que \u00abeste a\u00f1o, Rafaela cumple 145 a\u00f1os y, en el marco de los festejos, vamos a tener visitas de las comunidades hermanadas. Tambi\u00e9n, para el desarrollo de los Juegos Suramericanos queremos tener una bandera que nos identifique. Es por eso que hemos lanzado la convocatoria que tuvo el proceso administrativo que requieren todos los decretos. Esto es pasar por distintas secretar\u00edas, Fiscal\u00eda, hasta llegar al decreto oficial\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a los detalles del concurso, la funcionaria mencion\u00f3 que \u00abhay dos formas de participar: una es de manera individual, en donde pueden hacerlo personas mayores de 18 a\u00f1os que sean rafaelinos o residan en Rafaela. La otra es para menores de 18 a\u00f1os. En este caso, lo van a tener que hacer a trav\u00e9s de una instituci\u00f3n educativa y cada escuela podr\u00e1 presentar un dise\u00f1o\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl dise\u00f1o debe ser sencillo, con colores que identifiquen a la ciudad, en el que se vean reflejadas la historia y cultural rafaelinas. Puede utilizarse el escudo, pero respetando su formato ya que es el \u00fanico s\u00edmbolo oficial con el que contamos\u00bb, manifest\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Becchio indic\u00f3 que \u00abcuando se cierre la convocatoria, cada dise\u00f1o ser\u00e1 evaluado por un jurado conformado por personas representantes de distintos estamentos: Concejo Municipal, Centro Comercial e Industrial de Rafaela y la Regi\u00f3n, Consejo Universitario de Rafaela, Asociaci\u00f3n del Magisterio de Santa Fe, Secretar\u00eda de Educaci\u00f3n y Cultura, Federaci\u00f3n de Entidades Vecinales, un historiador y un dise\u00f1ador gr\u00e1fico\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abUna vez seleccionado el dise\u00f1o de la bandera, lo llevaremos al Concejo para su aprobaci\u00f3n y posteriormente al Intendente para que, mediante decreto, la nombre como bandera oficial de Rafaela\u00bb, se\u00f1al\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-sabado-100 wp-block-embed-sabado-100\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"o1n07USxHJ\"><a href=\"https:\/\/sabado100.com.ar\/es-ar\/proponen-una-bandera-para-rafaela-pero-fue-sancionada-por-el-concejo-en-2015\/\">Proponen una bandera para Rafaela, pero fue sancionada por el Concejo en 2015<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abProponen una bandera para Rafaela, pero fue sancionada por el Concejo en 2015\u00bb \u2014 Sabado 100\" src=\"https:\/\/sabado100.com.ar\/es-ar\/proponen-una-bandera-para-rafaela-pero-fue-sancionada-por-el-concejo-en-2015\/embed\/#?secret=L5VSe44Uic#?secret=o1n07USxHJ\" data-secret=\"o1n07USxHJ\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Germ\u00e1n Bottero puntualiz\u00f3: \u00abLa ordenanza del 2015 es clara y faculta al Departamento Ejecutivo Municipal para que, a trav\u00e9s del \u00e1rea correspondiente, organice la forma en la cual se determine el dise\u00f1o de la bandera de la ciudad. La anterior gesti\u00f3n nunca avanz\u00f3 en este tema y nosotros lo estamos haciendo. Entendemos que la participaci\u00f3n abierta a todos los rafaelinos es la forma\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre el concurso<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es v\u00e1lido indicar que la ordenanza 4726 faculta al Departamento Ejecutivo Municipal a efectuar la convocatoria para llevar adelante el proceso de creaci\u00f3n de la bandera que identificar\u00e1 a nuestra ciudad. Con base en la mencionada ordenanza, el intendente Leonardo Viotti refrend\u00f3, entonces, el decreto 645 para tal fin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho de que Rafaela cuente con bandera propia permitir\u00e1 que la ciudad est\u00e9 presente con su s\u00edmbolo en actos, as\u00ed como tambi\u00e9n acompa\u00f1ando a delegaciones representantes de entidades intermedias de car\u00e1cter educativo, deportivo, cultural o social tanto dentro como fuera de sus l\u00edmites.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En definitiva, el objetivo del concurso es dotar a la ciudad de un de un s\u00edmbolo identitario que represente su historia, valores, cultura, desarrollo y proyecci\u00f3n futura, promoviendo la participaci\u00f3n ciudadana en la construcci\u00f3n de los emblemas oficiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dise\u00f1o ganador ser\u00e1 elevado al Concejo Municipal para su tratamiento y eventual declaraci\u00f3n como bandera oficial de la ciudad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el concurso podr\u00e1n participar personas mayores de 18 a\u00f1os, nacidas o residentes en la ciudad de Rafaela, en forma individual e instituciones educativas p\u00fablicas o privadas de la ciudad de Rafaela de todos los niveles. En este caso, el dise\u00f1o deber\u00e1 surgir de un proceso colaborativo interno; no se admitir\u00e1n presentaciones individuales de alumnos; la propuesta tendr\u00e1 car\u00e1cter institucional; deber\u00e1 contar con validaci\u00f3n formal de la autoridad del establecimiento; los menores de edad \u00fanicamente podr\u00e1n participar en el marco de una propuesta institucional y no de manera individual; y podr\u00e1 presentarse un proyecto por persona o instituci\u00f3n educativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale aclarar que la participaci\u00f3n es gratuita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con respecto al plazo de inscripci\u00f3n, el mismo se extiende hasta el 3 de agosto en el siguiente enlace: <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScVWi75toAp11ZUfUAnAzX1yil6n-lXOj5nMcSn6UjCKiYpLA\/viewform\">https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLScVWi75toAp11ZUfUAnAzX1yil6n-lXOj5nMcSn6UjCKiYpLA\/viewform<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concurso est\u00e1 abierto hasta el 3 de agosto y pueden participar personas mayores de 18 a\u00f1os (rafaelinos o residentes en la ciudad) y menores de 18 a\u00f1os, a trav\u00e9s de sus entidades. <\/p>\n","protected":false},"author":1,"featured_media":38306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[8928],"class_list":["post-38305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-y-sociedad","tag-presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"El concurso est\u00e1 abierto hasta el 3 de agosto y pueden participar personas mayores de 18 a\u00f1os (rafaelinos o residentes en la ciudad) y menores de 18 a\u00f1os, a trav\u00e9s de sus entidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T20:47:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T20:47:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-17.13.37.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\"},\"headline\":\"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela\",\"datePublished\":\"2026-05-13T20:47:27+00:00\",\"dateModified\":\"2026-05-13T20:47:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/\"},\"wordCount\":805,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-17.13.37.jpeg\",\"keywords\":[\"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela\"],\"articleSection\":[\"Cultura y Sociedad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/\",\"name\":\"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-17.13.37.jpeg\",\"datePublished\":\"2026-05-13T20:47:27+00:00\",\"dateModified\":\"2026-05-13T20:47:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-17.13.37.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-17.13.37.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sabado100.com.ar\/es-ar\"],\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/","og_locale":"es_ES","og_type":"article","og_title":"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela - Sabado 100","og_description":"El concurso est\u00e1 abierto hasta el 3 de agosto y pueden participar personas mayores de 18 a\u00f1os (rafaelinos o residentes en la ciudad) y menores de 18 a\u00f1os, a trav\u00e9s de sus entidades.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2026-05-13T20:47:27+00:00","article_modified_time":"2026-05-13T20:47:28+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-17.13.37.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/"},"author":{"name":"admin","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5"},"headline":"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela","datePublished":"2026-05-13T20:47:27+00:00","dateModified":"2026-05-13T20:47:28+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/"},"wordCount":805,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-17.13.37.jpeg","keywords":["Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela"],"articleSection":["Cultura y Sociedad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/","url":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/","name":"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-17.13.37.jpeg","datePublished":"2026-05-13T20:47:27+00:00","dateModified":"2026-05-13T20:47:28+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-17.13.37.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-13-at-17.13.37.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/presentaron-la-convocatoria-de-participacion-ciudadana-para-el-diseno-de-la-bandera-oficial-de-rafaela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Presentaron la convocatoria de participaci\u00f3n ciudadana para el dise\u00f1o de la bandera oficial de Rafaela"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","caption":"admin"},"sameAs":["https:\/\/sabado100.com.ar\/es-ar"],"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/38305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=38305"}],"version-history":[{"count":1,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/38305\/revisions"}],"predecessor-version":[{"id":38307,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/38305\/revisions\/38307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/38306"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=38305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=38305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=38305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}