{"id":3258,"date":"2013-04-01T14:27:36","date_gmt":"2013-04-01T12:27:36","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=3258"},"modified":"2013-04-01T14:27:36","modified_gmt":"2013-04-01T12:27:36","slug":"con-la-salud-no-se-juega-se-invierte","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/","title":{"rendered":"Con la salud no se juega, se invierte"},"content":{"rendered":"<p>Coincidiendo con el aniversario de la creaci\u00f3n de la Organizaci\u00f3n Mundial de la Salud en 1948, el siete de abril, y considerando que la felicidad radica ante todo en la salud,  se me ocurre sembrar una serie de advertencias, sin obviar el entusiasmo de la alegr\u00eda como ingrediente principal en el compuesto de la energ\u00eda.<\/p>\n<p> \tEn los \u00faltimos tiempos, tambi\u00e9n hemos retrocedido en la cobertura sanitaria universal. Las pol\u00edticas sanitarias en el mundo dejan sin una asistencia sanitaria de calidad a buena parte de la ciudadan\u00eda, siempre los m\u00e1s pobres y los m\u00e1s vulnerables. No hay dinero para prevenir las enfermedades, tampoco para promover estilos de vida m\u00e1s saludables, y mucho menos para proteger a las personas de las amenazas para la salud como las pandemias; en cambio, si hay dinero para armamento, para derroches, para que el rico siga acrecentando su riqueza. La imposici\u00f3n de tasas a los usuarios de los servicios sanitarios, lo que hace es impedir que las personas con bajos ingresos econ\u00f3micos puedan acudir. Una regresi\u00f3n totalmente injusta e inhumana que debe hacernos recapacitar. Tanto es as\u00ed, que la asistencia sanitaria hoy ya es un privilegio para algunos, en este mundo crecido por la injusticia y la falta de \u00e9tica.<\/p>\n<p>\tSin duda, la asistencia sanitaria es un poderoso factor de desigualdad y expresi\u00f3n \u00faltima de crueldad. Cada pa\u00eds, por tanto, debe labrar su propio camino de prioridades. La salud p\u00fablica debiera ser una preocupaci\u00f3n fundamental para todas las autoridades. Normalmente la gente prefiere recibir asistencia sanitaria lo m\u00e1s cerca posible del lugar en el que reside, por lo que no es de recibo cerrar centros de salud, puesto que es un derecho humano. Sin embargo, se permite el gasto irracional en proyectos fara\u00f3nicos de dif\u00edcil utilizaci\u00f3n. Lo primero son las personas. Por tanto, a mi juicio, debe de hacerse m\u00e1s hincapi\u00e9 en la necesidad de prestar una salud integral e integradora, donde nadie quede excluido de la prestaci\u00f3n sanitaria. Evidentemente, ha de prestarse mayor atenci\u00f3n a los pa\u00edses que atraviesan por dificultades, que soportan una carga desproporcionada de enfermedades y mortalidad. No podemos, pues, aceptar sistemas sanitarios que no ofrecen el acceso a todo el mundo, ya sean ricos o pobres.<\/p>\n<p>\tMientras el mundo se enfrenta a los desaf\u00edos conjuntos de la desaceleraci\u00f3n econ\u00f3mica, la creciente globalizaci\u00f3n conllevar\u00e1 un aumento de enfermedades, y, por consiguiente, las demandas de la atenci\u00f3n a los enfermos ser\u00e1n cada vez mayores. A mi juicio, los gobiernos deber\u00e1n trabajar por encontrar los recursos precisos para la financiaci\u00f3n sanitaria para hacerla extensible y, al mismo tiempo, se deber\u00e1n establecer medidas de control para utilizar los recursos de una manera \u00f3ptima. Invertir en salud es tan preciso como necesario. Es el mejor avance. La vida y la salud tienen que ser nuestros bienes m\u00e1s preciados. En esto no podemos, ni debemos, entrar en crisis. El mundo, para ello, deber\u00eda lanzar la idea de asegurar a todos los moradores del planeta, una respuesta urgente y coordinada para reducir al m\u00ednimo cualquier amenaza en materia de salud.<\/p>\n<p>\tEstoy convencido de que todos los pa\u00edses pueden hacer m\u00e1s por mejorar la situaci\u00f3n sanitaria de su pueblo. Los servicios de salud han de ser accesibles y asequibles a toda la humanidad. Es cierto que las necesidades sanitarias de todas las poblaciones crecen sin cesar y se ha de hacer frente al aumento de los costos de dichos servicios, pero la soluci\u00f3n no pasa por introducir una tasa por dicho servicio, sino por lograr una cobertura sanitaria universal sostenible. Al fin y al cabo, de lo que se trata, es de recaudar m\u00e1s fondos para la salud. Y esto, hay que llevarlo a cabo de modo equitativo y el gasto de manera eficaz. El simple hecho de gastar de manera m\u00e1s inteligente, no tengo ninguna duda que ya incrementar\u00eda, en positivo, la cobertura sanitaria mundial. Ciertamente, no se puede cambiar la salud por el negocio, ni la transparencia por el poder. Lo fundamental es la realizaci\u00f3n de investigaciones sanitarias y la aplicaci\u00f3n de sus resultados para ayudar a fomentar comportamientos saludables.<\/p>\n<p>\tDesde esos comportamientos sanos, debe partir nuestra solidaridad. Por consiguiente, el esfuerzo por asistir se ha de extender a todo ser humano, puesto que esa atenci\u00f3n sanitaria va desde el cuidado del enfermo hasta los tratamientos preventivos, buscando el mayor desarrollo de la persona y favoreciendo un ambiente curativo. En el fondo, todos tenemos el fuerte compromiso de tutela y de cuidado, es un deber de adhesi\u00f3n que no excluye a nadie, ni siquiera a los que por su propia culpa han perdido la salud.  Precisamente este a\u00f1o, para el d\u00eda mundial, se ha elegido el tema de la hipertensi\u00f3n, algo que nosotros mismos podemos reducir, siguiendo una dieta equilibrada, evitando el uso nocivo del alcohol, haciendo ejercicio con regularidad, manteniendo un peso saludable, evitando el consumo de tabaco. O sea, activando el cuerpo de manera sana y que la mente repose.<\/p>\n<p>\tEn definitiva, que todos estamos obligados a crear entornos que favorezcan comportamientos saludables, mediante unas pol\u00edticas p\u00fablicas m\u00e1s acordes con los nuevos tiempos. De no corregir estos desajustes en la asistencia sanitaria, continuar\u00e1n las  regresiones en materia de salud, y muchas poblaciones desfavorecidas perder\u00e1n el tren de la vida. Sin duda, el cambio clim\u00e1tica y la inseguridad alimentaria, las fuertes tasas de desempleo, van a tener grandes repercusiones en la salud en los a\u00f1os venideros, de manera que una respuesta a tiempo  ser\u00e1 la mejor manera de afrontar el futuro. Es buena la unidad de acci\u00f3n y los llamamientos en pro de la atenci\u00f3n integral universal, pero ha llegado el momento de las actuaciones concretas. Y a\u00fan mejor es el entusiasmo por la cobertura universal en un mundo en el que las desigualdades sociales y de ingresos se han disparado. Ahora bien, este acceso a la asistencia sanitaria y a los medicamentos esenciales resultar\u00e1n m\u00e1s beneficiosos si se distribuyen apropiadamente y son utilizados correctamente por los pacientes. Ya saben, a veces conviene cerrar un ojo, pero no es prudente cerrar ambos a la vez, puesto que con la salud no se juega.<\/p>\n<p>V\u00edctor Corcoba Herrero\/ Escritor espa\u00f1ol<br \/>\ncorcoba@telefonica.net<br \/>\n31 de marzo de 2013.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este acceso a la asistencia sanitaria y a los medicamentos esenciales resultar\u00e1n m\u00e1s beneficiosos si se distribuyen apropiadamente y son utilizados correctamente por los pacientes. Ya saben, a veces conviene cerrar un ojo, pero no es prudente cerrar ambos a la vez, puesto que con la salud no se juega.<\/p>\n<p>Por V\u00edctor Corcoba Herrero (Granada)<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4,26],"tags":[],"class_list":["post-3258","post","type-post","status-publish","format-standard","hentry","category-cultura-y-sociedad","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Con la salud no se juega, se invierte - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con la salud no se juega, se invierte - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Este acceso a la asistencia sanitaria y a los medicamentos esenciales resultar\u00e1n m\u00e1s beneficiosos si se distribuyen apropiadamente y son utilizados correctamente por los pacientes. Ya saben, a veces conviene cerrar un ojo, pero no es prudente cerrar ambos a la vez, puesto que con la salud no se juega. Por V\u00edctor Corcoba Herrero (Granada)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-01T12:27:36+00:00\" \/>\n<meta name=\"author\" content=\"sabado100\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado100\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/\"},\"author\":{\"name\":\"sabado100\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/1a82439a05a3356129d4d51dd7ca16b4\"},\"headline\":\"Con la salud no se juega, se invierte\",\"datePublished\":\"2013-04-01T12:27:36+00:00\",\"dateModified\":\"2013-04-01T12:27:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/\"},\"wordCount\":1090,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"articleSection\":[\"Cultura y Sociedad\",\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/\",\"name\":\"Con la salud no se juega, se invierte - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"datePublished\":\"2013-04-01T12:27:36+00:00\",\"dateModified\":\"2013-04-01T12:27:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con la salud no se juega, se invierte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/1a82439a05a3356129d4d51dd7ca16b4\",\"name\":\"sabado100\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4048f7037fffe4fd73611d5730c1cb40.jpg?ver=1787740882\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4048f7037fffe4fd73611d5730c1cb40.jpg?ver=1787740882\",\"caption\":\"sabado100\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado1002\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con la salud no se juega, se invierte - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/","og_locale":"es_ES","og_type":"article","og_title":"Con la salud no se juega, se invierte - Sabado 100","og_description":"Este acceso a la asistencia sanitaria y a los medicamentos esenciales resultar\u00e1n m\u00e1s beneficiosos si se distribuyen apropiadamente y son utilizados correctamente por los pacientes. Ya saben, a veces conviene cerrar un ojo, pero no es prudente cerrar ambos a la vez, puesto que con la salud no se juega. Por V\u00edctor Corcoba Herrero (Granada)","og_url":"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2013-04-01T12:27:36+00:00","author":"sabado100","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado100","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/"},"author":{"name":"sabado100","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/1a82439a05a3356129d4d51dd7ca16b4"},"headline":"Con la salud no se juega, se invierte","datePublished":"2013-04-01T12:27:36+00:00","dateModified":"2013-04-01T12:27:36+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/"},"wordCount":1090,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"articleSection":["Cultura y Sociedad","General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/","url":"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/","name":"Con la salud no se juega, se invierte - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"datePublished":"2013-04-01T12:27:36+00:00","dateModified":"2013-04-01T12:27:36+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/con-la-salud-no-se-juega-se-invierte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Con la salud no se juega, se invierte"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/1a82439a05a3356129d4d51dd7ca16b4","name":"sabado100","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4048f7037fffe4fd73611d5730c1cb40.jpg?ver=1787740882","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4048f7037fffe4fd73611d5730c1cb40.jpg?ver=1787740882","caption":"sabado100"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado1002\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/3258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=3258"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/3258\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=3258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=3258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=3258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}