{"id":27068,"date":"2024-04-29T16:52:01","date_gmt":"2024-04-29T19:52:01","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=26828"},"modified":"2024-04-29T16:52:01","modified_gmt":"2024-04-29T19:52:01","slug":"solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/","title":{"rendered":"Solicitan que funcione la planta de procesamiento de aceite vegetal usado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por Emilio Grande (h.).-<\/strong> En la reuni\u00f3n de comisiones de este lunes, el Concejo Municipal dio despacho a nueve proyectos, los que se votar\u00e1n en la sesi\u00f3n ordinaria de este jueves a las 9:00 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Solicitud puesta en funcionamiento \u00abPlanta procesamiento de aceite vegetal usado\u00bb (Juntos por el Cambio y Unidos para Cambiar Santa Fe):<\/strong> se solicita a la Secretar\u00eda de Energ\u00eda de la Naci\u00f3n proceda a autorizar la puesta en funcionamiento de la planta de procesamiento de aceite vegetal usado, ubicada en el Parque Tecnol\u00f3gico de Reciclado de Rafaela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los considerandos, en el contexto ambiental y econ\u00f3mico que atravesamos, es de suma importancia tomar conciencia del potencial de los Aceites Vegetales Usados (AVUS) y de su correcta gesti\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El biodiesel es una alternativa al uso de combustibles f\u00f3siles, con un menor impacto en la huella de carbono, considerando la creciente preocupaci\u00f3n por la conservaci\u00f3n del medio ambiente y la reducci\u00f3n de las emisiones de gases de efecto invernadero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vinculaci\u00f3n de estas pol\u00edticas de biocombustibles al servicio de transporte p\u00fablico municipal permite una reducci\u00f3n significativa en el gasto en combustible, al tiempo que garantiza un transporte m\u00e1s limpio y eficiente para los ciudadanos de Rafaela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Parque Tecnol\u00f3gico del Reciclado de Rafaela (PTRR) integra el complejo ambiental y est\u00e1 situado en un predio destinado a la radicaci\u00f3n de emprendimientos p\u00fablicos, privados y mixtos relacionados con la transformaci\u00f3n y elaboraci\u00f3n de nuevos productos, a partir del uso de residuos y\/o subproductos de otros procesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las parcelas est\u00e1 destinada al procesamiento de aceites vegetal usado, donde actualmente se acopia, pero no se procesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La planta se encuentra paralizada; por lo tanto, la empresa adjudicataria se encuentra a la espera de la autorizaci\u00f3n para comenzar a operarla por parte de la Secretar\u00eda de Energ\u00eda de la Naci\u00f3n, lo cual imposibilita su funcionamiento e impide todos los beneficios que de su uso se derivan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Pedido de construcci\u00f3n de aulas en 3 escuelas (Juntos Avancemos y Frente de Todos):<\/strong>&nbsp;se solicita al Ejecutivo provincial la construcci\u00f3n de aulas en los siguientes establecimientos educativos de Rafaela: Escuela de Educaci\u00f3n Secundaria Orientada N\u00ba 505 \u00abMahatma Gandhi\u00bb (con una matr\u00edcula de 310 alumnos), Escuela de Educaci\u00f3n Secundaria Orientada N\u00ba 613 \u00abAlicia Catt\u00e1neo\u00bb (con m\u00e1s de 200 alumnos) y Escuela de Educaci\u00f3n T\u00e9cnico Profesional N\u00ba 495 \u00abMalvinas Argentinas\u00bb (con 503 alumnos).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los considerandos, en nuestra ciudad, ante la falta de lugar a los alumnos se los divide en peque\u00f1os espacios del edificio y rotan en los tiempos; tambi\u00e9n la falta de infraestructura puede generar cierta dificultad en el aprendizaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Modificar anexos I y II Reglamento Interno (Juntos por el Cambio, Unidos para Cambiar Santa Fe, Frente de Todos y Juntos Avancemos):<\/strong>&nbsp;para incluir en el encuadramiento de la Direcci\u00f3n General Administrativa-Departamento Administrativo el cargo de Subjefe de Divisi\u00f3n categor\u00eda 18 (art. 10 ley provincial 9.286) bajo el nombre \u00absupervisor administrativo\u00bb. Ser\u00e1n sus funciones: recibir notas, proyectos y documentaci\u00f3n en general proveniente del DEM y de las autoridades y ediles del Concejo. Recibir llamadas telef\u00f3nicas externas, y derivarlas seg\u00fan corresponda. Recibir y atender al p\u00fablico, brindar asesoramiento y derivar a quien corresponda por el motivo de la consulta y\/o visita. Colaborar en tareas referentes al Departamento Administrativo que fueren dispuestas por el Coordinador General Administrativo o autoridades del cuerpo. Esta incorporaci\u00f3n contribuir\u00e1 a una gesti\u00f3n m\u00e1s eficiente y efectiva de los recursos humanos y materiales del cuerpo legislativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Reconocimientos deportistas destacadas Emilia Acosta y Luc\u00eda Gonz\u00e1lez (Juntos por el Cambio y Unidos para Cambiar Santa Fe):<\/strong>&nbsp;por el logro obtenido, que les permitir\u00e1 participar del Campeonato Panamericano de Gimnasia Art\u00edstica a desarrollarse en Santa Marta (Colombia) del 19 al 26 de mayo, representando a nuestro pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Modificar Anexo II ordenanza 5.085 energ\u00edas renovables (Frente de Todos y Juntos Avancemos):<\/strong>\u00a0el IDSR destinar\u00e1 un total de 1.200.000 UCM que ir\u00e1 distribuyendo en los usos definidos seg\u00fan las presentaciones recibidas por los usuarios y efectuar\u00e1 las previsiones presupuestarias para los ejercicios correspondientes hasta alcanzar el cupo establecido. El reintegro ser\u00e1 por el valor monetario equivalente al 30% del costo de adquisici\u00f3n e instalaci\u00f3n del equipo de generaci\u00f3n de energ\u00eda renovable y\/o hasta el m\u00e1ximo definido en el presente, el que resulte de menor valor.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21-1.jpeg\"><img decoding=\"async\" src=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-26830\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Donaci\u00f3n fracci\u00f3n de terreno para calles p\u00fablicas concesi\u00f3n 338 (DEM):<\/strong>&nbsp;se acepta la donaci\u00f3n de Augusto Ricardo Bruno Brarda y Jos\u00e9 Ignacio Bruno Brarda de una fracci\u00f3n de terreno para ensanchar calle Santos Dumont (barrios Ant\u00e1rtida Argentina y \u00c1lamos del Aero Club), con una superficie de 1.747,56 m2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Compra de combustible (DEM):&nbsp;<\/strong>se prorroga a partir del 1 de mayo de 2024 y hasta el 30 de abril de 2026 la autorizaci\u00f3n otorgada al DEM para la compra directa de combustibles, seg\u00fan el art\u00edculo 11 de la ley Org\u00e1nica de Municipalidades 2756, con obligaci\u00f3n de remitir informaci\u00f3n detallada del combustible adquirido al Concejo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Pedido de restauraci\u00f3n del servicio de alumbrado p\u00fablico (Frente de Todos y Juntos Avancemos):<\/strong>&nbsp;solicitan al DEM que restaure el servicio de alumbrado p\u00fablico en diversos sectores de la ciudad que se ven afectados por la falta de funcionamiento de sus luminarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>*Solicitud puesta en marcha programa Nueva Oportunidad (Frente de Todos y Juntos Avancemos):<\/strong>&nbsp;se solicita a la Provincia del programa (ex Santa Fe M\u00e1s) en Rafaela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este proyecto se votar\u00e1 este jueves, pidiendo a la Secretar\u00eda de Energ\u00eda de la Naci\u00f3n para que proceda a su autorizaci\u00f3n. Est\u00e1 ubicada en el Parque Tecnol\u00f3gico de Reciclado de Rafaela, que integra el complejo ambiental. La planta est\u00e1 paralizada y la empresa adjudicataria se encuentra a la espera de la autorizaci\u00f3n para comenzar a operar.<\/p>\n","protected":false},"author":2,"featured_media":27110,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[49,5],"tags":[5960],"class_list":["post-27068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente","category-politica","tag-solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Solicitan que funcione la planta de procesamiento de aceite vegetal usado - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solicitan que funcione la planta de procesamiento de aceite vegetal usado - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Este proyecto se votar\u00e1 este jueves, pidiendo a la Secretar\u00eda de Energ\u00eda de la Naci\u00f3n para que proceda a su autorizaci\u00f3n. Est\u00e1 ubicada en el Parque Tecnol\u00f3gico de Reciclado de Rafaela, que integra el complejo ambiental. La planta est\u00e1 paralizada y la empresa adjudicataria se encuentra a la espera de la autorizaci\u00f3n para comenzar a operar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T19:52:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"Solicitan que funcione la planta de procesamiento de aceite vegetal usado\",\"datePublished\":\"2024-04-29T19:52:01+00:00\",\"dateModified\":\"2024-04-29T19:52:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/\"},\"wordCount\":943,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21.jpeg\",\"keywords\":[\"Solicitan que funcione la planta de procesamiento de aceite vegetal usado\"],\"articleSection\":[\"Medio Ambiente\",\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/\",\"name\":\"Solicitan que funcione la planta de procesamiento de aceite vegetal usado - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21.jpeg\",\"datePublished\":\"2024-04-29T19:52:01+00:00\",\"dateModified\":\"2024-04-29T19:52:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solicitan que funcione la planta de procesamiento de aceite vegetal usado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solicitan que funcione la planta de procesamiento de aceite vegetal usado - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/","og_locale":"es_ES","og_type":"article","og_title":"Solicitan que funcione la planta de procesamiento de aceite vegetal usado - Sabado 100","og_description":"Este proyecto se votar\u00e1 este jueves, pidiendo a la Secretar\u00eda de Energ\u00eda de la Naci\u00f3n para que proceda a su autorizaci\u00f3n. Est\u00e1 ubicada en el Parque Tecnol\u00f3gico de Reciclado de Rafaela, que integra el complejo ambiental. La planta est\u00e1 paralizada y la empresa adjudicataria se encuentra a la espera de la autorizaci\u00f3n para comenzar a operar.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2024-04-29T19:52:01+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21.jpeg","type":"image\/jpeg"}],"author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"Solicitan que funcione la planta de procesamiento de aceite vegetal usado","datePublished":"2024-04-29T19:52:01+00:00","dateModified":"2024-04-29T19:52:01+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/"},"wordCount":943,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21.jpeg","keywords":["Solicitan que funcione la planta de procesamiento de aceite vegetal usado"],"articleSection":["Medio Ambiente","Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/","url":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/","name":"Solicitan que funcione la planta de procesamiento de aceite vegetal usado - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21.jpeg","datePublished":"2024-04-29T19:52:01+00:00","dateModified":"2024-04-29T19:52:01+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-29-at-12.19.21.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/solicitan-que-funcione-la-planta-de-procesamiento-de-aceite-vegetal-usado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Solicitan que funcione la planta de procesamiento de aceite vegetal usado"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/27068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=27068"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/27068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/27110"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=27068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=27068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=27068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}