{"id":27059,"date":"2024-04-27T17:41:37","date_gmt":"2024-04-27T20:41:37","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=26792"},"modified":"2024-04-27T17:41:37","modified_gmt":"2024-04-27T20:41:37","slug":"se-desarrollo-el-encuentro-plenario-industrial-del-ccirr","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/","title":{"rendered":"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El viernes 26 de abril, la\u00a0Comisi\u00f3n de Industrias\u00a0del CCIRR llev\u00f3 a cabo un\u00a0encuentro p\u00fablico-privado\u00a0en el cual se analizaron los principales desaf\u00edos del sector, se evalu\u00f3 la situaci\u00f3n de los diversos rubros industriales y se presentaron m\u00faltiples iniciativas pensadas para potenciar el desarrollo productivo regional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al inicio de la jornada, el economista Fernando Camusso moder\u00f3 un debate en torno a la&nbsp;<em>performance&nbsp;<\/em>productiva y las perspectivas del sector. En ese marco, se expuso la preocupaci\u00f3n por la ca\u00edda de los niveles de actividad, que viene registr\u00e1ndose desde hace al menos nueve meses y que exige la implementaci\u00f3n de pol\u00edticas concretas que permitan sostener la demanda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se plantearon inquietudes en torno a diversos \u00edtems del proyecto de ley Bases y Puntos de Partida para la Libertad de los Argentinos; las distorsiones de precios en insumos b\u00e1sicos para la producci\u00f3n industrial; las deficiencias estructurales del sistema financiero argentino, que provocan la ausencia cr\u00f3nica de cr\u00e9ditos para inversi\u00f3n productiva (los pr\u00e9stamos bancarios al sector privado de Argentina est\u00e1n entre los m\u00e1s bajos del planeta); la importancia de continuar con el proceso de modernizaci\u00f3n normativa laboral; la impostergable transformaci\u00f3n integral que necesita el sistema tributario; y las reformas administrativas pendientes para desburocratizar y simplificar un entramado normativo y documental que hoy requiere muchos tr\u00e1mites; entre otros temas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23520_g.jpg\"><img decoding=\"async\" src=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23520_g.jpg\" alt=\"\" class=\"wp-image-26794\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Seguidamente, se abri\u00f3 un espacio de di\u00e1logo p\u00fablico-privado con los funcionarios p\u00fablicos presentes: el secretario nacional de la Peque\u00f1a y Mediana Empresa, Emprendedores y Econom\u00eda del Conocimiento, Marcos Ayerra; la subsecretaria nacional de Pol\u00edtica Industrial, Daniela Ramos; el secretario provincial de Desarrollo Industrial, Guillermo Beccani; el secretario provincial de Infraestructura Productiva, Mauricio Basso; y la secretaria municipal de Desarrollo Econ\u00f3mico, Innovaci\u00f3n y Empleo, Patricia Imoberdorf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ecosistema industrial<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el segmento final de la jornada, Iv\u00e1n Acosta, director general del CCIRR, expuso sobre el ecosistema institucional que brinda apoyo, y que resulta clave para potenciar el sector industrial de Rafaela y la regi\u00f3n, que es din\u00e1mico, altamente diverso y se encuentra fuertemente integrado al mundo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, se\u00f1al\u00f3 la importancia de la asociatividad y los esquemas de colaboraci\u00f3n empresarial, y la articulaci\u00f3n p\u00fablico-privada como vectores de competitividad territorial. En esa l\u00ednea, puso en valor la relevancia estrat\u00e9gica del CCIRR en este entramado organizacional, a partir del rol protag\u00f3nico que asume como parte del Instituto Tecnol\u00f3gico Rafaela (ITEC), la Asociaci\u00f3n Civil para el Desarrollo y la Innovaci\u00f3n Competitiva Agencia Rafaela (ACDICAR) y la sede Rafaela del Instituto Nacional de Tecnolog\u00eda Industrial (INTI). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del mismo modo, resalt\u00f3 la amplia representatividad sectorial del CCIRR, las m\u00faltiples relaciones y alianzas institucionales construidas con actores claves (la Federaci\u00f3n Industrial de Santa Fe, la Federaci\u00f3n de C\u00e1maras Empresarias del Comercio y Otras Actividades de la Provincia de Santa Fe, la Confederaci\u00f3n Argentina de la Mediana Empresa, la Uni\u00f3n Industrial Argentina, la C\u00e1mara Argentina de Comercio y Servicios y el Instituto para el Desarrollo Empresarial de la Argentina, entre otros) y los diversos servicios que brinda la entidad (<em>networking<\/em>, formaci\u00f3n, vinculaci\u00f3n comercial, etc.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Internacionalizaci\u00f3n productiva<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el encuentro, la C\u00e1mara de Comercio Exterior del CCIRR (CACEX Rafaela) y el Municipio presentaron la edici\u00f3n 2024 del programa Rafaela Exporta, una herramienta de consultor\u00eda, asistencia t\u00e9cnica y promoci\u00f3n comercial destinada al acompa\u00f1amiento de empresas rafaelinas sin experiencia exportadora que pretenden dar sus primeros pasos en el comercio internacional de manera profesional y planificada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se brindaron detalles respecto de la inminente puesta en marcha del Centro Log\u00edstico Internacional de Rafaela; y Pablo Arcamone, presidente de la C\u00e1mara Argentina de S\u00e3o Paulo, expuso sobre las claves para desarrollar un v\u00ednculo estrat\u00e9gico con Brasil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Industriales de Rafaela y la regi\u00f3n dialogaron con funcionarios p\u00fablicos nacionales, provinciales y municipales sobre los principales desaf\u00edos del sector.<\/p>\n","protected":false},"author":2,"featured_media":27098,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[23],"tags":[5952],"class_list":["post-27059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-se-desarrollo-el-encuentro-plenario-industrial-del-ccirr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se desarroll\u00f3 el encuentro plenario industrial del CCIRR - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Industriales de Rafaela y la regi\u00f3n dialogaron con funcionarios p\u00fablicos nacionales, provinciales y municipales sobre los principales desaf\u00edos del sector.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-27T20:41:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23517_g.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR\",\"datePublished\":\"2024-04-27T20:41:37+00:00\",\"dateModified\":\"2024-04-27T20:41:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/\"},\"wordCount\":664,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23517_g.jpg\",\"keywords\":[\"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR\"],\"articleSection\":[\"Econom\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/\",\"name\":\"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23517_g.jpg\",\"datePublished\":\"2024-04-27T20:41:37+00:00\",\"dateModified\":\"2024-04-27T20:41:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23517_g.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23517_g.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/","og_locale":"es_ES","og_type":"article","og_title":"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR - Sabado 100","og_description":"Industriales de Rafaela y la regi\u00f3n dialogaron con funcionarios p\u00fablicos nacionales, provinciales y municipales sobre los principales desaf\u00edos del sector.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2024-04-27T20:41:37+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23517_g.jpg","type":"image\/jpeg"}],"author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR","datePublished":"2024-04-27T20:41:37+00:00","dateModified":"2024-04-27T20:41:37+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/"},"wordCount":664,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23517_g.jpg","keywords":["Se desarroll\u00f3 el encuentro plenario industrial del CCIRR"],"articleSection":["Econom\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/","url":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/","name":"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23517_g.jpg","datePublished":"2024-04-27T20:41:37+00:00","dateModified":"2024-04-27T20:41:37+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23517_g.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/23517_g.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/se-desarrollo-el-encuentro-plenario-industrial-del-ccirr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Se desarroll\u00f3 el encuentro plenario industrial del CCIRR"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/27059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=27059"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/27059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/27098"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=27059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=27059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=27059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}