{"id":27051,"date":"2024-04-25T20:18:49","date_gmt":"2024-04-25T23:18:49","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=26752"},"modified":"2024-04-25T20:18:49","modified_gmt":"2024-04-25T23:18:49","slug":"auditoria-municipal-con-el-65-de-sus-unidades-disponibles","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/","title":{"rendered":"Auditor\u00eda municipal: con el 65% de sus unidades disponibles"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Luego de cuatro meses de auditor\u00eda exhaustiva, el Municipio pone a disposici\u00f3n informaci\u00f3n sobre el estado del equipamiento de algunas de las \u00e1reas m\u00e1s importantes para el continuo mantenimiento de la ciudad de Rafaela. Durante esos 120 d\u00edas de an\u00e1lisis, la actual gesti\u00f3n se encontr\u00f3 con resultados alarmantes que deber\u00e1 afrontar r\u00e1pidamente pensando en el bienestar de la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En car\u00e1cter particular, la auditor\u00eda se realiz\u00f3 en los espacios que responden a la Secretar\u00eda de Infraestructura, Servicios y Ambiente, que encabeza Nicol\u00e1s Asensio. En ese sentido, del total auditado se encontraron con un 35% de los equipos necesarios fuera de servicio. Adem\u00e1s, hay un 65% de equipos en funcionamiento, pero un 20% de ellos se encuentran en muy malas condiciones y requieren de reparaci\u00f3n constante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00e1rea de Higiene Urbana, que aplica a la recolecci\u00f3n de residuos, riego y barrido de los espacios, cuenta con 49 dispositivos de los cuales nueve de ellos est\u00e1n fuera de servicio. Algunos requieren de una reparaci\u00f3n urgente para su normal funcionamiento y otros, como el caso de un tractor, se encuentra siendo utilizado en otro espacio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Complejo Ambiental, por su parte, cuenta con 34 unidades para la acci\u00f3n. Sin embargo, del total, 27 de esos veh\u00edculos se encuentran sin uso y en algunos casos, lo que funciona necesita de reparaci\u00f3n constante. Adem\u00e1s, desde aqu\u00ed se prest\u00f3 un tractor a otro sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Espacios Verdes se divide en Desmalezado, Acarreo y Extracciones y Livianos. En total, se disponen de 117 dispositivos de trabajo donde solo el 70% se encuentra funcionando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La auditor\u00eda tambi\u00e9n arroj\u00f3 sus resultados dentro del \u00e1rea de Log\u00edstica y Reparaciones, donde se cuenta con un total de 6 instrumentos, de los cuales s\u00f3lo funciona una gr\u00faa hidr\u00e1ulica. Tambi\u00e9n en el Aer\u00f3dromo hay un autobomba y un Jeep con requerimiento de reparaci\u00f3n constante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, el estudio arroj\u00f3 que de las 25 unidades del transporte p\u00fablico, solo 18 se encuentran en servicio, mientras que otras 4 son utilizadas en caso de refuerzo o reposici\u00f3n por mantenimiento de las otras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de las dificultades econ\u00f3micas existentes, el Municipio trabaja en la b\u00fasqueda de opciones para hacerle frente a las diferentes \u00e1reas, siempre dejando por delante el compromiso con la comunidad rafaelina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De todos los veh\u00edculos con los que cuenta el Municipio para el cuidado de la ciudad, el 35% se encuentra fuera de servicio. De lo que est\u00e1 en funcionamiento, gran parte requiere de reparaci\u00f3n constante.<\/p>\n","protected":false},"author":2,"featured_media":27085,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[5943],"class_list":["post-27051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-auditoria-municipal-con-el-65-de-sus-unidades-disponibles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Auditor\u00eda municipal: con el 65% de sus unidades disponibles - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auditor\u00eda municipal: con el 65% de sus unidades disponibles - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"De todos los veh\u00edculos con los que cuenta el Municipio para el cuidado de la ciudad, el 35% se encuentra fuera de servicio. De lo que est\u00e1 en funcionamiento, gran parte requiere de reparaci\u00f3n constante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T23:18:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-25-at-15.13.18.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"Auditor\u00eda municipal: con el 65% de sus unidades disponibles\",\"datePublished\":\"2024-04-25T23:18:49+00:00\",\"dateModified\":\"2024-04-25T23:18:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/\"},\"wordCount\":398,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-25-at-15.13.18.jpeg\",\"keywords\":[\"Auditor\u00eda municipal: con el 65% de sus unidades disponibles\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/\",\"name\":\"Auditor\u00eda municipal: con el 65% de sus unidades disponibles - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-25-at-15.13.18.jpeg\",\"datePublished\":\"2024-04-25T23:18:49+00:00\",\"dateModified\":\"2024-04-25T23:18:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-25-at-15.13.18.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-25-at-15.13.18.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auditor\u00eda municipal: con el 65% de sus unidades disponibles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auditor\u00eda municipal: con el 65% de sus unidades disponibles - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/","og_locale":"es_ES","og_type":"article","og_title":"Auditor\u00eda municipal: con el 65% de sus unidades disponibles - Sabado 100","og_description":"De todos los veh\u00edculos con los que cuenta el Municipio para el cuidado de la ciudad, el 35% se encuentra fuera de servicio. De lo que est\u00e1 en funcionamiento, gran parte requiere de reparaci\u00f3n constante.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2024-04-25T23:18:49+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-25-at-15.13.18.jpeg","type":"image\/jpeg"}],"author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"Auditor\u00eda municipal: con el 65% de sus unidades disponibles","datePublished":"2024-04-25T23:18:49+00:00","dateModified":"2024-04-25T23:18:49+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/"},"wordCount":398,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-25-at-15.13.18.jpeg","keywords":["Auditor\u00eda municipal: con el 65% de sus unidades disponibles"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/","url":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/","name":"Auditor\u00eda municipal: con el 65% de sus unidades disponibles - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-25-at-15.13.18.jpeg","datePublished":"2024-04-25T23:18:49+00:00","dateModified":"2024-04-25T23:18:49+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-25-at-15.13.18.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-25-at-15.13.18.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/auditoria-municipal-con-el-65-de-sus-unidades-disponibles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Auditor\u00eda municipal: con el 65% de sus unidades disponibles"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/27051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=27051"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/27051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/27085"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=27051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=27051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=27051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}