{"id":25861,"date":"2024-03-03T10:11:50","date_gmt":"2024-03-03T13:11:50","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=25861"},"modified":"2024-03-03T10:11:50","modified_gmt":"2024-03-03T13:11:50","slug":"vivimos-momentos-de-furia","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/","title":{"rendered":"Vivimos momentos de \u00abFuria\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por\u00a0Guillermo Briggiler.-<\/strong> Argentina vive momentos de furia, y no nos referimos a la casa de Gran Hermano, liderada por Juliana Scaglione apodada \u201cFuria\u201d, sino al argentino que conduce la Casa Rosada y con ella los destinos de la Naci\u00f3n, a quien tambi\u00e9n podr\u00edamos llamarlo de la misma manera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay rabia en los gobernadores: esta semana se la vio principalmente en la relaci\u00f3n con el de Chubut y con el de la provincia de Buenos Aires, pero tambi\u00e9n algunos m\u00e1s, que desatan esa emoci\u00f3n producto de la necesidad de pesos que el gobierno central no enviar\u00e1, dado su imperiosa urgencia de mantener el equilibrio de las cuentas p\u00fablicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, los que tambi\u00e9n arden de irritaci\u00f3n son los habitantes del Congreso, mientras el Frente Renovador parece que rompe filas con Uni\u00f3n por la Patria, los radicales son un tembladeral, y hay empleados del Parlamento nacional que se encuentran montados en c\u00f3lera por recortes en el mismo y reducci\u00f3n del personal, principalmente marcado por incorporaciones pol\u00edticas de otros tiempos y el vigente mandato de \u201cno hay plata\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los punteros sociales, tambi\u00e9n se encuentran tremendamente enojados ya que no solo les recortan los fondos que manejan, sino que los van sacando del medio, intentando llevar la ayuda social directamente a los necesitados y por eso se ven tantas manifestaciones a las que, con el protocolo antipiquete, no les permiten m\u00e1s cortar calles y esto los llena de ira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, los que no entiendan que est\u00e1n ante un radical cambio de paradigma en la pol\u00edtica econ\u00f3mica y financiera, montar\u00e1n en c\u00f3lera por no poder comprender las acciones del equipo gobernante, o en palabras de \u00e9stos, se enojan porque \u201cno la ven\u201d. Nos referimos a que los bonos y acciones argentinas, se encuentran recuperando precios, se trabaja a rajatabla sobre el d\u00e9ficit fiscal, los d\u00f3lares paralelos se encuentran casi un 30% debajo de sus valores previos al cambio de mandato, la inflaci\u00f3n viene mostrando que baja desde los estrafalarios valores que alcanz\u00f3 en diciembre y enero, la emisi\u00f3n monetaria sin respaldo no existe, el FMI desea realizar un nuevo acuerdo y el BCRA acumula reservas luego de a\u00f1os de perderlas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero tambi\u00e9n debemos decir que la gente est\u00e1 soportando un mal trago por el fuerte fogonazo inflacionario tras la devaluaci\u00f3n de diciembre y la consiguiente ca\u00edda del poder adquisitivo de los salarios. Pero al mismo -repetimos- que existe tendencia a la desaceleraci\u00f3n de los precios de los \u00faltimos dos meses y que se ha evitado una hiperinflaci\u00f3n que parec\u00eda inminente en diciembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El plan de ajuste de Milei, impulsado por el super\u00e1vit fiscal de enero y acompa\u00f1ado de un excedente en el mercado de divisas, junto con la absorci\u00f3n de pesos que est\u00e1 llevando a cabo el BCRA, est\u00e1 contribuyendo a reducir la brecha entre el d\u00f3lar oficial y el d\u00f3lar paralelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mantener esto implica continuar con los recortes significativos en el gasto p\u00fablico. Adem\u00e1s, es necesario tener presente que hubo una ca\u00edda notable en los pagos por importaciones que se deber\u00e1n afrontar en los pr\u00f3ximos meses, adem\u00e1s de la disminuci\u00f3n en la actividad econ\u00f3mica, lo que est\u00e1 generando un impacto negativo en los indicadores sociales -ca\u00edda del empleo, del poder adquisitivo del salario y pobreza, entre otros- que deber\u00e1n ser atendidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Precisamente el FMI pidi\u00f3 recientemente al Presidente viabilidad pol\u00edtica para darle m\u00e1s consistencia a las reformas, es decir que el di\u00e1logo y los consensos s\u00ed importan. Milei dio un giro hacia esa direcci\u00f3n el viernes a la noche en el Congreso con su propuesta para avanzar hacia el Pacto de Mayo con gobernadores y l\u00edderes pol\u00edticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed las cosas, al furibundo presidente se lo ve firme, calmado, decidido y tan encaminado a llevar adelante el crecimiento del pa\u00eds, como Furia de ganar Gran Hermano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>#BuenaSaludFinanciera<br>@ElcontadorB<br>@GuilleBriggiler<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong> https:\/\/diariolaopinion.com.ar\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pa\u00eds transita d\u00edas dif\u00edciles, con broncas cruzadas entre la Casa Rosada y las provincias. La inflaci\u00f3n, m\u00e1s all\u00e1 de que desacelera, golpe\u00f3 con fuerza el poder adquisitivo del salario y todo parece cuesta arriba. Pero tambi\u00e9n hay se\u00f1ales para elegir creer.<\/p>\n","protected":false},"author":1,"featured_media":25862,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[23],"tags":[110],"class_list":["post-25861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-vivimos-momentos-de-furia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vivimos momentos de &quot;Furia&quot; - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vivimos momentos de &quot;Furia&quot; - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"El pa\u00eds transita d\u00edas dif\u00edciles, con broncas cruzadas entre la Casa Rosada y las provincias. La inflaci\u00f3n, m\u00e1s all\u00e1 de que desacelera, golpe\u00f3 con fuerza el poder adquisitivo del salario y todo parece cuesta arriba. Pero tambi\u00e9n hay se\u00f1ales para elegir creer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-03T13:11:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-03-at-09.59.30.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\"},\"headline\":\"Vivimos momentos de \u00abFuria\u00bb\",\"datePublished\":\"2024-03-03T13:11:50+00:00\",\"dateModified\":\"2024-03-03T13:11:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/\"},\"wordCount\":690,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-03-at-09.59.30.jpeg\",\"keywords\":[\"Vivimos momentos de \\\"Furia\\\"\"],\"articleSection\":[\"Econom\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/\",\"name\":\"Vivimos momentos de \\\"Furia\\\" - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-03-at-09.59.30.jpeg\",\"datePublished\":\"2024-03-03T13:11:50+00:00\",\"dateModified\":\"2024-03-03T13:11:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-03-at-09.59.30.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-03-at-09.59.30.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vivimos momentos de \u00abFuria\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sabado100.com.ar\/es-ar\"],\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vivimos momentos de \"Furia\" - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/","og_locale":"es_ES","og_type":"article","og_title":"Vivimos momentos de \"Furia\" - Sabado 100","og_description":"El pa\u00eds transita d\u00edas dif\u00edciles, con broncas cruzadas entre la Casa Rosada y las provincias. La inflaci\u00f3n, m\u00e1s all\u00e1 de que desacelera, golpe\u00f3 con fuerza el poder adquisitivo del salario y todo parece cuesta arriba. Pero tambi\u00e9n hay se\u00f1ales para elegir creer.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2024-03-03T13:11:50+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-03-at-09.59.30.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/"},"author":{"name":"admin","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5"},"headline":"Vivimos momentos de \u00abFuria\u00bb","datePublished":"2024-03-03T13:11:50+00:00","dateModified":"2024-03-03T13:11:50+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/"},"wordCount":690,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-03-at-09.59.30.jpeg","keywords":["Vivimos momentos de \"Furia\""],"articleSection":["Econom\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/","url":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/","name":"Vivimos momentos de \"Furia\" - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-03-at-09.59.30.jpeg","datePublished":"2024-03-03T13:11:50+00:00","dateModified":"2024-03-03T13:11:50+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-03-at-09.59.30.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-03-at-09.59.30.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/vivimos-momentos-de-furia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Vivimos momentos de \u00abFuria\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","caption":"admin"},"sameAs":["https:\/\/sabado100.com.ar\/es-ar"],"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/25861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=25861"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/25861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/25862"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=25861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=25861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=25861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}