{"id":21899,"date":"2023-06-10T08:25:13","date_gmt":"2023-06-10T11:25:13","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=21899"},"modified":"2023-06-10T08:25:13","modified_gmt":"2023-06-10T11:25:13","slug":"la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/","title":{"rendered":"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por Emilio Grande (h.).-<\/strong> Este 7 de junio se celebr\u00f3 el D\u00eda del Periodista en la Argentina, en recordaci\u00f3n de la Gazeta de Buenos Ayres, fundada por Mariano Moreno, fecha instituida en un congreso de periodistas realizado en C\u00f3rdoba en 1938.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rompiendo la timidez y con total soltura, Diuco Litrac, alumno de 6\u00ba grado de la escuela Mariano Moreno, expres\u00f3: \u201cpienso en un periodismo libre, orientador y digno, siguiendo el esp\u00edritu patrio de la Gazeta de Buenos Ayres. Se trata de los aut\u00e9nticos ideales de la democracia como es el derecho a la libertad de prensa, como as\u00ed tambi\u00e9n los valores de la honestidad y la veracidad\u201d, durante el acto del d\u00eda del periodista, organizado por el C\u00edrculo de la Prensa de Rafaela en el SEOM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En aquella \u00e9poca como en la actualidad no resulta sencillo ejercer esta profesi\u00f3n que es apasionante, porque demanda mucho empe\u00f1o en la b\u00fasqueda de informaci\u00f3n y el chequeo de las fuentes, para as\u00ed interpretar los hechos de la realidad con criterios \u00e9ticos, en un contexto marcado por el cambio con los nuevos paradigmas culturales y tecnol\u00f3gicos con la irrupci\u00f3n de las redes sociales, con el fen\u00f3meno del \u201cprosumer\u201d (productores y consumidores de noticias).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo decir la verdad en una sociedad cuyos intereses econ\u00f3micos buscan desplazar a la dignidad de la persona? \u00bfC\u00f3mo decir la verdad cuando los valores son pisoteados por intereses pol\u00edticos y econ\u00f3micos? \u00bfC\u00f3mo decir la verdad cuando los sueldos de muchos periodistas no alcanzan para vivir dignamente y tenemos que trabajar en m\u00e1s de un medio de comunicaci\u00f3n para llegar a fin de mes frente a una galopante inflaci\u00f3n?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A decir verdad, si no tenemos un periodismo independiente no puede hablarse de una sociedad democr\u00e1tica y en este concepto se encuentra la relaci\u00f3n m\u00e1s conflictiva que la actividad period\u00edstica debe afrontar, que es la relaci\u00f3n prensa-poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por este motivo, el significado social del rol del periodista y los riesgos que el ejercicio profesional comporta fundamentan la exigencia de una \u00e9tica de la responsabilidad en la pr\u00e1ctica profesional del periodista, que contribuir\u00e1 decididamente en el servicio de la verdad y el bien com\u00fan, y con un sentido cr\u00edtico de la realidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si en m\u00e1s de una oportunidad realizamos cr\u00edticas a la dirigencia por sus malas pr\u00e1cticas, los periodistas tenemos tambi\u00e9n que hacer una autocr\u00edtica sobre determinadas actividades oscuras y en algunos casos poco dignas de nuestra profesi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciertamente, los medios de comunicaci\u00f3n y los periodistas tenemos distintas l\u00edneas editoriales, que se pueden compartir en un todo, en parte o en nada de sus contenidos escritos y audiovisuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siempre hubo, hay y habr\u00e1 un conflicto casi permanente con el poder de turno. La funci\u00f3n period\u00edstica es ser un puente entre las autoridades de los distintos niveles y la gente de a pie, por m\u00e1s que muchos o pocos entiendan esta noble misi\u00f3n de informar, opinar e interpretar los hechos de la realidad con idoneidad profesional, respeto por el que piensa diferente y la permanente b\u00fasqueda de la verdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco de la 57\u00ba Jornada Mundial de las Comunicaciones Sociales del 2023, el papa Francisco se\u00f1al\u00f3: \u201cComunicar cordialmente quiere decir que quien nos lee o nos escucha capta nuestra participaci\u00f3n en las alegr\u00edas y los miedos, en las esperanzas y en los sufrimientos de las mujeres y los hombres de nuestro tiempo. Quien habla as\u00ed quiere bien al otro, porque se preocupa por \u00e9l y custodia su libertad sin violarla\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, es bueno recordar un pensamiento del pr\u00f3cer Mariano Moreno: \u201cM\u00e1s vale una libertad peligrosa que una tranquila esclavitud\u201d. En palabras del colombiano Gabriel Garc\u00eda M\u00e1rquez: \u201cLa \u00e9tica debe acompa\u00f1ar siempre al periodismo, como el zumbido de un moscard\u00f3n\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata del editorial del programa \u201cS\u00e1bado 100\u201d por radio El Espectador (FM 100,1) de Rafaela. \u00bfC\u00f3mo decir la verdad en una sociedad cuyos intereses econ\u00f3micos buscan desplazar a la dignidad de la persona? \u00bfC\u00f3mo decir la verdad cuando los valores son pisoteados por intereses pol\u00edticos y econ\u00f3micos?<\/p>\n","protected":false},"author":1,"featured_media":21900,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4,31,5],"tags":[1199],"class_list":["post-21899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-y-sociedad","category-editorial","category-politica","tag-la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Se trata del editorial del programa \u201cS\u00e1bado 100\u201d por radio El Espectador (FM 100,1) de Rafaela. \u00bfC\u00f3mo decir la verdad en una sociedad cuyos intereses econ\u00f3micos buscan desplazar a la dignidad de la persona? \u00bfC\u00f3mo decir la verdad cuando los valores son pisoteados por intereses pol\u00edticos y econ\u00f3micos?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-10T11:25:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/06\/Periodismo_Digital.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\"},\"headline\":\"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales\",\"datePublished\":\"2023-06-10T11:25:13+00:00\",\"dateModified\":\"2023-06-10T11:25:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/\"},\"wordCount\":667,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/06\/Periodismo_Digital.jpg\",\"keywords\":[\"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales\"],\"articleSection\":[\"Cultura y Sociedad\",\"Editorial\",\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/\",\"name\":\"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/06\/Periodismo_Digital.jpg\",\"datePublished\":\"2023-06-10T11:25:13+00:00\",\"dateModified\":\"2023-06-10T11:25:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/06\/Periodismo_Digital.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/06\/Periodismo_Digital.jpg\",\"width\":720,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/sabado100.com.ar\/es-ar\"],\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/","og_locale":"es_ES","og_type":"article","og_title":"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales - Sabado 100","og_description":"Se trata del editorial del programa \u201cS\u00e1bado 100\u201d por radio El Espectador (FM 100,1) de Rafaela. \u00bfC\u00f3mo decir la verdad en una sociedad cuyos intereses econ\u00f3micos buscan desplazar a la dignidad de la persona? \u00bfC\u00f3mo decir la verdad cuando los valores son pisoteados por intereses pol\u00edticos y econ\u00f3micos?","og_url":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2023-06-10T11:25:13+00:00","og_image":[{"width":720,"height":440,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/06\/Periodismo_Digital.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/"},"author":{"name":"admin","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5"},"headline":"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales","datePublished":"2023-06-10T11:25:13+00:00","dateModified":"2023-06-10T11:25:13+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/"},"wordCount":667,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/06\/Periodismo_Digital.jpg","keywords":["La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales"],"articleSection":["Cultura y Sociedad","Editorial","Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/","url":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/","name":"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/06\/Periodismo_Digital.jpg","datePublished":"2023-06-10T11:25:13+00:00","dateModified":"2023-06-10T11:25:13+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/06\/Periodismo_Digital.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/06\/Periodismo_Digital.jpg","width":720,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/la-funcion-del-periodismo-frente-a-los-nuevos-paradigmas-comunicacionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"La funci\u00f3n del periodismo frente a los nuevos paradigmas comunicacionales"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/0a9d576d4c50f5ee5c774c01644c2bf5","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/4011a1aa10f57cda77b281e34885822b.jpg?ver=1787726386","caption":"admin"},"sameAs":["https:\/\/sabado100.com.ar\/es-ar"],"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/s100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/21899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=21899"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/21899\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/21900"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=21899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=21899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=21899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}