{"id":21693,"date":"2023-05-26T20:08:56","date_gmt":"2023-05-26T23:08:56","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=21693"},"modified":"2023-05-26T20:08:56","modified_gmt":"2023-05-26T23:08:56","slug":"senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/","title":{"rendered":"Senado: impulsan una ley para frenar escraches y falsas denuncias"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Esta situaci\u00f3n ha desembocado en una problem\u00e1tica alarmante en los \u00faltimos a\u00f1os: una intensificaci\u00f3n de las falsas denuncias que, motivadas por diversas razones (que incluyen la venganza, influir en casos de separaci\u00f3n y tenencia de hijos, obtener un subsidio o perjudicar una posici\u00f3n pol\u00edtica o empresarial) pueden tener consecuencias devastadoras para los hombres y para la sociedad en general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, un nuevo proyecto de ley en Argentina, presentado el 23 de mayo de 2023 en el Senado de la Naci\u00f3n, busca poner fin a esta situaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El papel crucial de los medios en la propagaci\u00f3n de un escrache puede conducir a una condena social anticipada, antes de que un tribunal de Justicia pueda emitir un veredicto. Esta tendencia es particularmente da\u00f1ina cuando se dirige a hombres acusados de abuso o violaci\u00f3n, frecuentemente presentados como culpables antes de un veredicto oficial.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/realpolitik.com.ar\/uploads\/ckeditor\/2023\/05\/20230526132159_captura-de-pantalla-2023-05-26-a-la-s-13-09-23.webp\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Este sesgo en la narrativa, que muchas veces representa a los hombres como agresores y a las mujeres como v\u00edctimas, ha contribuido a distorsionar la gravedad de la \u00abviolencia de g\u00e9nero\u00bb, y favorecer a las mujeres denunciantes al ser colocadas en un papel exclusivamente de v\u00edctimas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tiempos recientes, los medios de comunicaci\u00f3n en Argentina han comenzado a&nbsp;<a href=\"https:\/\/www.lanacion.com.ar\/editoriales\/deleznables-falsas-denuncias-nid22092022\/?s=08\">reconocer<\/a>&nbsp;y dar&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=vpAI1kmz-nU&amp;t=1961s\">visibilidad<\/a>&nbsp;a este problema. Este cambio en la narrativa ha sido impulsado por organizaciones como el&nbsp;<a href=\"https:\/\/observatoriodefalsasdenuncias.org\/\">Observatorio de Falsas Denuncias<\/a>&nbsp;y ha ganado notoriedad a nivel nacional e internacional, con el primer&nbsp;<a href=\"https:\/\/www.clarin.com\/sociedad\/marcharon-ministerio-mujer-reclamar-falsas-denuncias-presuncion-inocencia-_0_vEOdTwy5AP.html\">d\u00eda internacional contra las Falsas Denuncias<\/a>&nbsp;celebrado el 9 de septiembre de 2022.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/realpolitik.com.ar\/uploads\/ckeditor\/2023\/05\/20230526132142_70a8e7f5-386f-4076-ac57-54e88221694a.webp\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a la gravedad de la problem\u00e1tica, existen numerosos casos en los que, a\u00fan despu\u00e9s de demostrar que las denuncias eran falsas, las denunciantes no reciben condena alguna. Esta situaci\u00f3n plantea importantes cuestiones sobre la equidad y la justicia en estos casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para contrarrestar este desbalance, el proyecto de ley presentado por la senadora\u00a0<strong><a href=\"https:\/\/realpolitik.com.ar\/tag\/carolina-losada\">Carolina Losada<\/a><\/strong>\u00a0y la activista\u00a0<strong>Andrea Guacci<\/strong>, busca castigar a los falsos denunciantes y tipificar en el c\u00f3digo penal el delito de la falsa denuncia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este proyecto de ley propone una aproximaci\u00f3n para abordar la problem\u00e1tica de las falsas denuncias y los escraches, buscando fortalecer el marco legal al establecer una penalizaci\u00f3n para aquellos que presenten falsas denuncias. Se trata de un paso cr\u00edtico para disuadir a los individuos de instrumentalizar la Justicia con fines maliciosos y provocar da\u00f1os impunemente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La clasificaci\u00f3n de las falsas denuncias y los escraches como un delito contra el honor y buen nombre, especialmente en el caso de falsas denuncias de delitos sexuales y violencia de g\u00e9nero, refuerza la gravedad de estas acciones y su impacto perjudicial en la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la presentaci\u00f3n de este proyecto de ley podr\u00eda funcionar como un catalizador para programas de educaci\u00f3n que sensibilicen sobre las consecuencias de las falsas denuncias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al reconocer la falsa denuncia como un delito, se env\u00eda un mensaje claro a los actores del sistema judicial sobre la importancia de tomar en serio este problema y de investigar a fondo todas las denuncias para asegurarse de que se haga justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este cambio en la legislaci\u00f3n representa un paso crucial en la lucha contra las falsas denuncias y los escraches, y podr\u00eda sentar un precedente importante para otros pa\u00edses que enfrentan problemas similares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para poner \u00e9nfasis en la gravedad de este problema y hacer eco de la necesidad de un cambio legal, el pr\u00f3ximo 30 de mayo de 2023 se celebrar\u00e1 el primer d\u00eda Contra el Escrache hacia los Hombres en Argentina. Impulsado por el \u00abFrente de Mujeres\u00bb, este evento marcar\u00e1 un precedente hist\u00f3rico en la lucha contra las falsas denuncias y escraches hacia los hombres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incrustado en esta protesta, tambi\u00e9n habr\u00e1 un recuerdo para aquellos que tr\u00e1gicamente se han quitado la vida debido a las consecuencias de las falsas acusaciones y la difamaci\u00f3n p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Participantes y organizadores por igual se movilizar\u00e1n en apoyo al proyecto de ley recientemente introducido, con el objetivo de arrojar luz sobre el problema en cuesti\u00f3n y ejercer presi\u00f3n sobre los legisladores para asegurar que este proyecto de ley cr\u00edtico sea aprobado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente: <\/strong>https:\/\/realpolitik.com.ar\/ <strong>Colaboraci\u00f3n de la rafaelina Melisa Girardotti.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la era de la informaci\u00f3n y las redes sociales, la Justicia se desdobla en la corte formal y la corte de la opini\u00f3n p\u00fablica. Esta \u00faltima, empoderada por la velocidad y omnipresencia de internet, puede sentenciar a un individuo antes que un tribunal de Justicia lo haga, en un fen\u00f3meno conocido como \u201cescrache\u201d.<\/p>\n","protected":false},"author":2,"featured_media":21694,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[1401],"class_list":["post-21693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Senado: impulsan una ley para frenar escraches y falsas denuncias - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senado: impulsan una ley para frenar escraches y falsas denuncias - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"En la era de la informaci\u00f3n y las redes sociales, la Justicia se desdobla en la corte formal y la corte de la opini\u00f3n p\u00fablica. Esta \u00faltima, empoderada por la velocidad y omnipresencia de internet, puede sentenciar a un individuo antes que un tribunal de Justicia lo haga, en un fen\u00f3meno conocido como \u201cescrache\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-26T23:08:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-20.01.51.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"495\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"Senado: impulsan una ley para frenar escraches y falsas denuncias\",\"datePublished\":\"2023-05-26T23:08:56+00:00\",\"dateModified\":\"2023-05-26T23:08:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/\"},\"wordCount\":732,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-20.01.51.jpeg\",\"keywords\":[\"Senado: impulsan una ley para frenar escraches y falsas denuncias\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/\",\"name\":\"Senado: impulsan una ley para frenar escraches y falsas denuncias - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-20.01.51.jpeg\",\"datePublished\":\"2023-05-26T23:08:56+00:00\",\"dateModified\":\"2023-05-26T23:08:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#primaryimage\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-20.01.51.jpeg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-20.01.51.jpeg\",\"width\":880,\"height\":495},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Senado: impulsan una ley para frenar escraches y falsas denuncias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senado: impulsan una ley para frenar escraches y falsas denuncias - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/","og_locale":"es_ES","og_type":"article","og_title":"Senado: impulsan una ley para frenar escraches y falsas denuncias - Sabado 100","og_description":"En la era de la informaci\u00f3n y las redes sociales, la Justicia se desdobla en la corte formal y la corte de la opini\u00f3n p\u00fablica. Esta \u00faltima, empoderada por la velocidad y omnipresencia de internet, puede sentenciar a un individuo antes que un tribunal de Justicia lo haga, en un fen\u00f3meno conocido como \u201cescrache\u201d.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2023-05-26T23:08:56+00:00","og_image":[{"width":880,"height":495,"url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-20.01.51.jpeg","type":"image\/jpeg"}],"author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"Senado: impulsan una ley para frenar escraches y falsas denuncias","datePublished":"2023-05-26T23:08:56+00:00","dateModified":"2023-05-26T23:08:56+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/"},"wordCount":732,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-20.01.51.jpeg","keywords":["Senado: impulsan una ley para frenar escraches y falsas denuncias"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/","url":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/","name":"Senado: impulsan una ley para frenar escraches y falsas denuncias - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#primaryimage"},"thumbnailUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-20.01.51.jpeg","datePublished":"2023-05-26T23:08:56+00:00","dateModified":"2023-05-26T23:08:56+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#primaryimage","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-20.01.51.jpeg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-20.01.51.jpeg","width":880,"height":495},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/senado-impulsan-una-ley-para-frenar-escraches-y-falsas-denuncias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Senado: impulsan una ley para frenar escraches y falsas denuncias"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/21693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=21693"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/21693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media\/21694"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=21693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=21693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=21693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}