{"id":14280,"date":"2021-10-12T23:16:52","date_gmt":"2021-10-13T02:16:52","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=14280"},"modified":"2021-10-12T23:16:52","modified_gmt":"2021-10-13T02:16:52","slug":"anibal-fernandez-con-el-lenguaje-de-la-mafia","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/","title":{"rendered":"An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por <a href=\"https:\/\/www.lanacion.com.ar\/autor\/joaquin-morales-sola-51\/\">Joaqu\u00edn Morales Sol\u00e1<\/a>.-<\/strong> Conoci\u00f3 la retorica de la revoluci\u00f3n cuando ya era un hombre grande y confundi\u00f3 la m\u00edstica revolucionaria con los m\u00e9todos mafiosos. Antes,\u00a0<strong>An\u00edbal Fern\u00e1ndez<\/strong>\u00a0hab\u00eda sido un conservador dirigente del duro y arisco conurbano bonaerense. Suele usar un lenguaje barriobajero y maleducado para hacer pol\u00edtica, tal vez porque esa es la escuela en la que aprendi\u00f3 en la ind\u00f3mita Buenos Aires. La versiones lo vincularon con el tr\u00e1fico de efedrina (una sustancia imprescindible para fabricar la metanfetamina, una droga poderosa) y la Iglesia argentina lo cruz\u00f3 en 2015 hasta arruinarle su carrera hacia la gobernaci\u00f3n bonaerense, que perdi\u00f3. Nunca se llev\u00f3 bien con Alberto Fern\u00e1ndez, por quien sent\u00eda celos pol\u00edticos por la cercan\u00eda de este con\u00a0<strong>N\u00e9stor y Cristina Kirchner<\/strong>. El actual presidente lo mand\u00f3 en 2020 de penitencia como interventor de Yacimientos Carbon\u00edferos Fiscales, que era mucho si se lo compara con la perdidosa candidatura de An\u00edbal a concejal en Pinamar un a\u00f1o antes.\u00a0<strong>Alberto Fern\u00e1ndez<\/strong>\u00a0sab\u00eda que su tocayo An\u00edbal le provocar\u00eda m\u00e1s problemas que los que resolver\u00eda, pero la derrota es la madre de las herej\u00edas, las rectificaciones y las paradojas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El nombre de An\u00edbal Fern\u00e1ndez volvi\u00f3 a cobrar vuelo (mal vuelo) el lunes \u00faltimo cuando en un&nbsp;<a href=\"https:\/\/www.lanacion.com.ar\/politica\/la-justificacion-de-anibal-fernandez-por-el-tuit-a-nik-el-vive-agraviandonos-nid12102021\/\">tuit patotero<\/a>&nbsp;amenaz\u00f3 a la familia de&nbsp;<strong>Nik<\/strong>, un dibujante y humorista con un olfato pol\u00edtico m\u00e1s fino que el de muchos analistas pol\u00edticos. El ministro de Seguridad no nombr\u00f3 a las hijas de Nik, pero s\u00ed nombr\u00f3 al colegio donde ellas estudian (la prestigiosa ORT) y, de paso, desliz\u00f3 una mentira: que esa instituci\u00f3n recibe subsidios del Estado. La ORT no recibe ning\u00fan subsidio estatal; es financiada mayormente por las contribuciones de la comunidad jud\u00eda; admite el ingreso de ni\u00f1os y j\u00f3venes de cualquier religi\u00f3n, y otorga becas a j\u00f3venes pobres sin distinci\u00f3n de credos. Ayer, en un reportaje en&nbsp;<a href=\"https:\/\/www.clarin.com\/politica\/anibal-fernandez-nik-quiere-hacerme-denuncia-haga-_0_LODtHqXw_.html\" rel=\"noreferrer noopener\" target=\"_blank\">Clar\u00edn&nbsp;<\/a>An\u00edbal dijo que no sab\u00eda que las hijas de Nik cursan en el colegio ORT. \u00bfPor qu\u00e9 nombr\u00f3 a esa instituci\u00f3n, entonces? \u00bfCinismo puro o pura cobard\u00eda? Qui\u00e9n lo sabe.&nbsp;<strong>Ricardo L\u00f3pez Murphy<\/strong>&nbsp;asegur\u00f3 p\u00fablicamente que en esa amenaza de An\u00edbal Fern\u00e1ndez \u201csobrevuela el antisemitismo\u201d. An\u00edbal contest\u00f3 que tiene amigos jud\u00edos. Cu\u00e1ndo no. El m\u00e9todo (mostrar sin nombrar) es perfectamente mafioso. Recuerda al \u201ccaso Pentangeli\u201d en la primera parte de la ic\u00f3nica pel\u00edcula&nbsp;<em>El Padrino<\/em>. Francesco Pentageli (interpretado magistralmente por Michael Gazzo) es un mafioso arrestado por la polic\u00eda de Nueva York que decide contar en un juicio p\u00fablico las andanzas de sus c\u00f3mplices. Cuando ya estaba sentado en el estrado a punto de hablar, ve aparecer entre el p\u00fablico a un hombre vestido con el estilo de los campesinos sicilianos. Era su hermano, que la mafia hab\u00eda trasladado de Sicilia a Nueva York. Pentangeli call\u00f3 para siempre; no habl\u00f3 nunca hasta que muri\u00f3 por un suicidio inducido. An\u00edbal Fern\u00e1ndez le mostr\u00f3 a Nik qu\u00e9 sabe d\u00f3nde estudian sus hijas, sin nombrar a sus hijas. Las cosas nunca son id\u00e9nticas, pero muchas veces son dram\u00e1ticamente parecidas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resizer.glanacion.com\/resizer\/s0peULf9Xh4YvJtMyJmVtpx0Em4=\/768x0\/filters:quality(80)\/cloudfront-us-east-1.images.arcpublishing.com\/lanacionar\/ES5PFV2BB5G77FMA5QQIFBDBGQ.PNG\" alt=\"El mensaje del ministro de Seguridad, An\u00edbal Fern\u00e1ndez, al caricaturista por su tuit\"\/><figcaption><strong>El mensaje del ministro de Seguridad, An\u00edbal Fern\u00e1ndez, al caricaturista por su tuit.<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 hab\u00eda hecho Nik para enfurecer al ministro de Seguridad, que aprovech\u00f3 para exhibir sus conocimientos de la vida privada y personal de las personas? El historietista escribi\u00f3 un tuit cr\u00edtico sobre la pol\u00edtica de despilfarro de dinero espurio por parte del Gobierno en la campa\u00f1a electoral hacia el 14 de noviembre. Critic\u00f3 desde el regalo de bicicletas y heladeras hasta los viajes gratis de egresados, que ser\u00e1n financiados por un Estado quebrado. Nada que no critique cualquier argentino con sentido com\u00fan. Pero Nik, conocido y respetado, era un buen blanco para expandir el temor entre muchos argentinos. Nadie se asust\u00f3, es cierto; son leones sin dientes. Reaccionaron los periodistas, las entidades period\u00edsticas, algunos empresarios (faltaron las entidades, salvo las del campo), menos el presidente de la Naci\u00f3n. Alberto Fern\u00e1ndez calla. Dicen que se conform\u00f3 con el supuesto pedido de disculpas de An\u00edbal a Nik. Ese pedido concluye diciendo que el humorista \u201cvive agravi\u00e1ndonos\u201d. Extra\u00f1a disculpa y m\u00e1s extra\u00f1a comparaci\u00f3n: para An\u00edbal Fern\u00e1ndez es lo mismo un ministro de Seguridad, con acceso, como se vio, a los datos personales de todos los argentinos, que una persona cuya \u00fanica arma es dibujar a los trastornados que gobiernan. Mucho m\u00e1s porte tuvo el jefe de Gabinete,&nbsp;<strong>Juan Manzur<\/strong>, que calific\u00f3 de&nbsp;<a href=\"https:\/\/www.lanacion.com.ar\/politica\/que-dijo-leandro-santoro-el-primer-oficialista-que-hablo-sobre-las-intimidaciones-de-anibal-nid12102021\/\">\u201cmuy desafortunada\u201d<\/a>&nbsp;la frase de An\u00edbal Fern\u00e1ndez, aunque \u00e9l tambi\u00e9n se qued\u00f3 con esas disculpas que no sirven para disculpar a nadie.&nbsp;<a href=\"https:\/\/www.lanacion.com.ar\/politica\/anibal-fernandez-vs-nik-cuando-el-presidente-no-dice-ni-si-ni-no-nid12102021\/\">El silencio del Presidente aturde<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">An\u00edbal Fern\u00e1ndez fue un operador todoterreno de Eduardo Duhalde cuando ni las hojas se mov\u00edan en la provincia de Buenos Aires sin que este lo supiera. Duhalde, un peronista cl\u00e1sico al que le gusta promover la convivencia de sindicatos y empresarios, es ideol\u00f3gicamente lo m\u00e1s distinto que puede haber con las ideas de los Kirchner. Durante el reinado de Duhalde en territorio bonaerense, An\u00edbal Fern\u00e1ndez fue intendente de Quilmes. Una leyenda dice que huy\u00f3 de la Justica en el ba\u00fal del auto de su abogado Mart\u00edn Ordoqui. Nunca se supo si esa historia fue cierta, pero Ordoqui termin\u00f3 haciendo una veloz carrera judicial que lo convirti\u00f3 en juez de la C\u00e1mara de Casaci\u00f3n. Mucho despu\u00e9s, An\u00edbal Fern\u00e1ndez desminti\u00f3 que haya estado pr\u00f3fugo, pero lo hizo con una frase confusa: \u201cEstuve alejado de la Justicia para preservar la investidura del intendente de Quilmes\u201d, dijo suelto de cuerpo. \u00bfAlejado y pr\u00f3fugo son cosas distintas en este caso? La causa judicial era una denuncia de Aguas Argentinas contra la intendencia. Por aquellos tiempos, An\u00edbal Fern\u00e1ndez militaba en la derecha peronista de su jefe pol\u00edtico, Duhalde.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resizer.glanacion.com\/resizer\/YvITe9x91J6yxSmb1rzQvzIbPmA=\/768x0\/filters:quality(80)\/cloudfront-us-east-1.images.arcpublishing.com\/lanacionar\/7QTEHAVLTVDENE4OEKITK26JAI.JPG\" alt=\"An\u00edbal Fern\u00e1ndez, Juan Manzur y Alberto Fern\u00e1ndez, el lunes en Tucum\u00e1n\"\/><figcaption><strong>An\u00edbal Fern\u00e1ndez, Juan Manzur y Alberto Fern\u00e1ndez, el lunes en Tucum\u00e1n.<\/strong><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La Morsa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mucho m\u00e1s graves fueron las&nbsp;<strong>denuncias posteriores que lo vincularon con el tr\u00e1fico de efedrina<\/strong>&nbsp;y con el triple crimen de General Rodr\u00edguez. Uno de los pr\u00f3fugos detenidos por ese crimen, Mart\u00edn Lanatta, cont\u00f3 luego que entre ellos, los delincuentes, hablaban de \u201cLa Morsa\u201d y que se refer\u00edan de ese modo al actual ministro de Seguridad. Otros testimonios se\u00f1alaron que \u201cLa Morsa\u201d era un polic\u00eda o un agente de los servicios de inteligencia. Nunca se aclar\u00f3 qui\u00e9n era&nbsp;<strong>\u201cLa Morsa\u201d<\/strong>, pero lo cierto es que durante la gesti\u00f3n de An\u00edbal Fern\u00e1ndez como ministro de Justicia se triplic\u00f3 en un a\u00f1o la importaci\u00f3n de efedrina. La efedrina, una droga que se usa en muy peque\u00f1as dosis para fabricar antihistam\u00ednicos, est\u00e1 prohibida en M\u00e9xico, donde se produce la metanfetamina. Seg\u00fan investigaciones de la Justicia local, la efedrina que importaba la Argentina se contrabandeaba a M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lleg\u00f3 An\u00edbal Fern\u00e1ndez a 2015 cuando decidi\u00f3 dar el gran salto de su vida: ser gobernador elegido en la provincia de Buenos Aires, la tierra de sus amores, donde intim\u00f3 con la gloria y la ruina, donde conoce a poetas y malandras, a pol\u00edticos y malhechores. En la campa\u00f1a electoral, los p\u00falpitos de la Iglesia se llenaron de curas que todos los domingos pregonaban una sola frase:\u00a0<strong>\u201cCon la droga, no\u201d.<\/strong>\u00a0Es imposible saber si se trataba de una inspiraci\u00f3n de la Providencia o de esa clase de informaci\u00f3n reservada y fidedigna que siempre tiene la Iglesia. Lo cierto es que hubo una l\u00ednea pol\u00edtica de la Iglesia para impedir el arribo de An\u00edbal Fern\u00e1ndez a la gobernaci\u00f3n bonaerense. Pero An\u00edbal nunca confundi\u00f3 a\u00a0<strong>Carlos Kunkel<\/strong>, un viejo montonero y militante fan\u00e1tico del kirchnerismo. \u201cA An\u00edbal lo condenan su historia y su presente. Es un piantavotos\u201d, se despach\u00f3 Kunkel en plena campa\u00f1a electoral de 2015. Mar\u00eda Eugenia Vidal lo bati\u00f3 en esas elecciones en la decisiva Buenos Aires. An\u00edbal le abri\u00f3 el paso a la presidencia de\u00a0<strong>Mauricio Macri<\/strong>; tal vez por eso lo odia tanto. Es mucho m\u00e1s f\u00e1cil ganar la presidencia de la Naci\u00f3n cuando ya se gan\u00f3 la provincia de Buenos Aires. Es probable que ahora vuelva a hacerles otro favor a los opositores del kirchnerismo gobernante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No puede extra\u00f1ar lo que hizo con Nik si An\u00edbal es el mismo An\u00edbal que difam\u00f3 a&nbsp;<strong>Alberto Nisman<\/strong>&nbsp;despu\u00e9s de que este ya hab\u00eda sido asesinado. Asesinado es un t\u00e9rmino correcto porque fue un crimen seg\u00fan las conclusiones de la Justicia argentina, que no cambiaron aun. Dijo del Nisman ya muerto: \u201cEs un sinverg\u00fcenza que usaba dinero de la AMIA para salir con minas y pagar \u00f1oquis\u201d. Esa falta de respeto hacia una persona muerta, incapaz por lo tanto de defenderse, se respaldaba en carteles an\u00f3nimos con la foto de Nisman rodeado de mujeres. No ten\u00edan nada de an\u00f3nimos. Todos sab\u00edan que eran carteles financiados y distribuidos por el gobierno al que pertenec\u00eda An\u00edbal Fern\u00e1ndez. A&nbsp;<strong>Elisa Carri\u00f3<\/strong>&nbsp;la trat\u00f3 de \u201cgorda y loca\u201d y nadie en el mundo del kirchnerismo, tan sensible al feminismo y a la igualdad de g\u00e9nero, se inmut\u00f3 por semejante ultraje a una mujer. Se puede disentir con una dirigente pol\u00edtica, pero ese trato es inadmisible cualquiera sea el nivel de la disputa. El kirchnerismo es as\u00ed: lo pol\u00edticamente correcto es aplicable a los enemigos; los amigos pueden hacer lo que quieran con el lenguaje, el maltrato y la calumnia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando los Kirchner despojaron del poder a Duhalde, An\u00edbal Fern\u00e1ndez se enamor\u00f3 del palabrer\u00edo revolucionario. Adi\u00f3s a la derecha peronista. Abandon\u00f3 a los recios barones del conurbano y se conmovi\u00f3 con \u201clos pibes para la revoluci\u00f3n\u201d. Pero siempre conserv\u00f3 algo del viejo An\u00edbal. En sus tiempos de ministro del Interior, la Polic\u00eda Federal depend\u00eda de \u00e9l. Llevaba colgado en la cintura un celular especial para comunicarse con los jefes de cada comisaria de la Capital. \u201cHac\u00e9 lo que ten\u00e9s que hacer o le dir\u00e9 al jefe lo que est\u00e1s haciendo cuando nadie te ve\u201d, lo amenaz\u00f3 una vez a un comisario. \u201cYo no hac\u00eda nada, pero me di cuenta de c\u00f3mo presionaba el ministro a mis compa\u00f1eros\u201d, cont\u00f3 luego el comisario.\u00a0<strong>La mafia no practica el lirismo de la revoluci\u00f3n, sino el rugoso dialecto de la amenaza.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong> https:\/\/www.lanacion.com.ar\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Seguridad fue fiel a su historia y coloc\u00f3 al Gobierno en una situaci\u00f3n delicada; el silencio del Presidente sobre la amenaza a Nik aturde.<\/p>\n","protected":false},"author":2,"featured_media":14281,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[3168,3169],"class_list":["post-14280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-anibal-fernandez","tag-con-el-lenguaje-de-la-mafia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"El ministro de Seguridad fue fiel a su historia y coloc\u00f3 al Gobierno en una situaci\u00f3n delicada; el silencio del Presidente sobre la amenaza a Nik aturde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-13T02:16:52+00:00\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia\",\"datePublished\":\"2021-10-13T02:16:52+00:00\",\"dateModified\":\"2021-10-13T02:16:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/\"},\"wordCount\":1849,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"An\u00edbal Fern\u00e1ndez\",\"con el lenguaje de la mafia\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/\",\"name\":\"An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-10-13T02:16:52+00:00\",\"dateModified\":\"2021-10-13T02:16:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/","og_locale":"es_ES","og_type":"article","og_title":"An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia - Sabado 100","og_description":"El ministro de Seguridad fue fiel a su historia y coloc\u00f3 al Gobierno en una situaci\u00f3n delicada; el silencio del Presidente sobre la amenaza a Nik aturde.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2021-10-13T02:16:52+00:00","author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia","datePublished":"2021-10-13T02:16:52+00:00","dateModified":"2021-10-13T02:16:52+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/"},"wordCount":1849,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#primaryimage"},"thumbnailUrl":"","keywords":["An\u00edbal Fern\u00e1ndez","con el lenguaje de la mafia"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/","url":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/","name":"An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-10-13T02:16:52+00:00","dateModified":"2021-10-13T02:16:52+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/anibal-fernandez-con-el-lenguaje-de-la-mafia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"An\u00edbal Fern\u00e1ndez, con el lenguaje de la mafia"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/14280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=14280"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/14280\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=14280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=14280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=14280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}