{"id":13072,"date":"2021-07-18T19:23:54","date_gmt":"2021-07-18T22:23:54","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=13072"},"modified":"2021-07-18T19:23:54","modified_gmt":"2021-07-18T22:23:54","slug":"no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/","title":{"rendered":"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por Emilio Grande (h.).-<\/strong> Para las PASO del 12 de septiembre en nuestra ciudad se presentaron 15 listas para concejales, de las cuales 10 participar\u00e1n en internas. El Frente Federal Vida y Familia es encabezado por Delvis Bodoira, abogado de 40 a\u00f1os, docente de la UCSE DAR y de la UNRAF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuenta con una extensa militancia en el PJ desde 1999, en 2003 fue secretario del bloque justicialista en el Concejo y en 2004 secretario privado de la Presidencia del cuerpo a cargo de Luis Castellano. Desde 2011 hasta 2019 se desempe\u00f1\u00f3 como funcionario municipal, ocupando los cargos de subsecretario de Deportes (fue fundador de la marat\u00f3n 21k \u201cCiudad de Rafaela\u201d en homenaje al profesor Daniel \u201cTecla\u201d Far\u00edas), secretario de Gobierno y Ciudadan\u00eda, y secretario Prevenci\u00f3n en Seguridad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.sabado100.com.ar\/wp-content\/uploads\/2021\/07\/image-2.jpg\"><img decoding=\"async\" src=\"https:\/\/www.sabado100.com.ar\/wp-content\/uploads\/2021\/07\/image-2.jpg\" alt=\"\" class=\"wp-image-13074\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFue hablado con el Intendente, quien entendi\u00f3 que el 10 de diciembre de 2019 ten\u00eda que hacer una renovaci\u00f3n equipo y me qued\u00e9 afuera; el salir del microclima y el poder ver la realidad desde otra lado te hace ver las cosas distintas. Desde afuera me junt\u00e9 varias veces con el Intendente para aportar para la ciudad y le dije que tal decisi\u00f3n no es acertada, lo que escucho hablando con los comerciantes, gastron\u00f3micos y hoteleros me parece que le estamos errando, siempre con intenciones de sumar; se est\u00e1n tomando decisiones en Buenos Aires o Santa Fe, que no tienen nada que ver con la realidad rafaelina, y somos arrastrados por una pol\u00edtica nacional que no se condice con la realidad local. Mantenemos una relaci\u00f3n excelente y de amistad, pero empezamos a diferenciarnos porque pensamos distinto, cada uno est\u00e1 en su derecho y tenemos que respetar al otro; \u00e9l entiende que uno est\u00e1 equivocado\u201d, expres\u00f3 en el programa \u201cS\u00e1bado 100\u201d por radio El Espectador (FM 100,1) de Rafaela, conducido por quien firma esa entrevista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La lista se completa con la doctora M\u00f3nica Schmutzler de Becla (representante del SAMCO de Villa Rosas), Diego Soltermann (empresario metal\u00fargico y tuvo el restaurante El Chateau), Ermelinda Godoy (presidente vecinal del barrio 2 de Abril), Ezequiel Torres (t\u00e9cnico en Comunicaci\u00f3n Social y asesor del diputado provincial Juan Arga\u00f1araz), Natalia Fiordelli (tiene una pasteler\u00eda sin tacc y su familia tiene la panificadora San Rafael en el barrio G\u00fcemes), Juan Lang (hist\u00f3rico mozo del comedor Susana) y Mar\u00eda Eugenia Ram\u00edrez (joven psicopedagoga). \u201cHemos conformado una muy linda lista, con buena gente sana, honesta, trabajadora y con principios\u201d, agreg\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/open.spotify.com\/episode\/2KnowG9eAdSQHgzH5M5NKf?si=D-Swc4ywQ4iHIzYrKHdA3Q&#038;dl_branch=1\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-\u00bfHay diferencias ideol\u00f3gicas sobre los proyectos pol\u00edticos con el oficialismo?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Hay cuestiones que tienen que ver con los valores y con la formaci\u00f3n que uno no comparte, lo m\u00e1s sano fue plante\u00e1rselo y armar nuestro propio espacio porque no nos sent\u00edamos representados; con el diputado Arga\u00f1araz encontr\u00e9 un hermoso grupo de gente, que comparte estos valores y principios, y fue el gestor de este espacio. Alguien dijo una vez si no est\u00e1n de acuerdo armen su propio partido y ganen las elecciones; as\u00ed fue que armamos el partido, ofrecemos una alternativa a la ciudadan\u00eda para que tenga otra voz alejada de las grandes estructuras a la que estamos acostumbrados y debe existir otro espacio. A nivel nacional y provincial es m\u00e1s dif\u00edcil, pero a nivel local se puede plantear un partido que tenga estos valores que hicieron grande a Rafaela como la cultura del trabajo y del esfuerzo, la honestidad, tener gente sana y trabajadora, que defienda la vida y la familia. Decidimos plasmarlo en un nuevo espacio pol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-Tienen buenos antecedentes: a nivel provincial entraron 6 diputados en 2019, el Concejo Municipal declar\u00f3 a la ciudad pro-vida y pro-familia en 2015, y aprob\u00f3 un proyecto sobre la protecci\u00f3n integral de las mujeres embarazadas vulnerables y los ni\u00f1os por nacer en 2018. \u00bfArrancan con un caudal importante de votos?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Ofrecemos esta alternativa electoral para toda la ciudad, creemos en la pluralidad, respetamos al que piensa distinto y la libertad debe ser el valor supremo. La ciudadan\u00eda deber\u00e1 decidir y nuestra intenci\u00f3n es gobernar para toda la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-\u00bfCu\u00e1l va a ser la estrategia de la campa\u00f1a electoral?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Estamos hablando con dirigentes, con formadores de opini\u00f3n, empresarios, presidentes vecinales, entre otros, tratando de elaborar la mejor plataforma electoral y para eso hay que escuchar a la gente. Nuestro espacio surge porque no nos sentimos representados y vemos que la agenda de la pol\u00edtica no tiene en cuenta a la gente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-\u00bfCu\u00e1les son las mayores cr\u00edticas a los gobiernos en los tres niveles que sufre el com\u00fan de la gente por las decisiones tomadas durante la pandemia y la cuarentena eterna?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Pareciera ser que no se toman las decisiones en Rafaela, acatamos \u00f3rdenes que vienen como una bajada de l\u00ednea nacional y provincial cuando la realidad nuestra es otra. Como rafaelinos tenemos la capacidad y la experiencia para tomar nuestras propias decisiones. Hace m\u00e1s de un a\u00f1o y medio que tenemos encerrada la gente, con incongruencias porque un d\u00eda s\u00ed vamos para adelante y despu\u00e9s vamos para atr\u00e1s; no desconozco ni niego los casos y la situaci\u00f3n epidemiol\u00f3gica, pero la realidad local no es la misma que la de Rosario, Santa Fe o Buenos Aires. Se podr\u00edan haber tomado otras decisiones y se lo plante\u00e9 al Intendente. Nosotros tenemos otra mirada y me parece que el Intendente se est\u00e1 equivocando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>-\u00bfC\u00f3mo est\u00e1n posicionados?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Tenemos las devoluciones de la gente cuando salimos a la cancha, muchos dijeron que quieren colaborar en la campa\u00f1a y qu\u00e9 bueno que aparezca una alternativa. La ciudadan\u00eda quiere un cambio en Rafaela y en 2017 vot\u00f3 otra cosa (por Cambiemos), pero se defraud\u00f3 y se decepcion\u00f3 porque de 5 concejales hab\u00edan metido 4. \u00bfQu\u00e9 aportes hicieron a la ciudad? El gen del cambio est\u00e1, la gente no estaba encontrando el espacio y podemos ser una linda oferta para este gran sector que hoy no se siente representado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Destac\u00f3 Delvis Bodoira, quien decidi\u00f3 alejarse del oficialismo luego de trabajar en distintas funciones legislativas y ejecutivas durante 16 a\u00f1os. \u201cEl Intendente entiende que uno est\u00e1 equivocado\u201d, aclar\u00f3 en el programa \u201cS\u00e1bado 100\u201d por radio El Espectador (FM 100,1). Sobre la pandemia y la cuarentena, opin\u00f3 que \u201cse est\u00e1n tomando decisiones en Buenos Aires o Santa Fe, que no tienen nada que ver con la realidad local\u201d.<\/p>\n","protected":false},"author":2,"featured_media":13073,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[3767],"class_list":["post-13072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Destac\u00f3 Delvis Bodoira, quien decidi\u00f3 alejarse del oficialismo luego de trabajar en distintas funciones legislativas y ejecutivas durante 16 a\u00f1os. \u201cEl Intendente entiende que uno est\u00e1 equivocado\u201d, aclar\u00f3 en el programa \u201cS\u00e1bado 100\u201d por radio El Espectador (FM 100,1). Sobre la pandemia y la cuarentena, opin\u00f3 que \u201cse est\u00e1n tomando decisiones en Buenos Aires o Santa Fe, que no tienen nada que ver con la realidad local\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-18T22:23:54+00:00\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d\",\"datePublished\":\"2021-07-18T22:23:54+00:00\",\"dateModified\":\"2021-07-18T22:23:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/\"},\"wordCount\":1031,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/\",\"name\":\"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-07-18T22:23:54+00:00\",\"dateModified\":\"2021-07-18T22:23:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d - Sabado 100","og_description":"Destac\u00f3 Delvis Bodoira, quien decidi\u00f3 alejarse del oficialismo luego de trabajar en distintas funciones legislativas y ejecutivas durante 16 a\u00f1os. \u201cEl Intendente entiende que uno est\u00e1 equivocado\u201d, aclar\u00f3 en el programa \u201cS\u00e1bado 100\u201d por radio El Espectador (FM 100,1). Sobre la pandemia y la cuarentena, opin\u00f3 que \u201cse est\u00e1n tomando decisiones en Buenos Aires o Santa Fe, que no tienen nada que ver con la realidad local\u201d.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2021-07-18T22:23:54+00:00","author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d","datePublished":"2021-07-18T22:23:54+00:00","dateModified":"2021-07-18T22:23:54+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/"},"wordCount":1031,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#primaryimage"},"thumbnailUrl":"","keywords":["\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/","url":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/","name":"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-07-18T22:23:54+00:00","dateModified":"2021-07-18T22:23:54+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/no-compartimos-los-valores-del-proyecto-municipal-y-formamos-otro-espacio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"\u201cNo compartimos los valores del proyecto municipal y formamos otro espacio\u201d"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/13072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=13072"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/13072\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=13072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=13072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=13072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}