{"id":10733,"date":"2021-01-27T20:44:07","date_gmt":"2021-01-27T23:44:07","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=10733"},"modified":"2021-01-27T20:44:07","modified_gmt":"2021-01-27T23:44:07","slug":"el-auxilio-a-los-peores-caudillos","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/","title":{"rendered":"El auxilio a los peores caudillos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por\u00a0<a href=\"https:\/\/www.lanacion.com.ar\/autor\/joaquin-morales-sola-51\">Joaqu\u00edn Morales Sol\u00e1<\/a>.-<\/strong> El senador\u00a0<a href=\"https:\/\/www.lanacion.com.ar\/politica\/jose-mayans-horacio-rodriguez-larreta-tiene-6000-nid2581954\">Jos\u00e9 Mayans<\/a>\u00a0es presidente del bloque kirchnerista; es decir, es un legislador de la m\u00e1xima confianza de\u00a0<strong>Cristina Kirchner<\/strong>, que maneja el Senado como si fuera su casa particular. Mayans acaba de decir que\u00a0<strong>\u00aben pandemia no hay derechos\u00bb.<\/strong>\u00a0Es una aberraci\u00f3n pol\u00edtica y una herej\u00eda para el sistema democr\u00e1tico. Seg\u00fan su disparatada teor\u00eda, la sociedad no solo debe padecer la ferocidad del virus que azota al mundo; tambi\u00e9n est\u00e1 condenada a perder las garant\u00edas propias de un Estado de Derecho. Es el infierno pol\u00edtico en toda su densidad. Sin embargo, ser\u00eda injusto detenernos solo en Mayans, porque \u00e9l es una criatura de l\u00edderes pol\u00edticos mucho m\u00e1s importantes.\u00a0<a href=\"https:\/\/www.lanacion.com.ar\/politica\/formosa-gobierno-gildo-insfran-extendio-aislamiento-comunidades-nid2582978\">Gildo Insfr\u00e1n<\/a>, que lleva un cuarto de siglo gobernando Formosa, es el padrino pol\u00edtico de Mayans. Cristina Kirchner es su protectora en la pol\u00edtica nacional. Y el presidente Alberto Fern\u00e1ndez lo elev\u00f3 a la condici\u00f3n de gobernador ejemplar. Mayans no existir\u00eda sin Insfr\u00e1n, Cristina y el Presidente. O dejar\u00eda de ser lo que es si no dijera los desprop\u00f3sitos que frecuenta como senador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El problema es Insfr\u00e1n y la cobertura pol\u00edtica que recibe del peronismo nacional. Insfr\u00e1n comenz\u00f3 su aventura pol\u00edtica en el\u00a0<strong>Partido Comunista Revolucionario<\/strong>\u00a0de orientaci\u00f3n mao\u00edsta. Pecado de juventud que luego lo resolvi\u00f3 convirti\u00e9ndose al menemismo, al duhaldismo, al kirchnerismo nestorista y, por \u00faltimo, al cristinismo. Sus sucesivas lealtades parecen no haber borrado, con todo, su primera adhesi\u00f3n al duro r\u00e9gimen pol\u00edtico de Mao y sus sucesores. En\u00a0<strong>Formosa<\/strong>, la democracia es una vaga noci\u00f3n que aparece cada tanto, en tiempos de elecciones, para ratificar el liderazgo de Insfr\u00e1n. Casi todos los medios period\u00edsticos (gr\u00e1ficos y audiovisuales) est\u00e1n en manos de adeptos al gobernador. Los medios nacionales no pudieron entrar a Formosa durante la pandemia porque Insfr\u00e1n les neg\u00f3 el permiso de ingreso con la excusa de la\u00a0<a href=\"https:\/\/www.lanacion.com.ar\/sociedad\/en-detalle-infectados-fallecidos-coronavirus-argentina-nid2350330\/\">pandemia<\/a>. Solo llegaron al conocimiento de la opini\u00f3n p\u00fablica nacional algunos videos caseros hechos con celulares por periodistas o ciudadanos de Formosa. Preocupado por la escasez del sistema sanitario provincial, Insfr\u00e1n decidi\u00f3 enfrentar la pandemia violando todos los derechos humanos. Encerr\u00f3 entre rejas a los enfermos en escuelas y hospitales, los mezcl\u00f3 con los contactos cercanos que no estaban enfermos y les prohibi\u00f3 a todos hasta el derecho a caminar. En medio del hacinamiento en que viven, nadie sabe qu\u00e9 clase de comida y de asistencia m\u00e9dica reciben. Nadie conoce cu\u00e1ntos internados hay. Ya en octubre del a\u00f1o pasado muri\u00f3 un joven e 23 a\u00f1os cuando intent\u00f3 llegar a nado a Formosa, porque todos los otros accesos estaban cerrados. El argumento de Insfr\u00e1n es que la frontera con Paraguay torna incontrolable el tr\u00e1nsito de virus. Tambi\u00e9n tiene frontera con Chaco, una provincia que fue muy castigada por el Covid-19. Nada m\u00e1s que pretextos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/bucket1.glanacion.com\/anexos\/fotos\/72\/3594672h768.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Solo el martes empezaron a salir algunos internados, supuestamente porque&nbsp;<a href=\"https:\/\/www.lanacion.com.ar\/politica\/horacio-pietragalla-secretario-derechos-humanos-alberto-fernandez-nid2583045\">en las pr\u00f3ximas horas llegar\u00eda&nbsp;<\/a>a Formosa una delegaci\u00f3n de la Secretar\u00eda de Derechos Humanos de la Naci\u00f3n. Esa Secretar\u00eda mantuvo un silencio exasperante durante los \u00faltimos d\u00edas. Su titular,&nbsp;<strong>Horacio Pietragalla<\/strong>, es el mismo que en su momento pidi\u00f3 la libertad hasta de&nbsp;<strong>Ricardo Jaime<\/strong>, un corrupto confeso ante la Justicia, en nombre de los derechos humanos. \u00bfImportan m\u00e1s los supuestos derechos de Jaime, entre varios corruptos m\u00e1s por los que se interes\u00f3 Pietragalla, que los de los formose\u00f1os encerrados y hacinados? La particular visi\u00f3n de Pietragalla parece indicar que s\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La conclusi\u00f3n y la informaci\u00f3n coinciden en la explicaci\u00f3n del caso Insfr\u00e1n. Es Cristina Kirchner la que lo protege. Insfr\u00e1n tiene una vieja relaci\u00f3n pol\u00edtica con la vicepresidenta (relaci\u00f3n de sumisi\u00f3n, desde ya). El control de los votantes de Formosa es f\u00e9rreo por parte de Insfr\u00e1n; en 2019, el 70 por ciento de los formose\u00f1os vot\u00f3 por la f\u00f3rmula Fern\u00e1ndez-Kirchner. Insfr\u00e1n reform\u00f3 la Constituci\u00f3n provincial y le introdujo la reelecci\u00f3n indefinida.\u00a0<strong>Lo mismo que hizo N\u00e9stor Kirchner en Santa Cruz.<\/strong>\u00a0Adem\u00e1s, la vicepresidenta tiene una particular seducci\u00f3n con los caudillos feudales de las provincias, tal vez porque ella es heredera de uno de esos caciques. Otro gobernador intocable para el kirchnerismo es\u00a0<strong>Gerardo Zamora<\/strong>, que gobierna Santiago del Estero con iguales o peores formas que Insfr\u00e1n. La disciplina de Zamora frente a Cristina es absoluta. Ella los recompens\u00f3 a Insfr\u00e1n y a Zamora. Al delegado de Insfr\u00e1n en el Senado, Mayans, le dio la presidencia del bloque de senadores oficialistas; a la esposa de Zamora le dio nada menos que la presidencia provisional del Senado, que tiene el segundo lugar en la l\u00ednea de sucesi\u00f3n presidencial. Los caudillos duros, que desaf\u00edan la democracia un d\u00eda s\u00ed y otro tambi\u00e9n, son los que mejor le caen a la jefa pol\u00edtica de la coalici\u00f3n gobernante. El Presidente, a su vez, no se detuvo ni siquiera en la est\u00e9tica (ni en la \u00e9tica) antes de abrazarse a Insfr\u00e1n. Pero no es \u00e9l quien protege al mandam\u00e1s formose\u00f1o; es Cristina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insfr\u00e1n sigui\u00f3 siempre las ocurrencias de la actual vicepresidenta. Cuando&nbsp;<strong>Amado Boudou<\/strong>&nbsp;era el ahijado pol\u00edtico predilecto de la entonces presidenta, Insfr\u00e1n firm\u00f3 un acuerdo con la firma&nbsp;<strong>The Old Fund<\/strong>, que controlaba Boudou, para que esta lo asesorara en la reestructuraci\u00f3n de la deuda p\u00fablica de Formosa con el gobierno nacional. Nunca hab\u00eda sucedido algo as\u00ed en la historia del pa\u00eds. Un gobierno provincial que contrata a una empresa privada para que lo asesore en la refinanciaci\u00f3n de la deuda con el Estado nacional. Formosa le pag\u00f3 7.600.000 pesos a esa empresa, que en esa \u00e9poca significaban unos dos millones de d\u00f3lares. La anomal\u00eda (o el delito) se investig\u00f3 en la justicia nacional, cuando esta abri\u00f3 el caso de&nbsp;<strong>Ciccone Calcogr\u00e1fica<\/strong>. Despu\u00e9s de deambular durante mucho tiempo por Comodoro Py, el expediente termin\u00f3 en el juzgado federal de Formosa por decisi\u00f3n de la C\u00e1mara Federal. Ah\u00ed morir\u00e1. Insfr\u00e1n controla toda la justicia de Formosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno nacional y el Partido Justicialista, tambi\u00e9n nacional, salieron en un&nbsp;<a href=\"https:\/\/www.lanacion.com.ar\/politica\/pj-insfran-nid2580145\">efusivo apoyo<\/a>&nbsp;a Insfr\u00e1n. El peronismo no siempre fue as\u00ed. Sea por convicci\u00f3n o por oportunismo, lo cierto es que dos presientes peronistas tomaron distancia de caudillos impresentables.&nbsp;<strong>Carlos Menem&nbsp;<\/strong>intervin\u00f3 Catamarca en 1991 y Santiago del Estero en 1993. El respaldo al catamarque\u00f1o Ram\u00f3n Saadi y al santiague\u00f1o Carlos Ju\u00e1rez significaba en ese momento un precio pol\u00edtico que el gobierno nacional no estaba dispuesto a pagar. El propio N\u00e9stor Kirchner volvi\u00f3 a intervenir Santiago del Estero en 2005 cuando la gobernadora era la esposa de Ju\u00e1rez, Nina Aragon\u00e9s. Ni Menem ni Kirchner aceptaron el desgaste que hubiera significado para sus figuras nacionales el apoyo a caprichosos caudillos provinciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, \u00bfpor qu\u00e9 con Insfr\u00e1n las cosas son distintas? \u00bfPor qu\u00e9 el peronismo, que siempre tuvo un fino olfato pol\u00edtico, corre en auxilio del desprestigiado Insfr\u00e1n? Versiones formose\u00f1as, imposibles de confirmar, indican que Insfr\u00e1n es tambi\u00e9n un importante aportante a las campa\u00f1as electorales del peronismo en el norte del pa\u00eds. Es probable. Y es posible tambi\u00e9n que Cristina no est\u00e9 dispuesta a sacrificar a un buen recolector de votos en un a\u00f1o electoral. Todo lo dem\u00e1s no tiene mucha relevancia para una estirpe pol\u00edtica obsesionada con sus propios problemas. Ni siquiera es importante que Insfr\u00e1n haya detenido durante varias horas a dos concejales,\u00a0<strong>Gabriela Neme y Celeste Ru\u00edz D\u00edaz<\/strong>, cuando estas iban a visitar a los encerrados en campos de hacinamiento. Neme y Ru\u00edz D\u00edaz ten\u00edan fueros y, por lo tanto, la inmunidad de arresto. Ese un principio sagrado para Cristina, porque ya hubiera pasado por la c\u00e1rcel si no tuviera fueros. Pero la oposici\u00f3n (Neme y Ru\u00edz D\u00edaz son opositoras a Insfr\u00e1n) tiene otros derechos o no los tienen. Mayans no se equivoca. Los derechos de las personas son de vigencia relativa cuando los liderazgos pol\u00edticos est\u00e1n en manos de dirigentes como Cristina o Insfr\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong> https:\/\/www.lanacion.com.ar\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por\u00a0Joaqu\u00edn Morales Sol\u00e1.- El senador\u00a0Jos\u00e9 Mayans\u00a0es presidente del bloque kirchnerista; es decir, es un legislador de la m\u00e1xima confianza de\u00a0Cristina [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10734,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[4012],"class_list":["post-10733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-el-auxilio-a-los-peores-caudillos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El auxilio a los peores caudillos - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El auxilio a los peores caudillos - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Por\u00a0Joaqu\u00edn Morales Sol\u00e1.- El senador\u00a0Jos\u00e9 Mayans\u00a0es presidente del bloque kirchnerista; es decir, es un legislador de la m\u00e1xima confianza de\u00a0Cristina [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-27T23:44:07+00:00\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"El auxilio a los peores caudillos\",\"datePublished\":\"2021-01-27T23:44:07+00:00\",\"dateModified\":\"2021-01-27T23:44:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/\"},\"wordCount\":1444,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"El auxilio a los peores caudillos\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/\",\"name\":\"El auxilio a los peores caudillos - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-01-27T23:44:07+00:00\",\"dateModified\":\"2021-01-27T23:44:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El auxilio a los peores caudillos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El auxilio a los peores caudillos - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/","og_locale":"es_ES","og_type":"article","og_title":"El auxilio a los peores caudillos - Sabado 100","og_description":"Por\u00a0Joaqu\u00edn Morales Sol\u00e1.- El senador\u00a0Jos\u00e9 Mayans\u00a0es presidente del bloque kirchnerista; es decir, es un legislador de la m\u00e1xima confianza de\u00a0Cristina [&hellip;]","og_url":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2021-01-27T23:44:07+00:00","author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"El auxilio a los peores caudillos","datePublished":"2021-01-27T23:44:07+00:00","dateModified":"2021-01-27T23:44:07+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/"},"wordCount":1444,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#primaryimage"},"thumbnailUrl":"","keywords":["El auxilio a los peores caudillos"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/","url":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/","name":"El auxilio a los peores caudillos - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-01-27T23:44:07+00:00","dateModified":"2021-01-27T23:44:07+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/el-auxilio-a-los-peores-caudillos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"El auxilio a los peores caudillos"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/10733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=10733"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/10733\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=10733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=10733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=10733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}