{"id":10127,"date":"2020-12-08T17:19:02","date_gmt":"2020-12-08T20:19:02","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=10127"},"modified":"2020-12-08T17:19:02","modified_gmt":"2020-12-08T20:19:02","slug":"fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/","title":{"rendered":"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En la fiesta de la Inmaculada Concepci\u00f3n de la Virgen Mar\u00eda, celebrada cada 8 de diciembre,\u00a0<a href=\"https:\/\/es.zenit.org\/2020\/11\/28\/tiempo-de-adviento-preparacion-para-la-llegada-de-jesus\/\">D. Rafael Mosteyr\u00edn<\/a>, sacerdote del\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/opusdei.org\/es-es\/\" target=\"_blank\">Opus Dei<\/a>, nos ofrece un art\u00edculo sobre la misma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">***<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/storage.googleapis.com\/cdnmedia.zenit.org\/uploads\/sites\/3\/2020\/12\/503d3936-download_20201208_025242-1024x1024.jpg\" alt=\"\" class=\"wp-image-213384\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A la Virgen Mar\u00eda le celebramos en distintas fiestas, una de las m\u00e1s importantes es la Inmaculada Concepci\u00f3n. Es un dogma de la Iglesia, precisamente desde el 8 de diciembre de 1854, pero con much\u00edsima devoci\u00f3n en Espa\u00f1a y otros pa\u00edses desde tiempos inmemoriales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfY qu\u00e9 significa este t\u00edtulo? Inmaculada quiere decir sin ninguna mancha, ni suciedad, sin pecados. Inmaculada es lo mismo que pura. Por eso tambi\u00e9n es conocido este d\u00eda como el de la Pur\u00edsima. Es el saludo acostumbrado cuando uno comienza a confesarse. Se dice Ave Mar\u00eda pur\u00edsima, y se contesta sin pecado concebida. Se recuerda as\u00ed el ejemplo de belleza y santidad de la Madre de Dios y Madre nuestra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concepci\u00f3n es el momento del nacimiento de una persona. Desde el momento de su concepci\u00f3n, por sus padres&nbsp;<a href=\"https:\/\/es.zenit.org\/2020\/07\/26\/san-joaquin-y-santa-ana-la-ternura-es-el-remedio-para-la-pandemia\/\">san Joaqu\u00edn y santa Ana<\/a>, no tuvo ning\u00fan pecado. Ha sido el \u00fanico caso, en la historia de la humanidad, de nacer sin pecado original. As\u00ed lo quiso Dios, porque su Madre ser\u00eda el primer sagrario, donde \u00c9l comenzar\u00eda a vivir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin pecado. As\u00ed fue el alma de la Virgen durante toda su vida. Nosotros estamos manchados frecuentemente por faltas, pecados y errores. Pero la Virgen Mar\u00eda es Madre, y no le importa que nos ensuciemos sino que nos ayuda r\u00e1pidamente a limpiarnos. Por eso, en esta fiesta podemos pedirle que nos mantenga siempre alejados del pecado, que no nos ensuciemos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Virgen Mar\u00eda siempre ha vencido en todas las tentaciones, y nunca cometi\u00f3 ninguno pecado. Mantuvo su alma limpia, y resplandeciente, durante toda su vida. Le pedimos ayuda ahora, para mejorar, con motivo de la celebraci\u00f3n y el reconocimiento de su pureza. \u00bfC\u00f3mo? Dependiendo de la generosidad de cada uno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si le pregunt\u00e1ramos a nuestra madre de la tierra qu\u00e9 regalo prefiere, por su cumplea\u00f1os, casi todas las madres suelen decir lo mismo. Por lo menos mi madre nos dec\u00eda, a mis siete hermanos y a m\u00ed, que el \u00fanico regalo que nos ped\u00eda es que nos port\u00e1ramos bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto, referido a la Virgen Mar\u00eda, se manifiesta en recibir dos sacramentos con m\u00e1s frecuencia: la Confesi\u00f3n y la Eucarist\u00eda. Gracias a estos dos sacramentos nos arrepentimos de nuestros pecados, somos perdonados y podemos recibir a su Hijo Jes\u00fas, dentro de nosotros, como ella hizo. Mar\u00eda tuvo a Jes\u00fas dentro de ella en los nueve meses de embarazo, y despu\u00e9s de la Resurrecci\u00f3n del Se\u00f1or, cuando pudo comulgar. Por estas razones es muy importante la limpieza de nuestra alma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se cuenta que un pintor quer\u00eda dibujar una imagen de la Inmaculada Concepci\u00f3n. Busc\u00f3 el rostro de una joven que pudiera servirle de modelo. Se acerc\u00f3 a una, y le pidi\u00f3 si estar\u00eda dispuesta a posar en su taller, para servir de modelo de un cuadro de la Virgen. La joven se qued\u00f3 sorprendida; pero, despu\u00e9s de tranquilizarse, dijo al artista: \u201cHoy no puede ser, volver\u00e9 pronto\u201d. Al d\u00eda siguiente, despu\u00e9s de los saludos previos, dijo la joven al pintor: \u201cAyer no me atrev\u00ed a servir de modelo para un cuadro de la Inmaculada, porque no estaba en gracia de Dios. Esta ma\u00f1ana me he confesado, y ahora podr\u00e9 servir como modelo menos indignamente\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla y a tratar de parecernos m\u00e1s a Ella cada d\u00eda. Los hijos deben parecerse a su Madre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aprovechemos esta ocasi\u00f3n para pedirle la limpieza de nuestra alma, con la confesi\u00f3n de nuestros pecados y el deseo de imitarle m\u00e1s a Ella. Tenemos nueve d\u00edas seguidos para acercarnos m\u00e1s a nuestra Madre. Lo que m\u00e1s le gustar\u00e1 es vernos decididos a parecernos m\u00e1s a Jes\u00fas, el fruto bendito de su vientre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El autor naci\u00f3 en 1973 en Sevilla, y ordenado sacerdote en 2014 en Roma. Desde entonces ha vivido en Barcelona y Sevilla, con estancias de colaboraci\u00f3n en Oberammergau (Alemania) y Huancavelica (Per\u00fa). Actualmente en C\u00f3rdoba, en el Club Alcorce y el colegio Torrealba.<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuente:<\/strong> https:\/\/es.zenit.org\/2020\/12\/08.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es un dogma de la Iglesia, precisamente desde el 8 de diciembre de 1854. Para Rafael Mosteyr\u00edn, inmaculada quiere decir sin ninguna mancha y concepci\u00f3n es el momento del nacimiento de una persona.<\/p>\n","protected":false},"author":2,"featured_media":10128,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[29],"tags":[4715],"class_list":["post-10127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-religion","tag-fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"Es un dogma de la Iglesia, precisamente desde el 8 de diciembre de 1854. Para Rafael Mosteyr\u00edn, inmaculada quiere decir sin ninguna mancha y concepci\u00f3n es el momento del nacimiento de una persona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-08T20:19:02+00:00\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla\",\"datePublished\":\"2020-12-08T20:19:02+00:00\",\"dateModified\":\"2020-12-08T20:19:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/\"},\"wordCount\":761,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla\"],\"articleSection\":[\"Religi\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/\",\"name\":\"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-12-08T20:19:02+00:00\",\"dateModified\":\"2020-12-08T20:19:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/","og_locale":"es_ES","og_type":"article","og_title":"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla - Sabado 100","og_description":"Es un dogma de la Iglesia, precisamente desde el 8 de diciembre de 1854. Para Rafael Mosteyr\u00edn, inmaculada quiere decir sin ninguna mancha y concepci\u00f3n es el momento del nacimiento de una persona.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2020-12-08T20:19:02+00:00","author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla","datePublished":"2020-12-08T20:19:02+00:00","dateModified":"2020-12-08T20:19:02+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/"},"wordCount":761,"commentCount":0,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#primaryimage"},"thumbnailUrl":"","keywords":["Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla"],"articleSection":["Religi\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/","url":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/","name":"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-12-08T20:19:02+00:00","dateModified":"2020-12-08T20:19:02+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/fiesta-de-la-inmaculada-concepcion-la-verdadera-devocion-a-maria-nos-debe-llevar-a-imitarla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Fiesta de la Inmaculada Concepci\u00f3n: la verdadera devoci\u00f3n a Mar\u00eda nos debe llevar a imitarla"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/10127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=10127"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/10127\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=10127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=10127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=10127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}