{"id":10117,"date":"2020-12-08T11:09:15","date_gmt":"2020-12-08T14:09:15","guid":{"rendered":"https:\/\/www.sabado100.com.ar\/?p=10117"},"modified":"2020-12-08T11:09:15","modified_gmt":"2020-12-08T14:09:15","slug":"proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial","status":"publish","type":"post","link":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/","title":{"rendered":"Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Diversos estudios coinciden en que el \u201ctiempo de vida medio\u201d de un matrimonio va disminuyendo cada vez m\u00e1s. Y las consecuencias de una ruptura afectan no s\u00f3lo a la pareja, sino a su familia, su entorno y a la sociedad en su conjunto. Es por esto que desde el Centro de Investigaci\u00f3n en Humanidades y Ciencias Sociales de la Universidad de Navarra (Espa\u00f1a) se busca responder a trav\u00e9s de una investigaci\u00f3n acad\u00e9mica rigurosa algunos de los principales desaf\u00edos que del mundo actual implica para los matrimonios y las familias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo de esta investigaci\u00f3n es \u201cidentificar las claves y los factores que contribuyen al \u00e9xito o al fracaso matrimonial\u201d, a trav\u00e9s de un estudio realizado con parejas de novios que se van a casar pr\u00f3ximamente. Se trata de conocer qu\u00e9 factores ayudan a la estabilidad y felicidad en el matrimonio para ayudar a los j\u00f3venes a construir una relaci\u00f3n conyugal feliz.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.sabado100.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-08-at-10.53.00-768x1024.jpeg\" alt=\"\" class=\"wp-image-10119\"\/><figcaption><strong>Orientadora familiar Luciana Mazzei.<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQueremos conocer sobre todo los factores que ayudan a que el matrimonio siga adelante, no tanto los factores que producen la separaci\u00f3n. En los \u00faltimos 30 a\u00f1os a partir de que la mujer se incorpor\u00f3 masivamente al mercado laboral, la organizaci\u00f3n familiar ha cambiado mucho, lo que implic\u00f3 que la familia tenga que volver a organizarse de una manera diferente. Se debe ayudar a que el matrimonio pueda crecer y mantener los v\u00ednculos sanos y duraderos\u201d, destac\u00f3 la licenciada en Orientaci\u00f3n Familiar Luciana In\u00e9s Mazzei (es referente en la ciudad de Rafaela), durante el programa \u201cS\u00e1bado 100\u201d por radio El Espectador (FM 100,1), conducido por Emilio Grande (h.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">AMAR (Antecedents of Marital Adjustment Research) es un estudio longitudinal que tiene la intenci\u00f3n de ir introduciendo nuevas parejas a lo largo de los a\u00f1os (durante 25 a\u00f1os). La extensi\u00f3n del proyecto en el tiempo permitir\u00e1 ofrecer mejores datos, para conocer las caracter\u00edsticas de los matrimonios que tienen \u00e9xito y para ayudar a otros j\u00f3venes a prepararse mejor para la vida matrimonial. Se trata de una investigaci\u00f3n con parejas con intenci\u00f3n de casarse, a las que \u201cofrecemos un seguimiento a lo largo de su matrimonio. Adem\u00e1s de obtener resultados para conocer mejor las claves del \u00e9xito en el matrimonio, damos a las parejas la oportunidad de conocerse mejor\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.sabado100.com.ar\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-08-at-10.56.24.jpeg\" alt=\"\" class=\"wp-image-10120\" width=\"577\" height=\"325\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1 dirigido a parejas que tienen intenci\u00f3n de casarse en los pr\u00f3ximos meses (un a\u00f1o o menos). Se trata de realizar un seguimiento de su relaci\u00f3n. Desde el noviazgo y durante los primeros a\u00f1os de matrimonio. A trav\u00e9s de la recogida de datos en diferentes momentos de la relaci\u00f3n. Como servicio por participar de la investigaci\u00f3n se les env\u00eda un breve informe basado en algunas de sus respuestas, que puede ayudar a mejorar la relaci\u00f3n de pareja. Tambi\u00e9n se les enviar\u00e1 informaci\u00f3n sobre los resultados que vayamos obteniendo en el proyecto. Adem\u00e1s, cada a\u00f1o, \u201csortearemos escapadas rom\u00e1nticas entre todos los matrimonios que hayan participado\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los resultados de los proyectos dar\u00e1n lugar a publicaciones cient\u00edficas de alta calidad. Todas las publicaciones resultantes de los proyectos siempre necesitar\u00e1n el acuerdo del equipo investigador del proyecto EASH, dirigido por el Dr. Jokin de Irala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Dr. Jokin de Irala, licenciado en Medicina y Cirug\u00eda por la Universidad de Navarra. Ha sido vicedecano de la Facultad de Medicina de la Universidad de Navarra. Adem\u00e1s de profesor en la Facultad, imparte dos asignaturas en el&nbsp;<a href=\"https:\/\/www.unav.edu\/matrimonioyfamilia\/master\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00e1ster en Matrimonio y Familia<\/a>. Es coordinador e investigador principal del proyecto multidisciplinar&nbsp;<strong>\u201cEducaci\u00f3n de la afectividad y sexualidad humana\u201d&nbsp;<\/strong>del Instituto Cultura y Sociedad (ICS) de la Universidad de Navarra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dirigen la investigaci\u00f3n el Dr. Alfonso Osorio, investigador responsable del proyecto y la Lic. Ma. Laura Divi como referente en Argentina, adem\u00e1s de contar con un equipo de profesionales de distintas disciplinas que se encargan de reclutar a las parejas, recabar la informaci\u00f3n, promover y difundir la investigaci\u00f3n, que surge en el Instituto de Cultura y Sociedad de la Universidad de Navarra, pero se trata de recolectar parejas de distintos pa\u00edses del mundo para que la muestra sea m\u00e1s representativa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para quienes deseen sumarse a participar de este proyecto est\u00e1n los datos de las redes sociales donde pueden encontrar m\u00e1s informaci\u00f3n y los datos de contacto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.amarhoy.org\/es\/\">https:\/\/www.amarhoy.org\/es\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Instagram:<\/strong> #amarhoyysiempre<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Rafaela: <a href=\"mailto:luchimazzei@gmail.com\">luchimazzei@gmail.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La investigaci\u00f3n est\u00e1 a cargo del Centro de Investigaci\u00f3n en Humanidades y Ciencias Sociales de la Universidad de Navarra (Espa\u00f1a) con participaci\u00f3n de la rafaelina Luciana Mazzei. El objetivo es averiguar qu\u00e9 factores facilitan un \u00f3ptimo desarrollo del matrimonio.<\/p>\n","protected":false},"author":2,"featured_media":10118,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[4713],"class_list":["post-10117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-y-sociedad","tag-proyecto-amar-identificar-claves-del-exito-o-fracaso-matrimonial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d - Sabado 100<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d - Sabado 100\" \/>\n<meta property=\"og:description\" content=\"La investigaci\u00f3n est\u00e1 a cargo del Centro de Investigaci\u00f3n en Humanidades y Ciencias Sociales de la Universidad de Navarra (Espa\u00f1a) con participaci\u00f3n de la rafaelina Luciana Mazzei. El objetivo es averiguar qu\u00e9 factores facilitan un \u00f3ptimo desarrollo del matrimonio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabado 100\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sabadocien\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-08T14:09:15+00:00\" \/>\n<meta name=\"author\" content=\"sabado cien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sabado cien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/\"},\"author\":{\"name\":\"sabado cien\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\"},\"headline\":\"Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d\",\"datePublished\":\"2020-12-08T14:09:15+00:00\",\"dateModified\":\"2020-12-08T14:09:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/\"},\"wordCount\":769,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Proyecto AMAR: \u201cidentificar claves del \u00e9xito o fracaso matrimonial\u201d\"],\"articleSection\":[\"Cultura y Sociedad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/\",\"name\":\"Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d - Sabado 100\",\"isPartOf\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-12-08T14:09:15+00:00\",\"dateModified\":\"2020-12-08T14:09:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sabado100.com.ar\/es-ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#website\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"name\":\"Sabado 100\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#organization\",\"name\":\"Sabado 100\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg\",\"width\":300,\"height\":174,\"caption\":\"Sabado 100\"},\"image\":{\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sabadocien\/\",\"https:\/\/www.instagram.com\/sabado100.com.ar\/\",\"https:\/\/www.youtube.com\/@sabado1003\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d\",\"name\":\"sabado cien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"contentUrl\":\"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622\",\"caption\":\"sabado cien\"},\"url\":\"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d - Sabado 100","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/","og_locale":"es_ES","og_type":"article","og_title":"Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d - Sabado 100","og_description":"La investigaci\u00f3n est\u00e1 a cargo del Centro de Investigaci\u00f3n en Humanidades y Ciencias Sociales de la Universidad de Navarra (Espa\u00f1a) con participaci\u00f3n de la rafaelina Luciana Mazzei. El objetivo es averiguar qu\u00e9 factores facilitan un \u00f3ptimo desarrollo del matrimonio.","og_url":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/","og_site_name":"Sabado 100","article_publisher":"https:\/\/www.facebook.com\/sabadocien\/","article_published_time":"2020-12-08T14:09:15+00:00","author":"sabado cien","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sabado cien","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#article","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/"},"author":{"name":"sabado cien","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d"},"headline":"Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d","datePublished":"2020-12-08T14:09:15+00:00","dateModified":"2020-12-08T14:09:15+00:00","mainEntityOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/"},"wordCount":769,"commentCount":2,"publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#primaryimage"},"thumbnailUrl":"","keywords":["Proyecto AMAR: \u201cidentificar claves del \u00e9xito o fracaso matrimonial\u201d"],"articleSection":["Cultura y Sociedad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/","url":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/","name":"Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d - Sabado 100","isPartOf":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#primaryimage"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-12-08T14:09:15+00:00","dateModified":"2020-12-08T14:09:15+00:00","breadcrumb":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/sabado100.com.ar\/es-ar\/proyecto-amar-identificar-las-claves-del-exito-o-fracaso-matrimonial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sabado100.com.ar\/es-ar\/"},{"@type":"ListItem","position":2,"name":"Proyecto AMAR: \u201cidentificar las claves del \u00e9xito o fracaso matrimonial\u201d"}]},{"@type":"WebSite","@id":"https:\/\/sabado100.com.ar\/es-ar\/#website","url":"https:\/\/sabado100.com.ar\/es-ar\/","name":"Sabado 100","description":"","publisher":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sabado100.com.ar\/es-ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sabado100.com.ar\/es-ar\/#organization","name":"Sabado 100","url":"https:\/\/sabado100.com.ar\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/uploads\/2024\/04\/logo3.jpg","width":300,"height":174,"caption":"Sabado 100"},"image":{"@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sabadocien\/","https:\/\/www.instagram.com\/sabado100.com.ar\/","https:\/\/www.youtube.com\/@sabado1003"]},{"@type":"Person","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/58e38b918ef4e44b11398f25d4684c6d","name":"sabado cien","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sabado100.com.ar\/es-ar\/#\/schema\/person\/image\/","url":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","contentUrl":"https:\/\/sabado100.com.ar\/es-ar\/wp-content\/litespeed\/avatar\/484bccfbd493fbb703b0f1b8113dad61.jpg?ver=1787731622","caption":"sabado cien"},"url":"https:\/\/sabado100.com.ar\/es-ar\/author\/sabado100\/"}]}},"_links":{"self":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/10117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/comments?post=10117"}],"version-history":[{"count":0,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/posts\/10117\/revisions"}],"wp:attachment":[{"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/media?parent=10117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/categories?post=10117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabado100.com.ar\/es-ar\/wp-json\/wp\/v2\/tags?post=10117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}